{"id":79639,"date":"2017-06-12T14:02:37","date_gmt":"2017-06-12T12:02:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pride-cs-convegno-sulla-violenza-domestica-nelle-coppie-lesbiche\/"},"modified":"2023-01-16T19:32:23","modified_gmt":"2023-01-16T18:32:23","slug":"159214-pride-cs-convegno-sulla-violenza-domestica-nelle-coppie-lesbiche","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/159214-pride-cs-convegno-sulla-violenza-domestica-nelle-coppie-lesbiche\/","title":{"rendered":"Pride Cs: convegno sulla violenza domestica nelle coppie lesbiche"},"content":{"rendered":"<h4>Il tema sar\u00e0 affrontato domani, alle 17,30, nella sala Tokyo del museo del Presente, a Rende.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L&#8217;incontro si inserisce nella programmazione proposta dal comitato <strong>P.R.I.D.E Cs<\/strong> che porter\u00e0 alla manifestazione del prossimo primo luglio a Cosenza. &#8220;La citt\u00e0 di Rende &#8211; afferma in una nota l&#8217;assessore <strong>Marina Pasqua<\/strong>&#8211; ha accolto la richiesta del patrocinio da parte degli organizzatori essendo l&#8217;autodeterminazione identitaria e la sensibilizzazione alle pari opportunit\u00e0 temi al centro del nostro discorso politico e alle base degli interventi sul territorio&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;L&#8217;argomento di cui parleremo domani\u00a0&#8211; ha proseguito l&#8217;avvocato &#8211; \u00e8 di grande attualit\u00e0 anche se ad oggi poco discusso. Ben vengano dunque iniziative come questa: la violenza contro le donne perpetrata dalle donne \u00e8 terreno ancora inesplorato. Da qui l&#8217;esigenza di riflettere sul fenomeno favorendo cos\u00ec l&#8217;emersione del problema del maltrattamento nelle relazioni di intimit\u00e0. Crediamo infatti che il cambiamento culturale debba muovere dal rispetto reciproco, aldil\u00e0 del genere di appartenenza.&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Il convegno vedr\u00e0, dopo i saluti del sindaco Marcello Manna, gli interventi dell&#8217;assessore alle pari opportunit\u00e0 del comune di Rende, di <strong>Angela Panza<\/strong> per il centro &#8220;R. Lanzino&#8221; e di <strong>Carla Catena<\/strong> per Arcilesbica Bologna. Il dibattito sar\u00e0 moderato da Gabriella Pingitore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tema sar\u00e0 affrontato domani, alle 17,30, nella sala Tokyo del museo del Presente, a Rende.<\/p>\n","protected":false},"author":22,"featured_media":79640,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-79639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79639"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79640"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}