{"id":79797,"date":"2017-06-15T13:42:15","date_gmt":"2017-06-15T11:42:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-sequestrati-5-milioni-di-beni-ad-un-esponente-della-cosca-sia-procopio-tripodi\/"},"modified":"2023-01-16T19:32:33","modified_gmt":"2023-01-16T18:32:33","slug":"159812-ndrangheta-sequestrati-5-milioni-di-beni-ad-un-esponente-della-cosca-sia-procopio-tripodi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/159812-ndrangheta-sequestrati-5-milioni-di-beni-ad-un-esponente-della-cosca-sia-procopio-tripodi\/","title":{"rendered":"&#8216;Ndrangheta, sequestrati 5 milioni di beni ad un esponente della cosca &#8220;Sia-Procopio-Tripodi&#8221;"},"content":{"rendered":"<h4><span style=\"line-height: 1.5;\"><strong>I beni sequestrati e confiscati sono quote societarie, due complessi aziendali, due automezzi, tre fabbricati, cinque terreni\u00a0nel catanzarese.<\/strong><\/span><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5;\">SOVERATO (CZ)\u00a0&#8211; Beni per un valore di circa 5 milioni di euro sono stati sequestrati e confiscati dai finanzieri del nucleo di polizia tributaria &#8211; Gico di Catanzaro, coordinati dalla Procura del capoluogo, a <\/span><strong style=\"line-height: 1.5;\">Maurizio Tripodi, indicato come esponente di vertice della cosca mafiosa &#8220;Sia-Procopio-Tripodi&#8221;<\/strong><span style=\"line-height: 1.5;\">, operante nell&#8217;area ionica soveratese e collegata alla cosca di &#8216;ndrangheta dei Vallelunga di Serra San Bruno. Tripodi, gi<\/span><span style=\"line-height: 1.5;\">\u00e0<\/span><span style=\"line-height: 1.5;\"> sottoposto alla misura di prevenzione personale della sorveglianza speciale con obbligo di soggiorno nel Comune di residenza per la durata di 5 anni, il 10 maggio <\/span><strong style=\"line-height: 1.5;\">2012 era stato arrestato nell&#8217;ambito dell&#8217;operazione denominata &#8220;Showdown&#8221;<\/strong><span style=\"line-height: 1.5;\"> e successivamente<\/span><strong style=\"line-height: 1.5;\"> condannato in primo grado a 12 anni e 6 mesi di reclusione<\/strong><span style=\"line-height: 1.5;\">, perch<\/span><span style=\"line-height: 1.5;\">\u00e8<\/span><span style=\"line-height: 1.5;\"> ritenuto colpevole, tra l&#8217;altro, di associazione mafiosa. La condanna <\/span><span style=\"line-height: 1.5;\">\u00e8<\/span><span style=\"line-height: 1.5;\">\u00a0stata confermata in appello. Tripodi <\/span><span style=\"line-height: 1.5;\">\u00e8<\/span><span style=\"line-height: 1.5;\">\u00a0stato anche condannato in appello a <\/span><strong style=\"line-height: 1.5;\">20 anni di reclusione per l&#8217;omicidio e l&#8217;occultamento del cadavere di Giuseppe Todaro<\/strong><span style=\"line-height: 1.5;\">, scomparso il 22 dicembre 2009 a Soverato<\/span><span style=\"line-height: 1.5;\">.<\/span><\/p>\n<p>Il delitto fu inquadrato nella <strong>&#8220;faida dei boschi&#8221;<\/strong> e sarebbe stato commesso da Tripodi in collaborazione con il defunto boss Vittorio Sia. Le indagini patrimoniali condotte dalle fiamme gialle avrebbero evidenziato una netta sproporzione tra i beni risultati nell&#8217;effettiva disponibilit\u00e0\u00a0dell&#8217;uomo, sebbene in larga parte formalmente intestati alla moglie e ai figli. Tripodi ha alternato, nel corso degli anni, l&#8217;attivit\u00e0 di lavoratore dipendente di una ditta edile e quella di imprenditore agricolo, presentando <strong>dichiarazioni dei redditi del tutto incoerenti con l&#8217;ingente patrimonio posseduto.<\/strong> Al tempo stesso la moglie \u00e8\u00a0risultata solo formalmente titolare di una ditta operante nel commercio di carni e di quote di partecipazione in diverse societ\u00e0, di fatto comunque considerate riconducibili a Tripodi, effettivo gestore delle attivit\u00e0 economiche. <strong>I beni sequestrati e confiscati sono quote societarie, due complessi aziendali, due automezzi, tre fabbricati, cinque terreni in provincia di Catanzaro<\/strong>, in particolare nei Comuni di Soverato, Satriano e Davoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I beni sequestrati e confiscati sono quote societarie, due complessi aziendali, due automezzi, tre fabbricati, cinque terreni\u00a0nel catanzarese.<\/p>\n","protected":false},"author":22,"featured_media":79798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-79797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79797"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79798"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}