{"id":79885,"date":"2017-06-18T06:52:02","date_gmt":"2017-06-18T04:52:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/centro-anziani-rende-cinque-consiglieri-convocano-unassise-ad-hoc\/"},"modified":"2023-01-16T19:32:39","modified_gmt":"2023-01-16T18:32:39","slug":"160088-centro-anziani-rende-cinque-consiglieri-convocano-unassise-ad-hoc","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/160088-centro-anziani-rende-cinque-consiglieri-convocano-unassise-ad-hoc\/","title":{"rendered":"Centro Anziani di Rende, cinque consiglieri convocano un\u2019assise ad hoc"},"content":{"rendered":"<h4>Prosegue il dibattito sul Centro Anziani di Rende, una struttura importante del welfare cittadino e in crisi da oltre un anno.<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; La situazione del Centro \u00e8 precipitata in seguito all\u2019affidamento del servizio fatto dal Comune alla cooperativa sociale \u201cSolidale\u201d a causa di una serie di intoppi burocratici. Il personale, privo di stipendi da circa cinque mesi, \u00e8 alla canna del gas, al punto che alcuni dei dipendenti, pressati dalle difficolt\u00e0 economiche, hanno preferito andare in disoccupazione. Sulla vicenda, di cui si \u00e8 interessata la Cgil, \u00e8 intervenuta l\u2019associazione civica Rende Protagonista, che ha chiesto ai consiglieri comunali di portare il dibattito nell\u2019assise cittadina.<br \/>\n&nbsp;<br \/>\nL\u2019invito \u00e8 stato accolto da cinque rappresentanti: Massimiliano De Rose, Carlo Petrassi, Carlo Scola, Francesco Beltrano e Alessandro De Rango. I cinque consiglieri hanno chiesto la convocazione di un consiglio comunale in seduta straordinaria e aperto. Cio\u00e8, come si legge nella richiesta,<em> \u00abin cui siano invitati a intervenire le parti interessate, i cittadini, gli organi istituzionali, i comitati spontanei che si sono interessati della questione e quanti possano dare un contributo e fornire proposte per la soluzione del problema\u00bb.<\/em><br \/>\n&nbsp;<br \/>\nPuntuale l\u2019intervento di <strong>Andrea Ferretti, il presidente di Rende Protagonista:<\/strong> \u00ab<em>Siamo contenti di questo importante risultato e ringraziamo i consiglieri comunali che hanno fatto propria l\u2019esigenza di portare all\u2019attenzione dell\u2019assemblea cittadina i problemi del Centro Anziani. \u00c8 importante che le istituzioni si facciano carico di questa vicenda non solo per motivi economici, che ci sono e sono gravissimi, ma anche per un motivo politico: l\u2019assistenza alla terza et\u00e0 \u00e8 un servizio che il Comune ha creato per i cittadini. Affrontarne le disfunzioni in un dibattito franco e aperto \u00e8 una questione di democrazia e perci\u00f2 prendiamo atto con piacere che la sensibilit\u00e0 politica non si \u00e8 estinta nel nostro territorio<\/em>\u00bb.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue il dibattito sul Centro Anziani di Rende, una struttura importante del welfare cittadino e in crisi da oltre un anno.<\/p>\n","protected":false},"author":22,"featured_media":79886,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-79885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79885"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79886"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}