{"id":8009,"date":"2012-11-19T14:08:42","date_gmt":"2012-11-19T13:08:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8009"},"modified":"2023-01-17T13:41:14","modified_gmt":"2023-01-17T12:41:14","slug":"3394-cosenza-aderisce-alla-giornata-contro-la-pedofilia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3394-cosenza-aderisce-alla-giornata-contro-la-pedofilia\/","title":{"rendered":"Pedofilia, il Comune sostiene iniziativa &#8220;Spegni le luci. Apri gli occhi&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Un minuto al buio. In occasione della prima giornata contro la pedofilia istituita dalla Lega Calcio e dalla presidenza della Camera dei Deputati, il Comune di Cosenza sostiene l\u2019iniziativa a favore di tutti i bambini vittime di violenza sessuale invitando i commercianti e i cittadini a spegnere<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">le luci sabato per un solo minuto, dalle 19 alle 19,01. L\u2019idea di una giornata contro la pedofilia, accolta dietro proposta del giornalista Mario Campanella in qualit\u00e0 di presidente dell\u2019associazione Peter Pan onlus, nasce al fianco di Meter Onlus, associazione guidata da don Fortunato Di Noto, che lotta quotidianamente per il recupero dei minori succubi di questo crimine e per l\u2019oscuramento di siti internet pedopornografici. Con un gesto di forte significato simbolico, l\u2019amministrazione di Palazzo dei Bruzi lancia lo slogan \u201cSpegni le luci. Apri gli occhi\u201d, rivolgendo a commercianti e a cittadini l\u2019appello di restare al buio solo per sessanta secondi, al fine di accendere i riflettori delle coscienze sui drammi che riguardano piccoli innocenti indifesi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un minuto al buio. In occasione della prima giornata contro la pedofilia istituita dalla Lega Calcio e dalla presidenza della Camera dei Deputati, il Comune di Cosenza sostiene l\u2019iniziativa a favore di tutti i bambini vittime di violenza sessuale invitando i commercianti e i cittadini a spegnere<\/p>\n","protected":false},"author":22,"featured_media":8010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-8009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8009"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8010"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}