{"id":80203,"date":"2017-06-23T17:27:10","date_gmt":"2017-06-23T15:27:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/e-morto-oggi-il-noto-giurista-cosentino-stefano-rodota\/"},"modified":"2023-01-16T19:33:00","modified_gmt":"2023-01-16T18:33:00","slug":"161303-e-morto-oggi-il-noto-giurista-cosentino-stefano-rodota","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/161303-e-morto-oggi-il-noto-giurista-cosentino-stefano-rodota\/","title":{"rendered":"E&#8217; morto oggi il noto giurista cosentino Stefano Rodot\u00e0"},"content":{"rendered":"<h4>Candidato alla Presidenza della Repubblica si \u00e8 spento all&#8217;et\u00e0 di 84 anni.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La citt\u00e0 di Cosenza e l&#8217;intera Italia piangono la scomparsa del politico e giurista calabrese Stefano Rodot\u00e0. Da sempre attivo nel panorama politico italiano proveniva da una famiglia piccolo borghese arbereshe di San Benedetto Ullano. Per anni ha vissuto in citt\u00e0 nei pressi di viale Trieste. Nella sua lunga militanza politica, dopo avere iniziato le sue lotte tra le fila dei Radicali (&#8220;l&#8217;unico partito al quale sono mai stato iscritto&#8221;), \u00e8 stato eletto deputato in quattro legislature (1979, 1983, 1987 e 1992) schierandosi con il Partito Comunista Italiano, Sinistra Indipendente, Partito democratico della sinistra, fino a presiedere la Camera dei Deputati in occasione della seduta per l\u2019elezione di Oscar Luigi Scalfaro (1992).<strong> Il giurista calabrese, docente universitario, \u00e8 stato anche membro dell\u2019Assemblea Parlamentare del Consiglio d\u2019Europa, quindi eletto parlamentare europeo nel 1989.\u00a0<\/strong>Tra gli incarichi ricoperti, anche quello di presidente del Garante per la protezione dei dati personali, mentre dal 1998 al 2005 ha presieduto il gruppo di coordinamento dei Garanti per il diritto alla riservatezza dell\u2019Unione Europea. Durante le ultime del Capo dello Stato \u00e8 stato candidato alla Presidenza della Repubblica per succedere a Giorgio Napolitano.<\/p>\n<p>&nbsp;<\/p>\n<p>Nato a Cosenza il 30 maggio del 1933, sposato da pi\u00f9 di cinquanta anni con Carla, collaboratrice di Repubblica lascia due figli, Carlo e Maria Laura. Il padre era un insegnante di matematica che diede ripetizioni a Giacomo Mancini ex sindaco di Cosenza che ricopr\u00ec la carica di ministro alla Sanit\u00e0 e ministro ai Lavori pubblici.\u00a0Nel 1953 lascia Cosenza per trasferirsi a Roma e laurearsi in legge. Inizia ad insegnare\u00a0diritto civile alla Sapienza di Roma non abbandonando mai le proprie passioni politiche e quella per il giornalista che lo vide collaborare da sempre con diverse testate tra cui La Repubblica e il Mondo. <strong>Nella sua carriera accademica sar\u00e0 chiamato ad insegna a nelle universit\u00e0 di Oxford, in Francia, in Germania e negli Stati Uniti<\/strong>. Entra in Parlamento per la prima volta nel 1979 e si candida come indipendente di sinistra nelle liste del Partito Comunista Italiano preferendo schierarsi con Berlinguer piuttosto che con Pannella. Abbandona il Pci quando il partito decide di votare le leggi repressive di Cossiga varate per soffocare le proteste di piazza durante gli anni di piombo. Si dimette nel 1993 a sorpresa dopo essere stato eletto vicepresidente della Camera. Durante il primo governo Prodi, nel 1997 diventa Garante della Privacy ruolo che ricoprir\u00e0, come gi\u00e0 detto sino al 2005. Sul conflitto d&#8217;interessi di\u00a0Berlusconi attiva diverse battaglie in difesa della democrazia ribadendo la necessit\u00e0 di pluralismo informativo nei media italiani denunciando per anni i &#8216;mostri&#8217; creati dal berlusconismo.<\/p>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2953\" target=\"_blank\" rel=\"noopener\"><span class=\"current\" style=\"color: #0000ff;\"> Premio Sila \u201949, Rodot\u00e0 torna nella sua Cosenza: \u2018\u2019Siamo nel secolo dello smartphone\u2019\u2019<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Candidato alla Presidenza della Repubblica si \u00e8 spento all&#8217;et\u00e0 di 84 anni.<\/p>\n","protected":false},"author":18,"featured_media":80204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-80203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=80203"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/80204"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=80203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=80203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=80203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}