{"id":80492,"date":"2017-06-30T04:55:56","date_gmt":"2017-06-30T02:55:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scoperta-nel-cosentino-lennesima-truffa-allinps\/"},"modified":"2023-01-16T19:33:20","modified_gmt":"2023-01-16T18:33:20","slug":"162431-scoperta-nel-cosentino-lennesima-truffa-allinps","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/162431-scoperta-nel-cosentino-lennesima-truffa-allinps\/","title":{"rendered":"Scoperta nel cosentino l&#8217;ennesima truffa all&#8217;Inps, 484 assunzioni fantasma e un danno da oltre un milione"},"content":{"rendered":"<h4>La guardia di Finanza di Cosenza ha scoperto l&#8217;ennesima truffa ai danni dell&#8217;Inps, che ammonta a un milione e trecentomila euro. Indennit\u00e0 percepite indebitamente da 484 lavoratori &#8216;fantasma&#8217;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La Guardia di Finanza di Sibari ha smascherato l\u2019ennesima truffa perpetrata ai danni dell\u2019I.N.P.S. ad opera di un\u2019azienda operante nel settore agricolo. Ben<strong> 484 le assunzioni fantasma<\/strong> che hanno arrecato un danno alle Casse dello Stato quantificato in oltre <strong>1.600.000 euro, tra indennit\u00e0 erogate e contributi non versati.<\/strong>\u00a0Il sistema di frode accertato dalla Fiamme Gialle, si sviluppava attraverso la sottoscrizione di un contratto di locazione di un terreno agricolo di breve durata, da utilizzare per la realizzazione del ciclo produttivo dell\u2019azienda agricola e la denuncia all\u2019I.N.P.S. dell\u2019impiego di un numero di Operai a Tempo Determinato, ritenuto congruo rispetto all\u2019estensione del terreno ed alla coltura da realizzare sullo stesso. inoltre grazie alla proroga del contratto attraverso la falsificazione della durata, l&#8217;azienda continuando a denunciare all\u2019I.N.P.S., l\u2019utilizzo di falsi braccianti agricoli.<\/p>\n<p>Il terreno \u00e8 risultato in realt\u00e0 concesso in locazione ad un altro imprenditore agricolo e all&#8217;esito delle attivit\u00e0 sono risultati falsamente denunciarti 484 braccianti agricoli per oltre 40 mila false giornate di lavoro agricolo. Cos\u00ec l\u2019imprenditore agricolo indagato ha denunciato all\u2019INPS l\u2019utilizzo di 484 lavoratori inesistenti, ma ben presenti nel momento che hanno incassato le relative indennit\u00e0 erogate dall\u2019ente previdenziale, quantificate in oltre 1.300.000 euro: assegni familiari per 500.000 euro, per malattia e maternit\u00e0 per oltre 380.000 euro e indennit\u00e0 di disoccupazione per oltre 450.000 euro.<\/p>\n<p>Gli accertamenti condotti dai militari del Gruppo di Sibari, hanno inoltre consentito di appurare che la ditta Individuale controllata ha omesso di versare nelle Casse dello Stato i relativi contributi previdenziali, quantificati in oltre 300.000 euro. L\u2019operazione si \u00e8 conclusa con la segnalazione a piede libero alla Procura della Repubblica presso il Tribunale di Castrovillari, dell\u2019imprenditore titolare della ditta Individuale, per i reati di truffa e falsit\u00e0 in atti. L\u2019Istituto di Previdenza ha gi\u00e0 avviato le prescritte procedure di recupero delle somme indebitamente erogate ed i falsi lavoratori sono stati segnalati all\u2019Autorit\u00e0 Giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guardia di Finanza di Cosenza ha scoperto l&#8217;ennesima truffa ai danni dell&#8217;Inps, che ammonta a un milione e trecentomila euro. Indennit\u00e0 percepite indebitamente da 484 lavoratori &#8216;fantasma&#8217;<\/p>\n","protected":false},"author":22,"featured_media":80493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-80492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=80492"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/80493"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=80492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=80492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=80492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}