{"id":80610,"date":"2017-07-02T06:30:52","date_gmt":"2017-07-02T04:30:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/belmonte-uniniziativa-contrastare-lo-spopolamento-dei-borghi\/"},"modified":"2023-01-16T19:33:28","modified_gmt":"2023-01-16T18:33:28","slug":"162798-belmonte-uniniziativa-contrastare-lo-spopolamento-dei-borghi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/162798-belmonte-uniniziativa-contrastare-lo-spopolamento-dei-borghi\/","title":{"rendered":"A Belmonte un&#8217;iniziativa per contrastare lo spopolamento dei borghi"},"content":{"rendered":"<h4>Da\u00a0domani e fino al 13 luglio a Belmonte Calabro si terr\u00e0 Crossings, un evento di innovazione culturale e sociale che intende considerare l&#8217;immigrazione non come situazione di criticit\u00e0 ma come opportunit\u00e0.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>BELMONTE C. (CS) &#8211; L&#8217;evento \u00e8 una rassegna internazionale di arte, architettura, musica, sport, teatro, cinema, in cui artisti, registi, attori, musicisti, architetti, cuochi, stilisti e artigiani incontrano i lettori, i cineasti, gli sportivi, gli anziani, i giovani e gli studenti, leggendo, dibattendo delle loro opere in una numerosa serie di eventi che impegna tutta la citt\u00e0 per dieci giorni. L&#8217;iniziativa \u00e8 la conseguenza di un <strong>laboratorio estivo<\/strong> organizzato dal gruppo le Seppie a luglio 2016 presso la residenza artistica l&#8217;Ex Convento a Belmonte Calabro, in collaborazione con la<strong> London Metropolitan University<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Il laboratorio ha dato vita a una classe di ricerca sulla Calabria presso la London Metropolitan University creando sei progetti che si concentrano su temi che riguardano l&#8217;abbandono dei villaggi italiani e il crescente bisogno di integrare i<strong> rifugiati<\/strong> che arrivano sulla costa meridionale. Il compito degli studenti \u00e8 stato quello di esaminare, capire, sviluppare e costruire iniziative culturali attraverso e all&#8217;interno della citt\u00e0 di Belmonte. Gli studenti e i loro tutor hanno deciso quindi di tornare a Belmonte e presentare i propri progetti come ringraziamento alla comunit\u00e0 dopo l&#8217;ospitalit\u00e0 e l&#8217;aiuto che hanno ricevuto durante il loro sopralluogo di qualche settimana a novembre 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>Insieme alle presentazioni, saranno organizzati concerti, seminari, laboratori ed eventi. In programma un laboratorio di progettazione e costruzione di quattro giorni insieme agli studenti della facolt\u00e0 di <strong>Architettura<\/strong> della London Metropolitan University, al collettivo di architettura Orizzontale e all&#8217;artista siciliana Barbara Cammarata. Sar\u00e0 coinvolta la comunit\u00e0 di Belmonte Calabro e gli ospiti del <strong>centro rifugiati di Amantea<\/strong> per creare una serie di interventi complementari che contribuiranno a sostenere la conversazione e le interazioni tra i diversi gruppi. Non mancheranno laboratori di musica e danza, seminari, tra cui uno di antropologia con <strong>Gian Piero Frassinelli<\/strong>, co-fondatore di Superstudio, presentazioni e momenti di convivialit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da\u00a0domani e fino al 13 luglio a Belmonte Calabro si terr\u00e0 Crossings, un evento di innovazione culturale e sociale che intende considerare l&#8217;immigrazione non come situazione di criticit\u00e0 ma come opportunit\u00e0.<\/p>\n","protected":false},"author":22,"featured_media":80611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-80610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=80610"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/80611"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=80610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=80610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=80610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}