{"id":8065,"date":"2012-11-20T10:32:39","date_gmt":"2012-11-20T09:32:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8065"},"modified":"2023-01-17T13:41:17","modified_gmt":"2023-01-17T12:41:17","slug":"3424-daspo-a-biccio-conferenza-stampa-dellattaccante","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3424-daspo-a-biccio-conferenza-stampa-dellattaccante\/","title":{"rendered":"Daspo a Biccio, conferenza stampa dell&#8217;attaccante"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> \u00abSiamo tutti &#8220;Biccio&#8221;\u00bb. Il Daspo di tre anni, emesso dal questore di Catanzaro, Guido Marino, per via di quella maglietta &#8220;pro-Speziale&#8221;, mostrata da Arcidiacono davanti alle telecamere di Rai Sport1, festeggiando il suo gol, messo a segno sabato pomeriggio nel derby contro il Sambiase<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">, ha innescato la miccia della rabbia, in seno alla tifoserie rossobl\u00f9. Dal tardo pomeriggio di ieri, quando la notizia del Daspo ha fatto velocemente il giro, con la stessa velocit\u00e0 con cui il furetto catanese dribbla gli avversari, i tifosi del Cosenza hanno contestato la decisione, manifestando la loro solidariet\u00e0 nei confronti del beniamino della Curva. I &#8220;muri&#8221; dei social network sono stati &#8220;imbrattati&#8221; di post pro-Biccio. Addirittura c&#8217;\u00e8 stato qualche tifoso che ha chiesto, come forma estrema di protesta, al patron del sodalizio silano di ritirare la squadra dal campionato. Una scelta che, sicuramente, Eugenio Guarascio e soci non hanno nessuna intenzione di intraprendere, considerato che la societ\u00e0, sin da subito ha &#8220;condannato&#8221; il gesto del suo attaccanto, sospendendolo dall&#8217;attivit\u00e0 agonistica. Lo stesso &#8220;Biccio&#8221;, affrettandosi a chiarire che il suo gesto, non voleva essere offensivo nei confronti delle forze dell&#8217;ordine, n\u00e8 tantomeno lesivo nei confronti dei familiari di Filippo Raciti, l&#8217;ispettore di polziia, morto durante quel drammatico Catania-Palermo del 2007, ma solo un modo per testimoniare la sua vicinanza a quell&#8217;Antonino Speziale, condannato a otto anni, in meniera definitiva, per quella morte, terr\u00e0 oggi pomeriggio, con inizio alle 14:30, presso l&#8217;Hotel Royal, di via Molinella, una conferenza stampa. Cosa dir\u00e0? Ribadir\u00e0 la sua innocenza? Chieder\u00e0 scusa? Domande alle quali si avranno precise risposte fra quasi un&#8217;ora. Intanto la mazzata del Daspo, ridimensionata molto dall&#8217;avvocato Chiacchio, uno dei consulenti legali della societ\u00e0 silana, non \u00e8 l&#8217;unica scure che s&#8217;\u00e8 abbattutta sul giocatore. Domani giorno di decisioni del giudice sportivo, potrebbe arrivare qualche ulterore provvedimento. Cos\u00ec come si aspetta anche la decisione che prender\u00e0 il procuratore federale Stefano Palazzi, numero uno della magistratura sportiva che dalla Lnd (lega nazionale dilettanti, ndr) ha ricevuto il fascicolo su &#8220;Biccio&#8221;, con richiesta di deferimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; \u00abSiamo tutti &#8220;Biccio&#8221;\u00bb. Il Daspo di tre anni, emesso dal questore di Catanzaro, Guido Marino, per via di quella maglietta &#8220;pro-Speziale&#8221;, mostrata da Arcidiacono davanti alle telecamere di Rai Sport1, festeggiando il suo gol, messo a segno sabato pomeriggio nel derby contro il Sambiase<\/p>\n","protected":false},"author":22,"featured_media":8066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-8065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8065"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8066"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}