{"id":80860,"date":"2017-07-07T09:25:38","date_gmt":"2017-07-07T07:25:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/montano-le-casse-e-iniziano-a-ballare-denunciate-quattro-persone\/"},"modified":"2023-01-16T19:33:45","modified_gmt":"2023-01-16T18:33:45","slug":"163894-montano-le-casse-e-iniziano-a-ballare-denunciate-quattro-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/163894-montano-le-casse-e-iniziano-a-ballare-denunciate-quattro-persone\/","title":{"rendered":"Montano le casse e iniziano a ballare, denunciate quattro persone"},"content":{"rendered":"<h4>La polizia di Stato \u00e8 intervenuta in provincia di Cosenza elevando una sanzione da 32mila euro.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROSSANO &#8211; Gli agenti della Polizia di Stato di Rossano, coadiuvati da personale la Polizia Municipale la scorsa notte hanno proceduto al controllo amministrativo di un villaggio turistico, ove all\u2019interno si stava svolgendo una serata danzante.\u00a0Dalle verifiche emergeva, che all\u2019evento aperto ed esposto al pubblico, si <strong>accedeva mediante il pagamento di un biglietto nell\u2019ambito di una attivit\u00e0 imprenditoriale sprovvista di qualsivoglia autorizzazione<\/strong> per pubblico intrattenimento e cosa ancor pi\u00f9 grave di licenza di agibilit\u00e0 dei luoghi interessati all\u2019evento.\u00a0A riguardo si \u00e8 accertato che alla serata danzante hanno partecipato circa 600 persone, e che gli organizzatori avevano la sola autorizzazione, regolarmente rilasciata dal comune di Rossano, per l\u2019esercizio di complesso turistico ricettivo e tutti i servizi annessi all\u2019intrattenimento delle sole persone in esso alloggiate.<br \/>\n&nbsp;<br \/>\nInvece gli organizzatori della festa danzante, sono risultati privi delle autorizzazioni obbligatorie per il pubblico intrattenimento e della <strong>licenza di agibilit\u00e0 rilasciata dal comune competente, obbligatoria per eventi con presenze superiore a 200 persone.\u00a0<\/strong>Le serate danzanti, come quella in argomento, sono regolamentate da apposite normative per le quali gli interessati a titolo organizzativo devono richiedere alle Istituzioni preposte le necessarie autorizzazioni.\u00a0Inoltre veniva rilevata altres\u00ec la falsa compilazione delle schede degli alloggiati presenti all\u2019interno del villaggio turistico.\u00a0Dalle specifiche verifiche \u00e8 emerso il fittizio pernottamento nella struttura di ospiti che in realt\u00e0 hanno partecipato esclusivamente alla festa danzante.<br \/>\n&nbsp;<br \/>\nGli organizzatori dell\u2019evento non autorizzato sono stati denunciati all\u2019autorit\u00e0 giudiziaria per\u00a0aver aperto e tenuto abusivamente un luogo di pubblico spettacolo e intrattenimento danzante.\u00a0In concorso tra di loro e senza aver osservato le prescrizioni dell\u2019autorit\u00e0 amministrativa a tutela dell\u2019incolumit\u00e0 e della sicurezza pubblica previste dall\u2019art.80 della cosiddetta\u00a0licenza di agibilit\u00e0, venivano deferiti altres\u00ec, per aver <strong>attestato false situazioni e sottoscritto firme false sulle schede degli alloggiati con trasmissione alle autorit\u00e0 di pubblica sicurezza,<\/strong> al fine di simulare il pernottamento di 283 persone all\u2019interno del villaggio turistico.\u00a0Nei confronti dei quattro soggetti sono state elevate sanzioni amministrative, per un ammontare complessivo di circa 32.000 Euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polizia di Stato \u00e8 intervenuta in provincia di Cosenza elevando una sanzione da 32mila euro.<\/p>\n","protected":false},"author":22,"featured_media":80861,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-80860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=80860"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/80861"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=80860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=80860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=80860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}