{"id":80864,"date":"2017-07-07T12:15:32","date_gmt":"2017-07-07T10:15:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-ci-aspetta-un-weekend-caldo-e-afoso-e-la-prossima-settimana-sara-ancora-rovente\/"},"modified":"2023-01-16T19:33:45","modified_gmt":"2023-01-16T18:33:45","slug":"163907-cosenza-ci-aspetta-un-weekend-caldo-e-afoso-e-la-prossima-settimana-sara-ancora-rovente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/163907-cosenza-ci-aspetta-un-weekend-caldo-e-afoso-e-la-prossima-settimana-sara-ancora-rovente\/","title":{"rendered":"Cosenza, nuova ondata di caldo nel weekend. La prossima settimana sar\u00e0 ancora rovente"},"content":{"rendered":"<h4>L&#8217;espansione dell&#8217;anticiclone africano si tramuter\u00e0 in un fine settimana torrido e afoso, con temperature in deciso aumento su tutta la provincia di Cosenza. Nella prossima settimana continuer\u00e0 l&#8217;intensa ondata di caldo subtropicale<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Dopo una settimana tutto sommato nella norma dal punto di vista climatico, con temperature nella media del periodo, <strong>il caldo \u00e8 pronto a tornare nuovamente protagonista<\/strong>. L&#8217;espansione dell&#8217;<strong>anticiclone africano<\/strong> verso nord est, anche a causa di una depressione che sta interessando la Penisola Iberica, porter\u00e0 ad una <strong>nuova ondata di calore<\/strong> che avr\u00e0 i suoi massimi effetti proprio in concomitanza di questo fine settimana, quando la colonnina di mercurio sulla provincia di Cosenza tender\u00e0 a salire raggiungendo <strong>valori intorno ai 37\u00a0gradi<\/strong>. Ci aspetta dunque <strong>un weekend sotto il sole cocente<\/strong>, a tratti afoso nelle zone interne e con <strong>assenza totale di precipitazioni<\/strong>. Questo non fa altro che acuire la <strong>crisi idrica<\/strong> e il <strong>periodo di forte siccit\u00e0<\/strong> dovuta alla mancanza di pioggia sulla Calabria da\u00a0oltre un mese. I mari, sia lo jonio che il tirreno, risulteranno calmi o al pi\u00f9 poco mossi mentre la ventilazione debole.<\/p>\n<p><span style=\"color: #ff0000;\"><b>Le previsioni del tempo del colonnello Mario Giuliacci\u00a0su Cosenza e Provincia\u00a0<\/b><\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Meteo Cosenza e Provincia: weekend 7-9 Luglio\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/47FA_VkOK1k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Poche novit\u00e0 sostanziali anche nella prossima settimana quando <strong>il caldo continuer\u00e0 ad essere\u00a0insistente<\/strong>\u00a0e l&#8217;aria rovente africana determiner\u00e0 un ulteriore lieve rialzo delle temperature. Il clima &#8220;soffocate&#8221; verr\u00e0 smorzato solo a met\u00e0 mese quando finalmente arriveranno <strong>correnti fresche che intorno al 15\/16 di luglio spazzeranno via la canicola<\/strong> <strong>africana<\/strong>.<\/p>\n<div id=\"attachment_163911\" style=\"width: 623px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-163911\" class=\"wp-image-163911\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/Mappa-Meteo-caldo-luglio.jpg\" alt=\"Mappa Meteo caldo luglio\" width=\"613\" height=\"405\" title=\"\"><p id=\"caption-attachment-163911\" class=\"wp-caption-text\">Nella prossima settimana ci aspettano ancora giornate di caldo africano<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;espansione dell&#8217;anticiclone africano si tramuter\u00e0 in un fine settimana torrido e afoso, con temperature in deciso aumento su tutta la provincia di Cosenza. Nella prossima settimana continuer\u00e0 l&#8217;intensa ondata di caldo subtropicale<\/p>\n","protected":false},"author":22,"featured_media":80865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,221],"tags":[],"class_list":["post-80864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-previsioni-meteo-per-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=80864"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/80864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/80865"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=80864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=80864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=80864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}