{"id":81284,"date":"2017-07-15T12:32:21","date_gmt":"2017-07-15T10:32:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/proclamati-i-vincitori-della-start-cup-calabria-competizione-di-idee-dimpresa\/"},"modified":"2023-01-16T19:34:13","modified_gmt":"2023-01-16T18:34:13","slug":"165579-proclamati-i-vincitori-della-start-cup-calabria-competizione-di-idee-dimpresa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/165579-proclamati-i-vincitori-della-start-cup-calabria-competizione-di-idee-dimpresa\/","title":{"rendered":"Proclamati i vincitori della Start Cup Calabria, competizione di idee d&#8217;impresa"},"content":{"rendered":"<h4>E&#8217; il nono\u00a0successo della Start Cup Calabria che ha assegnato la vittoria a &#8220;Ry GoldZip&#8221;, formulazione ad uso topico in grado di curare le ulcere diabetiche.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PIZZO (VV) &#8211; Svoltasi nei suggestivi ambienti del Castello Murat di Pizzo, la finale della competizione di <strong>idee d&#8217;impresa innovative<\/strong>, organizzata da Universit\u00e0 della Calabria, Universit\u00e0 Magna Graecia, Universit\u00e0 Mediterranea e CalabriaInnova, ha decretato il secondo posto per <strong>&#8220;GreenMo&#8221;<\/strong>, produzione di superfood fresco tramite cialde, e il terzo per <strong>&#8220;Biopharma membrane technologies&#8221;<\/strong>, membrana ad alta efficienza per il settore farmaceutico. A deliberare i primi tre vincitori della Start Cup Calabria una giuria di esperti, imprenditori, venture capitalist, giornalisti di settore e rappresentanti istituzionali.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-165587 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/impresa-2-440x247.jpg\" alt=\"impresa 2\" width=\"543\" height=\"305\" title=\"\"><\/p>\n<p>Per il primo classificato un premio in denaro di <strong>5mila euro<\/strong> oltre al &#8220;Premio Speciale Studio Rubino&#8221;, dello studio legale Rubino appunto, del valore di 4.000 euro consistente in un pacchetto servizi integrato di consulenza in propriet\u00e0 industriale per il deposito di una domanda di brevetto italiano. Premio da <strong>3mila euro<\/strong> per il secondo classificato e <strong>2mila<\/strong> per il terzo. Il Premio Speciale NTT Data Open Innovation\u00a0\u00e8 stato assegnato, invece, a <strong>&#8220;Smart Mobility Lab&#8221;<\/strong>, dispositivo per l&#8217;ottimizzazione del funzionamento dei semafori basato su smartphone e big data. E il Premio Speciale &#8220;One Ticket Heroes&#8221; a &#8220;GreenMo&#8221;. I primi tre classificati della business plan accademica accederanno alla finale nazionale del PNI, il <strong>Premio Nazionale per l&#8217;Innovazione<\/strong>, che si svolger\u00e0 a Napoli dal 30 novembre all&#8217;1 dicembre 2017.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-165588 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/impresa-3-440x247.jpg\" alt=\"impresa 3\" width=\"528\" height=\"296\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; il nono\u00a0successo della Start Cup Calabria che ha assegnato la vittoria a &#8220;Ry GoldZip&#8221;, formulazione ad uso topico in grado di curare le ulcere diabetiche.<\/p>\n","protected":false},"author":22,"featured_media":81285,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-81284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81284"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/81285"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}