{"id":81332,"date":"2017-07-17T09:04:52","date_gmt":"2017-07-17T07:04:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/discarica-scala-coeli-comitati-sollecitano-oliverio-e-preparano-una-marcia-lenta-di-protesta\/"},"modified":"2023-01-16T19:34:18","modified_gmt":"2023-01-16T18:34:18","slug":"165773-discarica-scala-coeli-comitati-sollecitano-oliverio-e-preparano-una-marcia-lenta-di-protesta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/165773-discarica-scala-coeli-comitati-sollecitano-oliverio-e-preparano-una-marcia-lenta-di-protesta\/","title":{"rendered":"Discarica Scala Coeli: Comitati sollecitano Oliverio e preparano una &#8216;Marcia lenta&#8217; di protesta"},"content":{"rendered":"<h4>Gli attivisti dei Comitati \u00a0hanno indetto una nuova manifestazione: una <strong>\u201cMarcia lenta per la biovalley del Nika\u201d<\/strong>, che si svolger\u00e0 sulla Statale 106 il <strong>prossimo 28 luglio.<\/strong><br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CARIATI (CS) &#8211; Un\u2019assemblea molto partecipata, quella indetta dal <strong>\u201cCoordinamento dei Comitati del Basso Ionio\u201d<\/strong>, che si \u00e8 svolta lo scorso venerd\u00ec\u00a0a Cariati con le rappresentanze dei comitati della provincia ionica cosentina e dell\u2019Alto Crotonese e la significativa presenza degli agricoltori della Valle del Nika.\u00a0Un segno ulteriore della mobilitazione di <strong>un intero territorio contro il progetto di ampliamento della discarica privata per rifiuti speciali<\/strong> (scarti industriali di indefinita tipologia provenienti da tutta l\u2019Italia) esistente in contrada <strong>Pipino di Scala Coeli,<\/strong> ma vicinissima a diverse localit\u00e0 di quell\u2019area.\u00a0Grande \u00e8 stato, finora, l\u2019impegno nel coinvolgere cittadini, istituzioni, forze sociali e politiche, agricoltori, associazioni (come Legambiente, Italia Nostra, Cia, Coldiretti), operatori economici, turisti ed emigrati, che hanno mostrato sensibilit\u00e0 e partecipazione alla lotta ambientalista per la salvaguardia di una zona ricca di bellezze naturalistiche, corsi d\u2019acqua, vigneti e uliveti coltivati con metodo biologico certificato all\u2019U.E., allevamenti di bovino podolico, e protetta poich\u00e9 coperta dal marchio DOP.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-165774 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/Comitato-antidiscarica3-440x239.jpg\" alt=\"Comitato antidiscarica3\" width=\"341\" height=\"185\" title=\"\">Durante la riunione \u00e8 stato tracciato un bilancio delle due ultime, intense settimane, in cui, dopo un riuscito incontro-dibattito svoltosi il 1\u00b0 luglio nel piazzale dell\u2019ex ospedale di Cariati, si \u00e8 dato vita a un <strong>sit-in informativo con raccolta firme<\/strong>, parallelo a una petizione lanciata via internet e a una forte sensibilizzazione mediatica.\u00a0Il presidio tenuto dai rappresentanti dei Comitati ha, infatti, richiamato tantissime persone del luogo e di centri anche distanti dall\u2019area interessata all\u2019impianto, motivate ad esprimere con la loro firma la partecipazione a un movimento che ha assunto i contorni <strong>di una lotta contro l\u2019abbandono del Basso Ionio, depredato di ospedali, tribunali, penalizzato in viabilit\u00e0 e trasporti ma destinato, se il progetto di ampliamento venisse approvato, a diventare \u201cla pattumiera d\u2019Italia\u201d.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-165775 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/Comitato-antidiscarica2-440x202.jpg\" alt=\"Comitato antidiscarica2\" width=\"342\" height=\"157\" title=\"\">Nel contempo, ci sono state trasferte a Terravecchia e a Crucoli, in occasione della nascita di nuovi comitati antidiscarica; sono state organizzate raccolte firme in altre localit\u00e0, come Campana; una rappresentanza di attivisti \u00e8 stata audita in Commissione Regionale Ambiente sulle ragioni dell\u2019opposizione alla richiesta di Autorizzazione Integrata Ambientale protocollata dalla ditta privata, nel dicembre scorso, presso il competente Dipartimento; allo stesso Dipartimento sono state, inoltre, inviate nuove osservazioni sulle <strong>numerose irregolarit\u00e0 della discarica esistente e del progetto del nuovo impianto.<\/strong>\u00a0L\u2019assemblea, al termine di un costruttivo dibattito, si \u00e8 determinata sul <strong>proseguimento ad oltranza della mobilitazione;<\/strong> inoltre, in risposta alla richiesta di partecipazione di paesi come Cir\u00f2, Cir\u00f2 Marina, Mandatoriccio, Pietrapaola, i sit-in informativi (sempre con raccolta firme) si svolgeranno in forma itinerante, mantenendo per quanto possibile, per il valore simbolico accanto alla Statale 106 e l\u2019ex ospedale, il presidio di Cariati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-165776 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/07\/Comitato-antidiscarica1-400x280.jpg\" alt=\"Comitato antidiscarica1\" width=\"305\" height=\"213\" title=\"\">Gli attivisti dei Comitati si impegneranno a raccoglierle anche a livello personale per <strong>raggiungere il traguardo di 5 mila firme (finora sono circa 3700 fra le due petizioni).\u00a0<\/strong>Tuttavia, la determinazione principale \u00e8 stata per una nuova manifestazione di protesta, una <strong>\u201cMarcia lenta per la biovalley del Nika\u201d<\/strong>, che si svolger\u00e0 sulla Statale 106 il <strong>prossimo 28 luglio<\/strong>, chiamando a raccolta la popolazione del Basso Ionio e tutti i soggetti istituzionali, politici e civili che insieme ai Comitati attendono dalla Regione Calabria e dal Governatore Oliverio il no allo smisurato ampliamento della discarica di Pipino e il via alla bonifica della Valle del Nika.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli attivisti dei Comitati \u00a0hanno indetto una nuova manifestazione: una \u201cMarcia lenta per la biovalley del Nika\u201d, che si svolger\u00e0 sulla Statale 106 il prossimo 28 luglio.<\/p>\n","protected":false},"author":22,"featured_media":81333,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-81332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81332"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81332\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/81333"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}