{"id":81384,"date":"2017-07-18T10:29:23","date_gmt":"2017-07-18T08:29:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/risarcito-dopo-59-anni-per-la-poliomelite-contratta-dopo-un-vaccino\/"},"modified":"2023-01-16T19:34:21","modified_gmt":"2023-01-16T18:34:21","slug":"165977-risarcito-dopo-59-anni-per-la-poliomelite-contratta-dopo-un-vaccino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/165977-risarcito-dopo-59-anni-per-la-poliomelite-contratta-dopo-un-vaccino\/","title":{"rendered":"Risarcito dopo 59 anni per la poliomelite, contratta dopo un vaccino"},"content":{"rendered":"<h4>All&#8217;uomo oggi 60enne, all&#8217;epoca neonato, era stato iniettato un <strong>vaccino insicuro e conservato in cattive modalit\u00e0.<strong style=\"line-height: 1.5;\">\u00a0Tar condanna Ministero al risarcimento.<\/strong> <\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5;\">PAOLA (CS) &#8211; La storia di un uomo <\/span><strong style=\"line-height: 1.5;\">60enne di San Lucido che, a soli 4 mesi (nel 1958), contrasse la poliomelite a causa di un vaccino &#8220;difettoso&#8221;.<\/strong><span style=\"line-height: 1.5;\"> Oggi la storia giunge ad un lieto fine:<\/span><strong style=\"line-height: 1.5;\"> il Tar ha condannato il Ministero al risarcimento dei danni subiti.<\/strong><span style=\"line-height: 1.5;\"> La commissione medica competente, infatti, accert\u00f2 nel 2011 il <\/span><strong style=\"line-height: 1.5;\">nesso tra la vaccinazione e la malattia.<\/strong><span style=\"line-height: 1.5;\"> All&#8217;uomo (all&#8217;epoca neonato) era stato iniettato un <\/span><strong style=\"line-height: 1.5;\">vaccino insicuro e conservato in cattive modalit\u00e0<\/strong><span style=\"line-height: 1.5;\">, presso l&#8217;azienda sanitaria del comune di San Lucido. Il Tar ha accolto le istanze del legale difensore dell&#8217;uomo, Anna Di Santo, nominando un commissario ad acta per rendere esecutiva la sentenza emessa tempo fa dal Tribunale di Paola.\u00a0<\/span><\/p>\n<p>Il Ministero della Salute aveva contestato la domanda del risarcimento, a causa del ritardo della stessa presentazione dell&#8217;istanza (4 anni dopo). Ma il giudice di Paola, Giselda Stella, non si trov\u00f2 d&#8217;accordo, riscontrando subito\u00a0lo stato in cui ancora oggi versa il 60enne. <strong>Segni e sofferenze che hanno cambiato per sempre la sua vita. L&#8217;uomo, comunque, non si \u00e8 mai abbattuto e ha continuato a lottare.<\/strong> Nonostante le sue insistenti\u00a0richieste di avere accesso alla cartella clinica ospedaliera (relativa al suo ricovero, quando gli venne iniettato il vaccino); questa non venne mai riscontrata. Con la spiegazione che<strong> il\u00a0registro delle vaccinazioni antipoliomielite del comune di San Lucido prima del 1964, era stato smarrito.<\/strong> L&#8217;uomo non si \u00e8 arreso e, infine, \u00e8 riuscito a trovare il documento che accertava la sua vaccinazione avvenuta <strong>il 15 dicembre 1958.<\/strong><\/p>\n<p>Oggi, finalmente, una piccola giustizia \u00e8 stata restituita al 60enne (anche se i danni provocati dal vaccino &#8220;difettoso&#8221;, non gli restituiranno mai la salute persa). Saranno accreditati <strong>200mila euro<\/strong> e nei prossimi mesi la somma restante di <strong>un milione.<\/strong> Lo Stato, inoltre, dovr\u00e0 versargli per tutta la sua esistenza la cifra di circa <strong>seimila euro al mese.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>All&#8217;uomo oggi 60enne, all&#8217;epoca neonato, era stato iniettato un vaccino insicuro e conservato in cattive modalit\u00e0.\u00a0Tar condanna Ministero al risarcimento.<\/p>\n","protected":false},"author":22,"featured_media":81385,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-81384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81384"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/81385"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}