{"id":81440,"date":"2017-07-19T10:24:11","date_gmt":"2017-07-19T08:24:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/volley-cosenza-maria-stella-barbagallo-e-loren\/"},"modified":"2023-01-16T19:34:24","modified_gmt":"2023-01-16T18:34:24","slug":"166225-volley-cosenza-maria-stella-barbagallo-e-loren","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/166225-volley-cosenza-maria-stella-barbagallo-e-loren\/","title":{"rendered":"Volley Cosenza, Maria Stella Barbagallo e Lorenzo Salerno entrano nello staff tecnico"},"content":{"rendered":"<h4>La Volley Cosenza\u00a0ASD sceglie la\u00a0linea dei giovani anche nel Settore Tecnico. \u00a0Arrivano Maria Stella Barbagallo e Lorenzo Salerno.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Si completa cos\u00ec il quadro degli allenatori della compagine rossoblu. Barbagallo e Salerno si aggiungono ai confermati Marco Crispino e Dario Rovito. La qualificata compagine dei trainer, collaboratori dei settori giovanili e preparatori vede tra l\u2019altro Romy Rizzuto, Antonio Vallotta e Antonio Gerbasi. Per quanto giovanissimi le due new entry hanno gi\u00e0 maturato diverse esperienze, un ottimo presupposto per questo nuovo impegno nella Volley Cosenza, che ha come mission proprio quella di puntare sui giovani talenti, siano essi atlete che tecnici. La compagine cosentina ha voluto dare piena fiducia a giovani tecnici che hanno la passione della pallavolo nel cuore ma soprattutto vogliono crescere in questo mondo e nella propria Regione. Bisogna credere nelle nuove generazioni, se sono poi frutto della nostra terra, se hanno caparbiet\u00e0 e volont\u00e0, \u00e8 indispensabile che restino e lavorino qui, perch\u00e9 qui possono rendere fertile un territorio per troppi anni reso arido da politiche ottuse.<\/p>\n<p>Maria Stella Barbagallo viene dalla recente esperienza nella stagione appena trascorsa a Roma dove ha lavorato con ben due societ\u00e0, la Volley Friends, societ\u00e0 di grande caratura nel Lazio e a livello nazionale nei settori giovanili, e l\u2019Apd Don Orione nella quale ha ricoperto il ruolo di primo allenatore nel campionato di seconda divisione. In precedenza aveva curato gruppi di minivolley e alcuni settori giovanili a Paola e San Lucido. Ha anche fatto parte dello staff tecnico della rappresentativa provinciale femminile di Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p>Lorenzo Salerno ha un passato da giocatore con la EuroSport Brutium. nei campionati giovanili fra Under 16 e 18 . Poi qualche anno fra serie C e D fra Cosenza, Donnici e Mendicino. Dal 2011 ha iniziato ad allenare sia in settori giovanili che in campionati maggiori in Prima Divisione e nell\u2019ultima stagione come secondo nella Milani Rende in serie C maschile. Con la formazione under 16 della Milani lo scorso anno si \u00e8 classificato terzo nella Finale Regionale. Dal 2012 ha guidato la rappresentativa provinciale maschile di Cosenza dapprima da secondo e nel 2017 da Primo allenatore, vincendo negli ultimi quattro anni il Trofeo delle Province.<br \/>\nLe premesse ci sono tutto affinch\u00e8 dalle mani di questi bravi istruttori maturino ragazze che raggiungano grande preparazione e possano competere ai massimi livelli. Nel recente stage dell\u2019Italia under 16 a Camigliatello Silano con gli incontri amichevoli Italia Belgio, una delegazione dei tecnici della Volley Cosenza composta da Barbagallo, Vallotta e Rizzuto guidata dal presidente del sodalizio cosentino Rocco Filippelli ha incontrato Simonetta Valle ed i tecnici della stessa nazionale. Tanti sono stati i suggerimenti dati ai giovani allenatori bruzi. In particolare Simonetta Valle, la pi\u00f9 esperta e rinomata esperta allenatrice nazionale di settori giovanili, \u00e8 stata prodiga di consigli, ma soprattutto ha concordato con il presidente Filippelli uno stage dedicato agli allenatori della Volley Cosenza da tenersi nei prossimi mesi nella citt\u00e0 bruzia. Un grande lavoro che sicuramente contribuir\u00e0 ancor pi\u00f9 a strutturare al meglio i settori giovanili della pallavolo femminile a Cosenza. L\u2019obiettivo espresso ai tecnici della nazionale italiana \u00e8 quello di vedere un giorno non lontano una ragazza cosentina convocata in una nazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Volley Cosenza\u00a0ASD sceglie la\u00a0linea dei giovani anche nel Settore Tecnico. \u00a0Arrivano Maria Stella Barbagallo e Lorenzo Salerno.<\/p>\n","protected":false},"author":24,"featured_media":81441,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-81440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81440"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/81441"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}