{"id":81690,"date":"2017-07-24T09:47:30","date_gmt":"2017-07-24T07:47:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sanita-aieta-greco-ai-sindaci-la-programmazione-della-sanita-calabrese\/"},"modified":"2023-01-16T19:34:41","modified_gmt":"2023-01-16T18:34:41","slug":"167268-sanita-aieta-greco-ai-sindaci-la-programmazione-della-sanita-calabrese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/167268-sanita-aieta-greco-ai-sindaci-la-programmazione-della-sanita-calabrese\/","title":{"rendered":"Sanit\u00e0, Aieta e Greco: &#8220;ai sindaci la programmazione della sanit\u00e0 calabrese&#8221;"},"content":{"rendered":"<h4>I consiglieri regionali Giuseppe Aieta e Orlandino Greco, chiedono che i sindaci siano i veri protagonisti, i custodi dei diritti di cittadinanza e che quindi siano loro ad occuparsi della programmazione in tema di sanit\u00e0\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CETRARO (CS) &#8211; A margine dell&#8217;incontro avuto a Cetraro venerd\u00ec scorso i due consiglieri regionali hanno ricevuto numerose richieste di intervento e di ascolto, soprattutto relativamente a storie di diritti negati e in particolar modo in sanit\u00e0. &#8220;Sulla base di una pressante richiesta occorre darsi da fare per una sanit\u00e0 degna di questo nome. E gi\u00e0, perch\u00e9 nella nostra regione di sanit\u00e0 si muore &#8211; scrivono Aieta e Greco &#8211; e si sta peggio anzich\u00e9 guarire. Di sanit\u00e0 c&#8217;\u00e8 chi si arricchisce e chi diventa potente, sino a decidere, spesso indebitamente, le sorti degli altri. Non solo! Ci\u00f2 avviene in Calabria da sempre con un commissariamento divenuto oramai strutturale fino a diventare parte integrante del DNA di una Regione \u201csotto tutela\u201d per tutto. Un ruolo, quello che svolge l&#8217;attuale commissario ad acta, divenuto ingombrante, pericoloso e devastante per la salute dei cittadini. Ci\u00f2 in quanto caratterizzato dall&#8217;assunzione di decisioni non condivise e da quelle difese isteriche che possono tutto al pi\u00f9 caratterizzare, sopportandone i conseguenti giudizi sociali, l&#8217;uomo ma non le istituzioni&#8221;.<\/p>\n<p>&#8220;L\u2019atteggiamento del commissario Scura \u00e8 pi\u00f9 funzionale ad incidere negativamente sul sistema, gi\u00e0 debole per suo conto &#8211; scrivono i due consiglieri &#8211; invece che costruirlo e ripararlo. I dati sono sotto gli occhi di tutti: il disavanzo che cresce, la mobilit\u00e0 passiva altrettanto e una rete manageriale che dissente, spesso a ragione. Il tutto a discapito delle prestazioni sanitarie che sono ridotte all&#8217;infinitesimale, quasi ad annullare il diritto alla salute. Esempio dello spregio, intendendo per tale l&#8217;esercizio della violenza esercitata dal commissario sugli atti che, di contro, avrebbe motivo di supportare. \u00c8 il trattamento riservato all&#8217;atto aziendale della pi\u00f9 popolosa ASP calabrese (Cosenza), che incide sulla salute di 750 mila residenti e oltre, e all&#8217;assistenza ospedaliera del Tirreno cosentino, oramai ridotta al lumicino. Due atteggiamenti impeditivi del miglioramento dello stato lacunoso che i cittadini sopportano nel vedersi negata una sanit\u00e0 efficiente. Oltretutto, su questo, incide negativamente l\u2019assurda competizione generatasi tra due delle forze politiche di maggioranza governativa. Un PD che da Roma non ha la forza di superare il commissariamento di Scura e Alternativa Popolare che, pur gestendo il Ministero alla Sanit\u00e0, nulla ha fatto per migliorare in Calabria un settore primario per le nostre comunit\u00e0. In mezzo, c&#8217;\u00e8 chi paga il conto di tutto questo&#8221;.<\/p>\n<p>&#8220;Da parte nostra c\u2019\u00e8 l&#8217;impegno a far s\u00ec che i sindaci calabresi &#8211; concludono &#8211; assumano un ruolo attivo nella programmazione della sanit\u00e0, anzi, che siano essi stessi a proporre il piano regionale della sanit\u00e0. Un modo perch\u00e9 la stessa corrisponda al soddisfacimento delle esigenze dei calabresi altrimenti violate e vilipese. Del resto essi sono i veri protagonisti, i custodi dei diritti di cittadinanza ed \u00e8 a loro che daremo sostegno nella fase dell&#8217;elaborazione e voce in Consiglio Regionale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I consiglieri regionali Giuseppe Aieta e Orlandino Greco, chiedono che i sindaci siano i veri protagonisti, i custodi dei diritti di cittadinanza e che quindi siano loro ad occuparsi della programmazione in tema di sanit\u00e0\u00a0<\/p>\n","protected":false},"author":21,"featured_media":81691,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-81690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81690"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/81691"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}