{"id":81999,"date":"2017-07-30T07:46:14","date_gmt":"2017-07-30T05:46:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maltratta-lex-le-sottrae-figli-incendia-le-auto-delle-sue-amiche-arrestato-36enne\/"},"modified":"2023-01-16T19:35:01","modified_gmt":"2023-01-16T18:35:01","slug":"168664-maltratta-lex-le-sottrae-figli-incendia-le-auto-delle-sue-amiche-arrestato-36enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/168664-maltratta-lex-le-sottrae-figli-incendia-le-auto-delle-sue-amiche-arrestato-36enne\/","title":{"rendered":"Maltratta l&#8217;ex compagna e incendia le auto delle sue amiche. Arrestato 36enne"},"content":{"rendered":"<h4>L&#8217;accusa \u00e8 di maltrattamenti in famiglia ma anche sottrazione di minori e danneggiamento. Il 36enne \u00e8 stato arrestato dai carabinieri<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SANTA CATERINA DELLO JONIO (CZ) &#8211; E&#8217; finito in manette C. M., di 36 anni, arrestato dai carabinieri di Soverato con l&#8217;accusa di maltrattamenti contro familiari e conviventi, sottrazione di minori e danneggiamento seguito da incendio. Il tutto sarebbe nato dopo il rifiuto della sua ex compagna a tornare insieme a lui. Da quel momento \u00e8 iniziato l&#8217;incubo per la donna e per le persone a lei vicine.<\/p>\n<p>Un incubo iniziato tre anni fa, e degenerata il 4 luglio scorso, quando il 36enne, utilizzando del liquido infiammabile, avrebbe appiccato il fuoco alle auto di propriet\u00e0 di due amiche della sua ex accusate, a suo dire, di averla appoggiata e aiutata. I carabinieri avrebbero ricostruito l\u2019escalation di violenza posta in essere dall&#8217;uomo che sarebbe stato protagonista di maltrattamenti anche davanti ai figli minori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;accusa \u00e8 di maltrattamenti in famiglia ma anche sottrazione di minori e danneggiamento. Il 36enne \u00e8 stato arrestato dai carabinieri<\/p>\n","protected":false},"author":22,"featured_media":82000,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-81999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=81999"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/81999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82000"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=81999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=81999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=81999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}