{"id":82234,"date":"2017-08-06T04:30:13","date_gmt":"2017-08-06T02:30:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sede-calabrese-a-bruxelles-in-due-anni-scarsissimo-organico-e-utilizzo-pari-a-zero\/"},"modified":"2023-01-16T19:35:17","modified_gmt":"2023-01-16T18:35:17","slug":"169719-sede-calabrese-a-bruxelles-in-due-anni-scarsissimo-organico-e-utilizzo-pari-a-zero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/169719-sede-calabrese-a-bruxelles-in-due-anni-scarsissimo-organico-e-utilizzo-pari-a-zero\/","title":{"rendered":"Sede Regione Calabria a Bruxelles, in due anni utilizzo pari a zero"},"content":{"rendered":"<h4 class=\"p1\"><b>Denunciata la scarsa trasparenza nella gestione degli uffici<\/b><b style=\"line-height: 1.5;\">: \u201cDopo due anni riorganizzano l&#8217;organico\u201d.<\/b><!--more--><\/h4>\n<p class=\"p1\"><b>\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">BRUXELLES &#8211; &#8220;La Regione Calabria si \u00e8 finalmente ricordata di avere una propria sede di rappresentanza a Bruxelles e bandisce un avviso pubblico per la <strong>selezione di 5 consulenti<\/strong> \u201cdi supporto al coordinamento tecnico delle attivit\u00e0 di programmazione settoriale e territoriale del POR Calabria FESR FSE 2014\/2020 e la sua integrazione con la Cooperazione Territoriale Europea, per la sede di Bruxelles della Regione Calabria\u201d, cos\u00ec come si legge nell&#8217;avviso&#8221;. Lo scrive in una nota l&#8217;eurodeputata del MoVimento 5 Stelle,<strong> Laura Ferrara.<\/strong>\u00a0&#8220;\u00c8 da novembre 2015 che la sede di Bruxelles, almeno formalmente, \u00e8 <strong>scoperta di organico.<\/strong> Salvo la presenza sporadica di un funzionario regionale, cos\u00ec come ci fu comunicato in una mail in cui chiedevamo informazioni al Dipartimento Programmazione della Regione Calabria. <strong>Quasi due anni in cui la sede ha organizzato pochissime attivit\u00e0 per lo pi\u00f9 convegni e in cui la promozione del nostro territorio, cos\u00ec come prevede la mission della sede stessa, \u00e8 stata pari a zero.<\/strong> Difficile tracciare come sia stata utilizzata, dunque, negli ultimi due anni la sede anche perch\u00e9 quelle poche informazioni presenti in rete \u2013 una breve sezione sul sito <span style=\"text-decoration: underline;\"><a href=\"https:\/\/quicosenza.it\/news\/3133\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">calabriaeuropa.it<\/span><\/a> <\/span>\u2013 non sono esaustive. Ci\u00f2 che sappiamo \u00e8 che fino a Novembre 2015 un esperto del Laboratorio Calabria 2020 ha seguito le attivit\u00e0 in loco.<\/p>\n<p class=\"p1\">\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p class=\"p1\">Dopo quella data, pur non avendo alcun contratto o deroga alla consulenza precedente con la Regione, lo stesso continuava ad essere presente nella sede calabrese a Bruxelles, non si capisce bene con quale funzione.<strong> Questa sede si \u00e8 connotata in questo periodo pi\u00f9 come un ufficio privato che come un punto di riferimento in Europa.<\/strong> Non si rinviene alcuna trasparenza sulla programmazione delle attivit\u00e0 svolte o l&#8217;organizzazione di iniziative, a differenza di altre Regioni le cui sedi hanno siti web dedicati in cui vengono anche indicati i componenti dell&#8217;organigramma, promuovono attivit\u00e0 di stages, tirocini e soprattutto, organizzano giornate di promozione territoriale.\u00a0Sul sito della Regione Calabria appare l&#8217;avviso pubblico per la selezione dei 5 esperti che dovranno anche prestare la loro opera nella sede e che avranno un contratto di consulenza pari, addirittura, a 36 mesi prorogabile non \u00e8 specificato fino a quante volte. Quei bandi &#8211; conclude la Ferrara &#8211; in salsa calabra, i cui beneficiari, magari gli stessi gi\u00e0 selezionati con il bando precedente, vengono blindati nella speranza, chiss\u00e0, di una possibile stabilizzazione&#8221;.<\/p>\n<h2 class=\"p1\"><\/h2>\n<h2 class=\"p1\" style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2 class=\"p1\" style=\"text-align: center;\"><\/h2>\n<h2 class=\"p1\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3134\" target=\"_blank\" rel=\"noopener\">Oliverio vola in Belgio e inaugura a Bruxelles una sede della Regione Calabria<\/a><\/span><\/h2>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3135\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">La Calabria degli sprechi: circa 100mila euro l\u2019anno, per una sede chiusa<\/span><\/a><\/h2>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3136\" target=\"_blank\" rel=\"noopener\">\u00a0<span class=\"current\">La sede della Regione Calabria a Milano chiusa per l\u2019intera durata dell\u2019EXPO<\/span><\/a><\/span><\/h2>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>Denunciata la scarsa trasparenza nella gestione degli uffici: \u201cDopo due anni riorganizzano l&#8217;organico\u201d.<\/p>\n","protected":false},"author":22,"featured_media":82235,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22,571],"tags":[],"class_list":["post-82234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82234"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82235"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}