{"id":82277,"date":"2017-08-06T12:34:36","date_gmt":"2017-08-06T10:34:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/diamante-rimane-ancora-senzacqua-due-giorni-dallultimo-guasto\/"},"modified":"2023-01-16T19:35:20","modified_gmt":"2023-01-16T18:35:20","slug":"169871-diamante-rimane-ancora-senzacqua-due-giorni-dallultimo-guasto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/169871-diamante-rimane-ancora-senzacqua-due-giorni-dallultimo-guasto\/","title":{"rendered":"Diamante ancora senz\u2019acqua a due giorni dall\u2019ultimo guasto"},"content":{"rendered":"<h4>Stessa zona, ancora un tubo che perde. La cittadinanza stavolta avvisata adeguatamente e in tempo mentre infervora il dibattito sulla morosit\u00e0 dell\u2019ente comunale<\/h4>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>DIAMANTE (CS) &#8211;\u00a0 Nuovo intoppo per la rete idrica che rifornisce Diamante. Ne da a conoscenza il Comune di Diamante con avviso sul sito istituzionale: \u201cIl guasto \u00e8 stato individuato e gli operatori Sorical sono al lavoro per risolvere il problema ma, al momento, non si possono definire con certezza i tempi di conclusione dell&#8217;intervento\u201d. A dispetto di quanto avvenuto due giorni fa, stavolta e sin dalle prime ore del mattino si \u00e8 dato allerta della problematica attraverso il<strong> megafonaggio da parte delle auto di Polizia Municipale<\/strong> che hanno fatto il giro del paese per informare e preparare la popolazione sul disagio che verr\u00e0 a procurarsi. In questo momento i tecnici sono al lavoro intenti a riparare la nuova rottura che peraltro &#8211; ci \u00e8 stato detto dagli addetti ai lavori sul posto &#8211; \u00a0\u00e8 occorsa quasi nello stesso punto danneggiato e poi riparato l\u2019altro ieri, giusto qualche metro pi\u00f9 avanti. Da capire se il nuovo danneggiamento sia da correlarsi o meno all\u2019ultimo in ordine di tempo.<\/p>\n<p>La rete idrica rifornente \u00e8 considerata da molti esperti come vero e proprio colabrodo, ma avanza \u00a0il <strong>problema della morosit\u00e0 nei confronti della societ\u00e0 erogatrice del servizio idrico<\/strong>, sollevata a pi\u00f9 riprese anche durante la seduta del Consiglio Comunale nel luglio scorso da parte del Gruppo consiliare \u201cPer Una Diamante Migliore&#8221;. Proprio in queste ore il suo consigliere di minoranza Antonio Cauteruccio attraverso i social provoca l\u2019amministrazione comunale chiedendo al sindaco \u201cse ha pagato la Sorical\u201d.<\/p>\n<p>A pensar male si fa peccato ma riparare un guasto e ritrovarsene un altro qualche metro pi\u00f9 in l\u00e0 non \u00e8 poi cos\u00ec normale. Nell\u2019ultima interrogazione i punti all\u2019ordine del giorno sono stati proprio la liquidazione delle fatture alla Sorical degli ultimi 3 anni e gli eventuali interventi \u201c effettuati nelle ultime settimane sui serbatoi, sulle sorgenti e sulla rete idrica al fine di ottimizzare la portata, la distribuzione e l\u2019erogazione di acqua sul territorio comunale\u201d. Si parla almeno di <strong>400 mila euro di debiti comunali<\/strong> verso la Societ\u00e0 Risorse Idriche Calabresi e le accuse vertono sui mancati investimenti\u00a0 (61 mila in tre anni, circa il 5% del totale del pacchetto del servizio idrico integrato da poter utilizzare) soprattutto a fronte degli ultimi rilievi idrici risalenti al 2014 in base ai quali \u00e8 ipotizzabile una <strong>perdita nelle condotte idriche in misura del 40% circa<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #0000ff;\">LEGGI ANCHE:<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3142\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Diamante a secco, ai cittadini mancano acqua e informazioni<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stessa zona, ancora un tubo che perde. La cittadinanza stavolta avvisata adeguatamente e in tempo mentre infervora il dibattito sulla morosit\u00e0 dell\u2019ente comunale &nbsp;<\/p>\n","protected":false},"author":22,"featured_media":82278,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-82277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82277"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82278"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}