{"id":82610,"date":"2017-08-18T15:41:33","date_gmt":"2017-08-18T13:41:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-a-corigliano-ragazzino-perde-la-vita-in-un-incidente\/"},"modified":"2023-01-16T19:35:42","modified_gmt":"2023-01-16T18:35:42","slug":"171306-tragedia-a-corigliano-ragazzino-perde-la-vita-in-un-incidente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/171306-tragedia-a-corigliano-ragazzino-perde-la-vita-in-un-incidente\/","title":{"rendered":"Tragedia a Corigliano, ragazzino cade e perde la vita"},"content":{"rendered":"<h4>Il quattordicenne \u00e8 morto sul colpo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO CALABRO (CS) &#8211; Un ragazzino di quattordici anni \u00e8 morto oggi intorno alle 17.00 a Corigliano Calabro. Il giovane pare sia caduto dalla bicicletta nei pressi di una macelleria mentre percorreva via Nazionale. I genitori che risiedono a Corigliano Calabro, che si trovavano nelle vicinanze, sono accorsi immediatamente sul posto ed hanno assistito inermi alla tragedia. Sul posto sono intervenuti i sanitari del 118 e l&#8217;elisoccorso che non hanno potuto far altro che constatare l&#8217;avvenuto decesso. <strong>L&#8217;adolescente sembrerebbe che, per cause ancora in corso d&#8217;accertamento, abbia perso il controllo della bici e scivolando a terra abbia battuto il cranio al marciapiede.<\/strong> I carabinieri sono al lavoro per capire se il ragazzino sia stato investito da un auto o abbia perso l&#8217;equilibrio a causa di un malore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il quattordicenne \u00e8 morto sul colpo.<\/p>\n","protected":false},"author":22,"featured_media":82611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-82610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82610"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82611"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}