{"id":82618,"date":"2017-08-19T06:25:17","date_gmt":"2017-08-19T04:25:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendio-cosenza-vecchia-distrutti-manoscritti-bernardino-telesio\/"},"modified":"2023-01-16T19:35:42","modified_gmt":"2023-01-16T18:35:42","slug":"171360-incendio-cosenza-vecchia-distrutti-manoscritti-bernardino-telesio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/171360-incendio-cosenza-vecchia-distrutti-manoscritti-bernardino-telesio\/","title":{"rendered":"Spento l&#8217;incendio a Cosenza Vecchia, distrutti i manoscritti di Bernardino Telesio (FOTO)"},"content":{"rendered":"<h4>Tre persone morte carbonizzate e\u00a0mezzo millennio di storia cosentina in fumo. La famiglia Bilotti da otto anni chiedeva alla Procura di Cosenza di intervenire.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211;\u00a0Tre persone morte carbonizzate e il patrimonio storico culturale della citt\u00e0 andato in fumo. Questo il risultato del mancato intervento dei servizi sociali presso la famiglia Noce. Roberto Golia, la moglie Serafina Speranza e lo zio Antonio Noce hanno perso la vita avvolti dalle fiamme. Il fratello, che viveva con loro in casa, \u00e8 salvo perch\u00e9 da poche settimane era ospite dell&#8217;Oasi Francescana. Fino allo stremo delle sue forze la donna ha chiesto aiuto urlando dal balcone. I vigili del fuoco sono arrivati con oltre quaranta minuti di ritardo e l&#8217;acqua a cui attingere nel quartiere non c&#8217;era. Ritardi su ritardi e il rogo si \u00e8 esteso ai piani superiori e alla residenza Ruggi D&#8217;Aragona. Nel palazzo nobiliare risalente al 1100, che la famiglia Bilotti aveva inteso aprire al pubblico, erano conservati, in una fornita biblioteca gi\u00e0 catalogata dal Centro Studi Telesiani, i documenti pi\u00f9 rari e significativi della storia della citt\u00e0.<strong> Tra questi diverse pergamene oltre alle uniche copie esistenti dei manoscritti gotici di Bernardino Telesio (tra cui la prima stampa del De rerum natura iuxta propria principia), i carteggi tra Bombini e Galileo Galilei,\u00a0<\/strong>degli scritti del filosofo Aulo Giano Parrasio e degli atti di suo fratello cardinale e primo ministro di Carlo V.<\/p>\n<p>&nbsp;<\/p>\n<p>Cosenza perde cos\u00ec mezzo millennio di memoria storica che era conservata nell&#8217;antico campanile del Duomo di Cosenza. Roberto Bilotti\u00a0attonito assiste alla scena guardando, inerme, andare in fumo tutto il patrimonio (dipinti, mobili d&#8217;antiquariato, l&#8217;intera cappella) di cui si sentiva essere custode pi\u00f9 che proprietario. La rabbia \u00e8 rivolta n<strong>ei confronti della Procura di Cosenza pi\u00f9 volte sollecitata allo sgombero della famiglia di occupanti di cui qualcuno avrebbe dovuto prendersi cura per tutelare le proprie vite e quelle altrui.<\/strong> Otto lunghi anni di esposti, sopralluoghi dell&#8217;Asp e delle forze dell&#8217;ordine che certificavano le pessime condizioni igienico sanitarie in cui versava l&#8217;appartamento. Una strage annunciata per l&#8217;inerzia del sistema welfare cosentino e la superficialit\u00e0 di una Procura che non ha inteso intervenire. Alla mezzanotte di ieri, ad otto ore di distanza dall&#8217;esplosione dell&#8217;incendio, le fiamme non erano ancora state del tutto domate. Stamattina si proceder\u00e0 ad estrarre i corpi dall&#8217;appartamento ed eseguire alla loro identificazione, mentre la Procura ha aperto un&#8217;inchiesta sulla vicenda. Il centro storico di Cosenza intanto \u00e8 gi\u00e0 in lutto, mentre i residenti continuano a segnalare casi simili. Implorano l&#8217;intervento delle autorit\u00e0 affinch\u00e9 non si debba assistere ad un nuovo dramma.<\/p>\n<p>&nbsp;<\/p>\n<p>[huge_it_gallery id=&#8221;267&#8243;]<\/p>\n<p><iframe loading=\"lazy\" title=\"salme cs vecchia\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/sFx8dlL_-xQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3167\" target=\"_blank\" rel=\"noopener\">\u00a0<span class=\"current\">Appartamento in fiamme a Cosenza Vecchia, tre vittime\u00a0(VIDEO E FOTO)<\/span><\/a><\/span><\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\">CLICCA IN BASSO PER<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3168\" target=\"_blank\" rel=\"noopener\">Conoscere la Residenza Ruggi D&#8217;Aragona<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tre persone morte carbonizzate e\u00a0mezzo millennio di storia cosentina in fumo. La famiglia Bilotti da otto anni chiedeva alla Procura di Cosenza di intervenire.<\/p>\n","protected":false},"author":22,"featured_media":82619,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-82618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82618"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82619"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}