{"id":82658,"date":"2017-08-20T11:59:01","date_gmt":"2017-08-20T09:59:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scooter-contro-albero-un-morto-a-santa-maria-del-cedro\/"},"modified":"2023-01-16T19:35:45","modified_gmt":"2023-01-16T18:35:45","slug":"171585-scooter-contro-albero-un-morto-a-santa-maria-del-cedro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/171585-scooter-contro-albero-un-morto-a-santa-maria-del-cedro\/","title":{"rendered":"Scooter contro albero, uomo muore a Santa Maria del Cedro"},"content":{"rendered":"<h4>Il colpo non ha dato scampo al cinquantaduenne.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SANTA MARIA DEL CEDRO (CS) &#8211; Incidente fatale stamattina a Santa Maria del Cedro, in provincia di Cosenza. All&#8217;alba in via degli Ulivi, nota per i numerosi sinistri che si verificano periodicamente, Pino Lauria ha perso la vita.<strong> Il cinquantaduenne \u00e8 morto schiantandosi contro un albero.<\/strong> Una morte violenta per il cinquantaduenne che viaggiava in scooter poco prima delle 5:00 sulla strada che collega Marcellina alla statale 18. Si tratta della strada che porta al centro storico di Santa Maria del Cedro dove vive con la moglie che in quel momento lo stava seguendo. A bordo di un&#8217;altra auto, la donna ha assistito alla scena inerme. Il colpo incassato dopo essere finito a bordo strada \u00e8 stato fatale. Lauria dopo aver perso il controllo del motorino, cadendo, \u00e8 morto sul colpo. I sanitari del 118, intervenuti sul posto, non hanno potuto fare altro che constatare l&#8217;avvenuto decesso.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">In foto uno scorcio di via degli Ulivi<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il colpo non ha dato scampo al cinquantaduenne.<\/p>\n","protected":false},"author":22,"featured_media":82659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-82658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82658"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82659"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}