{"id":82714,"date":"2017-08-23T08:45:27","date_gmt":"2017-08-23T06:45:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sisma-ad-ischia-tansi-calabria-oltre-140-mila-case-abusive-rischio-crollo\/"},"modified":"2023-01-16T19:35:49","modified_gmt":"2023-01-16T18:35:49","slug":"171896-sisma-ad-ischia-tansi-calabria-oltre-140-mila-case-abusive-rischio-crollo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/171896-sisma-ad-ischia-tansi-calabria-oltre-140-mila-case-abusive-rischio-crollo\/","title":{"rendered":"Sisma ad Ischia, Tansi: &#8220;In Calabria oltre 140 mila case abusive e a rischio crollo&#8221; (AUDIO)"},"content":{"rendered":"<h4>&#8220;Un terremoto insignificante (magnitudo 4) che in Giappone ed Usa non farebbe neanche notizia, ad Ischia ha fatto sbriciolare interi palazzi che hanno ucciso vittime innocenti. Sono crollati gli edifici abusivi, realizzati senza progetto e con cemento depotenziato, mentre quelli realizzati a norma di legge sono rimasti perfettamente in piedi e immacolati&#8221;.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Ad affermarlo \u00e8 Carlo Tansi, responsabile della Protezione civile della Regione Calabria, evidenziando che &#8220;il terremoto non uccide ma sono le case costruite male che crollano e uccidono&#8221;. &#8220;La Calabria &#8211; prosegue &#8211; \u00e8 una regione tra le pi\u00f9 esposte al mondo al rischio sismico, dove le faglie sono in grado di generare terremoti di magnitudo molto molto pi\u00f9 elevata e che hanno fatto molte molte pi\u00f9 vittime del terremoto di Ischia: 7.2 terremoto del 1908 (120.000 morti), 7.1 terremoto del 1783 (35.000 morti), 7.0 terremoto del 1638 (10.000 morti), giusto per citare i sismi pi\u00f9 violenti tra i tanti che hanno martoriato la Calabria. Ebbene s\u00ec, proprio in Calabria queste catastrofi non ci hanno insegnato un bel niente: il numero di case abusive censite ufficialmente dal catasto sono 142.000. E anche tutte queste case abusive, dove abitano centinaia di migliaia di calabresi, cos\u00ec come \u00e8 accaduto ad Ischia, se vicine all&#8217;epicentro potrebbero sbriciolarsi e uccidere. Chi ha realizzato case abusive in Calabria deve seriamente preoccuparsi, deve avere paura anzi il terrore del terremoto. Chi invece ha costruito le case a norma di legge, dopo gli anni 80, pu\u00f2 dormire sonni tranquilli, anzi tranquillissimi.<\/p>\n<p>Le parole di <strong>Tansi<\/strong> sono state ribadite anche questa mattina ai microfoni di <strong>Rlb Radioattiva<\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/h4>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/08\/tansi-su-palazzi-e-sisma.mp3&#8243;]<\/p>\n<p>&nbsp;<\/p>\n<p>Non facciamo scongiuri alla Cetto Laqualunque, ma ragioniamo e cambiamo cultura. Possiamo aggirare le leggi degli uomini ma non quelle della natura che, anche con i terremoti, non fa sconti a nessuno e prima o poi, inesorabilmente, si riprende tutto ci\u00f2 che le appartiene, case comprese&#8221;. &#8220;Per abbattere drasticamente il rischio sismico &#8211; afferma Tansi &#8211; l&#8217;unica via percorribile, abbandonando la nefasta cultura del fatalismo, \u00e8 la prevenzione. Questa si pu\u00f2 attuare attraverso due vie: approvare una legge che imponga di abbattere le case abusive; in mancanza del libretto del fabbricato, sensibilizzare l&#8217;opinione pubblica a verificare autonomamente la qualit\u00e0 degli edifici realizzati prima degli anni 80, avvalendosi di tecnici qualificati (ingegneri, architetti e geologi) e provvedere, nel caso fosse necessario, alla loro messa in sicurezza. Pu\u00f2 dormire tranquillamente su sette cuscini infine chi abita in edifici realizzati a norma di legge dopo gli anni 80&#8221;.<\/p>\n<p>&#8220;Ho precisato &#8216;dopo gli anni 80&#8217; &#8211; afferma Tansi &#8211; perch\u00e9 all&#8217;abusivismo si aggiungono i centri storici e gli edifici realizzati soprattutto durante il boom edilizio degli 60\/70, epoca non esistevano le cosiddette &#8216;leggi sismiche&#8217;. Queste leggi nazionali, che pongono vincoli sugli edifici per renderli pi\u00f9 resistenti ai terremoti, sono diventate sempre pi\u00f9 rigide e restrittive a partire dai terremoti del 1976 (Friuli) e del 1980 (Irpinia). Per gli edifici degli anni 60\/70 e per i centri storici \u00e8 ormai ineludibile una legge che renda obbligatorio il cosiddetto &#8216;Libretto del fabbricato&#8217;, che impone l&#8217;obbligo di verificare la vulnerabilit\u00e0 sismica di tutti gli edifici, pubblici e privati, con studi di tipo ingegneristico (per verificare la qualit\u00e0 delle strutture) e geologico (per verificare la propensione dei terreni su cui sorgono gli edifici ad amplificare gli effetti dei terremoti)&#8221;.<\/p>\n<p>&#8220;Il libretto del fabbricato &#8211; prosegue &#8211; \u00e8 un po&#8217; come il libretto di circolazione per un&#8217;auto che necessita di periodiche revisioni; ci preoccupiamo e spendiamo soldi per la revisione della nostra auto, perch\u00e9 non dovremmo fare altrettanto per &#8216;revisionare&#8217; periodicamente le case in cui viviamo, fattore da cui dipende la nostra vita e quella dei nostri figli in caso di terremoto? Questa &#8216;revisione&#8217; &#8211; oltre a fornire elementi tecnici per apporre i necessari correttivi strutturali agli edifici e renderli adeguati a resistere ai terremoti &#8211; consentirebbe di classificare ogni edificio in base alla vulnerabilit\u00e0 sismica, con criteri simili alla classificazione energetica: permetterebbe cos\u00ec in sostanza di apporre sul portone di certi edifici una sorta di &#8216;bollino rosso&#8217; per indicarne l&#8217;alta vulnerabilit\u00e0 e quindi la propensione a crollare in caso di terremoto. Perch\u00e9 a mio avviso non \u00e8 mai decollata la legge che rende obbligatorio il libretto del fabbricato che salta alla ribalta ad ogni terremoto ma che poi torna &#8216;stranamente&#8217; nel dimenticatoio? Perch\u00e9 tocca interessi di potenti lobby in quanto innescherebbe un crollo del mercato immobiliare: chi comprerebbe un appartamento, anche in pieno centro, in un palazzo con il bollino rosso a rischio-sbriciolamento in caso di terremoto?&#8221;. \u201cAllo stato attuale &#8211; conclude Tansi &#8211; la scienza non consente di prevedere il momento esatto in cui si verificher\u00e0 un terremoto. La scienza sa per\u00f2 dove sono collocate le faglie e, quindi, dove colpir\u00e0 il terremoto che, di certo prima o poi, si verificher\u00e0 in ben note zone d&#8217;Italia, tra cui la Calabria&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Un terremoto insignificante (magnitudo 4) che in Giappone ed Usa non farebbe neanche notizia, ad Ischia ha fatto sbriciolare interi palazzi che hanno ucciso vittime innocenti. Sono crollati gli edifici abusivi, realizzati senza progetto e con cemento depotenziato, mentre quelli realizzati a norma di legge sono rimasti perfettamente in piedi e immacolati&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":82715,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-82714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82714"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82715"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}