{"id":82879,"date":"2017-08-28T12:55:54","date_gmt":"2017-08-28T10:55:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/notte-da-far-west-spara-tra-la-gente-in-piazza-e-poi-scappa-via\/"},"modified":"2023-01-16T19:36:00","modified_gmt":"2023-01-16T18:36:00","slug":"172870-notte-da-far-west-spara-tra-la-gente-in-piazza-e-poi-scappa-via","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/172870-notte-da-far-west-spara-tra-la-gente-in-piazza-e-poi-scappa-via\/","title":{"rendered":"Notte da far west, spara tra la gente in piazza e poi scappa via"},"content":{"rendered":"<h4>Forze dell&#8217;ordine a caccia dell&#8217;uomo, ancora ignoto, che ha seminato il panico in un&#8217;affollata zona balneare.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Grande lo spavento per le famiglie e i turisti che ieri sera affollavano piazza De Nava a Reggio Calabria. Gli agenti della Polizia di Stato sono intervenuti nel corso dei controlli concentrati nella zona dei lidi balneari. Si tratta di luoghi interessati da <strong>una notevole presenza di cittadini dove stanotte al centro della piazza \u00e8 stata\u00a0segnalata l\u2019esplosione di alcuni colpi di arma da fuoco<\/strong>. Il tempestivo intervento delle volanti ha consentito di portare alla normalit\u00e0 la situazione, rassicurando le persone presenti ed evitando che il panico tra la gente potesse provocare gravi conseguenze.<\/p>\n<p>&nbsp;<\/p>\n<p>Secondo una prima ricostruzione dei fatti, un soggetto al momento ignoto, a bordo di un\u2019autovettura, avrebbe esploso due colpi di arma da fuoco in aria poco prima dell\u2019arrivo delle Volanti. Il personale del Gabinetto Regionale della Polizia Scientifica di Reggio Calabria ha rinvenuto sul posto due bossoli. Sono in corso le indagini da parte degli investigatori della Polizia di Stato finalizzate ad<strong> identificare e rintracciare il responsabile del gesto che tanta preoccupazione ha destato tra residenti e turisti<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forze dell&#8217;ordine a caccia dell&#8217;uomo, ancora ignoto, che ha seminato il panico in un&#8217;affollata zona balneare.<\/p>\n","protected":false},"author":22,"featured_media":82880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-82879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82879"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82880"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}