{"id":82936,"date":"2017-08-30T08:06:54","date_gmt":"2017-08-30T06:06:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cetraro-due-rilevanti-iniziative-sulla-disabilita\/"},"modified":"2023-01-16T19:36:04","modified_gmt":"2023-01-16T18:36:04","slug":"173118-cetraro-due-rilevanti-iniziative-sulla-disabilita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/173118-cetraro-due-rilevanti-iniziative-sulla-disabilita\/","title":{"rendered":"Cetraro, due rilevanti iniziative sulla disabilit\u00e0"},"content":{"rendered":"<h4>Inaugurato il Sollevatore per Disabili presso il porto della cittadina tirrenica. Si \u00e8 tenuto anche il convegno \u201cIl valore sociale della disabilit\u00e0, una scommessa possibile!\u201d.<\/h4>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>CETRARO (CS) &#8211; \u201cIl bello della politica\u201d. Cos\u00ec \u00e8 stata definita la giornata di ieri dal consigliere regionale <strong>Giuseppe Aieta<\/strong>. Una giornata che l\u2019ha visto impegnato a <strong>Cetraro<\/strong>, dove si sono tenute due importanti iniziative dedicate al sociale.<\/p>\n<p>La prima ha visto l\u2019inaugurazione di un <strong>sollevatore per disabili<\/strong> istallato sul porto della cittadina tirrenica: uno strumento che consentir\u00e0 anche ai disabili di godere del diritto alla nautica e al mare. \u00abSe dovessi raccontare ad un giovane curioso di sapere <strong>cosa c&#8217;\u00e8 di bello nella politica oggi<\/strong>, racconterei la giornata vissuta ieri \u2013 ha scritto Aieta \u2013. Una giornata sobria, come d&#8217;altra parte siamo abituati a fare, senza ostentare i segni del potere ma solo il potere dei segni attraverso risultati concreti che possono regalare sorrisi e felicit\u00e0. Una piccola cosa che aiuta molte persone in difficolt\u00e0 che da oggi possono godere della bellezza del mare. \u00c8 il caso del <strong>Sollevatore per Disabili<\/strong> che abbiamo inaugurato e che sar\u00e0 gestito dalla <strong>Lega Navale nel porto di Cetraro<\/strong> in attesa di inaugurare anche le postazioni nei porti di Roccella, Cariati e Badolato dove il servizio innalzer\u00e0 il grado di civilt\u00e0 della Calabria fino ad oggi sprovvista degli ausili per disabili\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-173119 size-large aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/08\/sollevatore-per-disabili-533x400.jpg\" alt=\"sollevatore per disabili\" width=\"533\" height=\"400\" title=\"\"><\/p>\n<p>La seconda iniziativa che ha visto la partecipazione del Consigliere regionale e dell\u2019assessore alle politiche sociale della Regione <strong>Federica Roccisano<\/strong>, \u00e8 l\u2019incontro che si \u00e8 tenuto, sempre a <strong>Cetraro<\/strong>, in localit\u00e0 san Biagio \u2013 organizzato dal Centro Diurno Di Sole e D\u2019Azzurro \u2013, dal titolo \u201c<em>Il valore sociale della disabilit\u00e0, una scommessa possibile!<\/em>\u201d. Un incontro al quale hanno partecipato anche le atlete paralimpiche <strong>Giusy Versace<\/strong> e <strong>Roberta Cogliandro<\/strong>.<\/p>\n<p>\u00abMolti cittadini presenti, un Centro Diurno ben tenuto con bellissime opere realizzate dai ragazzi che lo frequentano, una bella atmosfera\u00bb racconta Aieta. \u00abE poi gli interventi di <strong>Giusy<\/strong> e <strong>Roberta<\/strong>, a tratti commoventi, che hanno incitato noi tutti a dare una spallata alla rassegnazione ritrovando entusiasmo proprio aiutando chi \u00e8 in difficolt\u00e0\u00bb.<\/p>\n<p>\u00abIntensi anche i saluti di <strong>Angelo Aita<\/strong>, sindaco di Cetraro, e di <strong>Vincenzo Tamburi<\/strong>, ottimo Sindaco di San Basile e garbato consigliere provinciale, accompagnato dal suo collega <strong>Franco Pascarelli<\/strong>, uomo serio delle istituzioni. Ed \u00e8 stato bello notare la presenza di molti assessori comunali e consiglieri rappresentati dal consigliere delegato alle politiche sociali, <strong>Samuele Losardo<\/strong>, che tanta parte ha avuto nell&#8217;allestimento del Sollevatore\u00bb.<\/p>\n<p>\u00abInsomma <strong>una gran bella giornata<\/strong> conclusa dalle parole mai ovvie e sempre cariche di competenza, testa e cuore, di <strong>Federica Roccisano<\/strong>, assessore alle politiche sociali della Regione, che ha voluto fortemente dotare i porti calabresi di un servizio di civilt\u00e0\u00bb.<br \/>\n\u00abEcco \u2013 conclude il consigliere \u2013, se un giovane mi chiedesse di raccontargli <strong>il bello che pure c&#8217;\u00e8 in politica<\/strong>, racconterei la straordinaria giornata vissuta ieri e condita da parole che si trasformano in fatti e mai in chiacchiere\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugurato il Sollevatore per Disabili presso il porto della cittadina tirrenica. Si \u00e8 tenuto anche il convegno \u201cIl valore sociale della disabilit\u00e0, una scommessa possibile!\u201d. &nbsp;<\/p>\n","protected":false},"author":33,"featured_media":82937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-82936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=82936"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/82936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/82937"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=82936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=82936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=82936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}