{"id":83009,"date":"2017-08-31T17:18:00","date_gmt":"2017-08-31T15:18:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendi-siccita-calabria-modificato-calendario-venatorio\/"},"modified":"2023-01-16T19:36:09","modified_gmt":"2023-01-16T18:36:09","slug":"173363-incendi-siccita-calabria-modificato-calendario-venatorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/173363-incendi-siccita-calabria-modificato-calendario-venatorio\/","title":{"rendered":"Incendi e siccit\u00e0 in Calabria, modificato il calendario venatorio"},"content":{"rendered":"<h4>I cacciatori dovranno rispettare le nuove disposizioni deliberate dalla Regione Calabria.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO \u00a0&#8211; La Giunta Regionale, in data 30 agosto 2017, ha deliberato la modifica del calendario venatorio 2017\/2018 per la situazione meteoclimatica ed idrologica verificatasi sul territorio regionale a causa della siccit\u00e0 e degli incendi che hanno interessato in questa stagione estiva larghe aree della Calabria. La limitazione dell\u2019attivit\u00e0 venatoria riguarder\u00e0 le <strong>giornate di pre-apertura del 2, 3 e 10 Settembre 2017, durante le quali l\u2019orario di caccia sar\u00e0 ridotto da un\u2019ora prima del sorgere del sole fino alle 13,00.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3215\" target=\"_blank\" rel=\"noopener\">\u00a0<span class=\"current\" style=\"color: #0000ff;\">Incendi e siccit\u00e0 distruggono gli habitat della fauna calabrese, chiesta sospensione caccia<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>I cacciatori dovranno rispettare le nuove disposizioni deliberate dalla Regione Calabria.<\/p>\n","protected":false},"author":22,"featured_media":83010,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-83009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=83009"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/83010"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=83009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=83009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=83009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}