{"id":83013,"date":"2017-09-01T06:42:21","date_gmt":"2017-09-01T04:42:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/chi-ha-detto-che-lacqua-a-cosenza-non-ce\/"},"modified":"2023-01-16T19:36:09","modified_gmt":"2023-01-16T18:36:09","slug":"173380-chi-ha-detto-che-lacqua-a-cosenza-non-ce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/173380-chi-ha-detto-che-lacqua-a-cosenza-non-ce\/","title":{"rendered":"Chi ha detto che l&#8217;acqua a Cosenza non c&#8217;\u00e8?"},"content":{"rendered":"<h4><strong>Mentono! Ce n&#8217;\u00e8 cos\u00ec tanta che scorre liberamente. Per la strada.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 Stagione torrida, questa del 2017. Caldo, afa soffocante. E niente piogge. Una catastrofe, se ci mettiamo anche gli incendi. Niente pioggia vuol dire anche meno acqua nei rubinetti, perch\u00e8 le sorgenti soffrono. Si essiccano. Gli invasi si impoveriscono. <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-173378 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/acqua-fontane-cosenza-05.jpg\" alt=\"\" width=\"208\" height=\"289\" title=\"\"><\/p>\n<p>Gli acquedotti cominciano a singhiozzare. E gli utenti piangono. <strong>Perch\u00e8 l&#8217;acqua \u00e8 un bene primario. L&#8217;acqua \u00e8 un bene pubblico.<\/strong> Che non vuol dire che non \u00e8 di nessuno, perch\u00e8 \u00e8 pubblico. Vuol dire che \u00e8 di tutti! E tutti dobbiamo averne, di acqua. E dobbiamo, o meglio dovremmo, difenderla.<\/p>\n<p>Ma capita che te ne vai a spasso, in un giorno qualunque d&#8217;estate, la calda estate, su viale parco. <strong>E capita che trovi le fontanelle, pubbliche, che erogano acqua senza sosta.<\/strong> Ma come, ti domandi, con questa penuria di acqua le fontane non vengono chiuse? Qualcuno avr\u00e0 lasciato il rubinetto aperto, &#8216;sti scellerati di cosentini!&#8230; E allora ti impegni, pure, a tentare di chiuderlo, il rubinetto. Macch\u00e8. E&#8217; incastrato. Non si sblocca. E allora ti chiedi se bisogna fare una raccolta fondi per comprare un po&#8217; di rubinetti nuovi, che costeranno 3 euro l&#8217;uno, non di pi\u00f9, ed evitare questo stillicidio continuo di prezioso liquido. <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-173376 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/acqua-fontane-cosenza-03.jpg\" alt=\"\" width=\"454\" height=\"255\" title=\"\"><\/p>\n<p>Provi a fare un calcolo: da uno di questi rubinetti usciranno forse 20 litri d&#8217;acqua al minuto&#8230; per un&#8217;ora sono 1200&#8230; in un giorno sono 28800&#8230; cio\u00e8 pi\u00f9 di 28 metri cubi&#8230; e in un mese&#8230; continuate voi&#8230; accidenti&#8230; molti, tanti, troppi!!! E questo solo per una fontanella! Che te ne accorgi quando sei sotto la doccia e ti manca l&#8217;acqua proprio quando sei insaponato, cosa vuol dire avere anche solo 10 litri d&#8217;acqua in pi\u00f9 nell&#8217;autoclave (ormai indispensabile in ogni casa&#8230;)<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-173377\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/acqua-fontane-cosenza-04-271x280.jpg\" alt=\"\" width=\"271\" height=\"280\" title=\"\"><strong>E che dire degli innaffiatori automatici che curano il verde delle aiuole?<\/strong> Doverosi, per carit\u00e0. Che noi al verde ci teniamo. Ma, in un periodo di siccit\u00e0, \u00e8 proprio necessario che funzionino tutti i giorni, per ore? Che poi vedi l&#8217;acqua che scola per strada e ti chiedi se non gliene stiamo dando troppo, al praticello. Che poi, magari, gli fa anche male. E che dire del posizionamento degli spruzzatori? Qualcuno direbbe che, se non fossero montati proprio a \u201cpene di canide\u201d, magari l&#8217;acqua andrebbe nella giusta direzione e non, invece, sul parabrezza delle auto che passano. Vero \u00e8 che, a qualcuno, questo fa anche piacere: ti lavano i vetri senza neanche fermarti due minuti all&#8217;area di servizio! Una vera comodit\u00e0! Bisogna ricordarsi, per\u00f2, di chiudere i finestrini&#8230;<\/p>\n<p><strong>Insomma, risparmiare l&#8217;acqua si puo&#8217;.<\/strong> Cominciando da quella \u201cpubblica\u201d. Ma dobbiamo volerlo tutti. Davvero. Ma tanto, ormai, stanno arrivando le piogge&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-173374 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/acqua-fontane-cosenza-01.jpg\" alt=\"\" width=\"778\" height=\"366\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentono! Ce n&#8217;\u00e8 cos\u00ec tanta che scorre liberamente. Per la strada.<\/p>\n","protected":false},"author":22,"featured_media":83014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-83013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=83013"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/83014"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=83013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=83013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=83013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}