{"id":83048,"date":"2017-09-01T18:49:56","date_gmt":"2017-09-01T16:49:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/impianti-lorica-fermi-per-colpa-della-magistratura\/"},"modified":"2023-01-16T19:36:11","modified_gmt":"2023-01-16T18:36:11","slug":"173557-impianti-lorica-fermi-per-colpa-della-magistratura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/173557-impianti-lorica-fermi-per-colpa-della-magistratura\/","title":{"rendered":"Impianti Lorica fermi per &#8216;colpa&#8217; della magistratura, si rischia di perdere i finanziamenti"},"content":{"rendered":"<h4>Dopo la morte di un operaio e l&#8217;arresto dell&#8217;amministratore del gruppo Barbieri, accusato di collusione con il clan Muto, si chiede di intervenire per non paralizzare l&#8217;economia silana.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO \u00a0&#8211; &#8220;Puntare sullo sviluppo turistico ed economico di Lorica e&#8217; esigenza fondamentale per la nostra regione&#8221;. E&#8217; quanto afferma il consigliere regionale Mario Magno che in un&#8217;interrogazione rivolta al Presidente della Giunta regionale Mario Oliverio, raccogliendo l&#8217;appello di imprenditori e cittadini del centro silano, chiede al governatore &#8220;<strong>quali azioni intenda intraprendere per non perdere il cospicuo finanziamento di oltre 15 milioni di euro,<\/strong> ottenuto con finanziamenti della comunita&#8217; europea e finalizzato alla realizzazione degli impianti sciistici di Lorica. Quattro anni fa &#8211; aggiunge &#8211; gli impianti sciistici presenti nel centro silano, di proprieta&#8217; della Regione Calabria e gestiti dall&#8217;A.R.S.S.A., sono stati chiusi perche&#8217;, ormai, divenuti obsoleti e, quindi, inutilizzabili.<\/p>\n<p>&nbsp;<\/p>\n<p>La precedente giunta regionale aveva previsto il rifacimento degli impianti sciistici attraverso il finanziamento effettuato con il PISL &#8216;Hamata Sila&#8217;, ma lo scorso anno <strong>quando sembrava si stesse arrivando al momento dell&#8217;inaugurazione del complesso, note vicende giudiziarie<\/strong>, che hanno coinvolto l&#8217;amministratore delegato della societa&#8217; vincitrice della gara d&#8217;appalto, hanno determinato una nuova fase di stallo per la realizzazione dell&#8217;infrastruttura. Anche i lavoratori coinvolti nel progetto lamentano a tutt&#8217;oggi il mancato pagamento di diverse mensilita&#8217; arretrate&#8221;. &#8220;Lorica &#8211; osserva Magno &#8211; e&#8217; dotata di un suggestivo e incantevole impatto ambientale-paesaggistico che affascina coloro i quali si recano a visitarla. Non puo&#8217; essere abbandonata al suo destino.<\/p>\n<p>&nbsp;<\/p>\n<p>Il completamento dei lavori per la realizzazione dei nuovi impianti sciistici e del centro turistico polifunzionale denominati &#8220;<strong>Lorica Ski Area&#8221; rappresentano esigenza non piu&#8217; rinviabile in quanto gli imprenditori, gli operatori economici e i cittadini stanno subendo un danno economico rilevante<\/strong> dalla mancata realizzazione delle importanti infrastrutture e altre conseguenze significative potrebbero verificarsi a breve determinando perdite di posti di lavoro a causa della possibile chiusura di esercizi alberghieri e commerciali&#8221;. Per queste ragioni Magno chiede ancora ad Oliverio nell&#8217;interrogazione &#8220;quali iniziative intenda adottare per tutelare le attivita&#8217; imprenditoriali e rilanciare l&#8217;occupazione e lo sviluppo turistico ed economico di una tra le piu&#8217; note localita&#8217; calabresi per le sue straordinarie potenzialita&#8217; e bellezze paesaggistiche e naturali. La Regione Calabria &#8211; conclude Magno &#8211; intervenga immediatamente. Servono azioni concrete per realizzare quello sviluppo annunciato ma mai effettivamente prodotto da questa giunta di centrosinistra&#8221;.<\/p>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">LEGGI ANCHE<\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3223\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lorica, quasi ultimata la nuova seggiovia. A breve\u00a0inaugurazione degli impianti<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3224\" target=\"_blank\" rel=\"noopener\">\u00a0<span class=\"current\">Tragedia a Lorica: si stacca cestello dalla seggiovia e cadono nel vuoto. Morto operaio 31enne<\/span><\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2594\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Gli affari tra il gruppo Barbieri e il clan Muto. Ecco cosa dicono i &#8216;pentiti&#8217;<\/span><\/a><\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3225\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">\u00a0<span class=\"current\">\u2018Striscia la Notizia\u2019 a Lorica: per indagare sugli impianti di risalita, fermi da mesi<\/span><\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3226\" target=\"_blank\" rel=\"noopener\">Appalti Piazza Bilotti, impianti Lorica, areoporto Scalea gestiti dal clan Muto. Imprenditori in carcere<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2249\">Appalti e \u2018ndrangheta: Fermati 35 imprenditori.<\/a><\/span><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2249\">Sigilli al parcheggio di Piazza Bilotti (FOTO e VIDEO)<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2244\" target=\"_blank\" rel=\"noopener\">Operazioni \u201cCumbertazione\u201d e \u201c5 Lustri\u201d, eseguiti 33 fermi<\/a><\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2244\" target=\"_blank\" rel=\"noopener\">NOMI e AZIENDE SEQUESTRATE<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la morte di un operaio e l&#8217;arresto dell&#8217;amministratore del gruppo Barbieri, accusato di collusione con il clan Muto, si chiede di intervenire per non paralizzare l&#8217;economia silana.<\/p>\n","protected":false},"author":22,"featured_media":83049,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-83048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=83048"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/83049"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=83048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=83048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=83048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}