{"id":8315,"date":"2012-11-22T22:00:00","date_gmt":"2012-11-22T21:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8315"},"modified":"2023-01-17T13:41:32","modified_gmt":"2023-01-17T12:41:32","slug":"3562-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3562-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","title":{"rendered":"Giornata internazionale per l\u2019eliminazione della violenza contro le donne"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211; \u201c<strong>Avere coraggio di aver coraggio<\/strong>\u201d, \u00e8 questa la frase<\/p>\n<p>  <!--more-->  <\/p>\n<p>che ogni donna dovrebbe ripetersi prima di cadere in situazioni che la vedranno protagonista di violenze e oppressioni da parte di mariti, fidanzati o uomini incontrati per strada.<br \/>La violenza sulla donna \u00e8 un fenomeno sviluppato e combattuto a lungo ma, ancora oggi, vede sullo sfondo moltissime vittime rinchiuse nelle loro gabbie di paura, intrappolate in una vita che non vogliono, segnate da traumi incancellabili.<br \/>Se da un lato sono ancora tantissime le donne che soffrono e si chiudono nelle loro tragiche situazioni, dall\u2019altro lato ci sono le donne che combattono, che hanno avuto il coraggio di urlare dopo anni di silenzio e di raccontare la loro storia, liberandosi dei mostri che le hanno perseguitate, violentate, disintegrate.<br \/>Sono donne in rinascita, donne che hanno deciso di prendere in mano una vita che stavano distruggendo con la paura, con quegli amori malati che le hanno intrappolate.<br \/>E\u2019 questo che si celebra domenica,<strong> 25 Novembre<\/strong>, in tutto il Mondo: <strong>Giornata internazionale per l\u2019eliminazione della violenza contro le donne<\/strong>.<br \/>Un giorno scelto dall\u2019Assemblea Generale delle Nazioni Unite, con la risoluzione numero 54\/134 del 17 dicembre 1999: l\u2019Onu ha invitato tutti i governi, le ONG e le organizzazioni internazionali ad organizzare eventi per sensibilizzare l\u2019opinione pubblica sull\u2019argomento.<br \/>Le iniziative contro la violenza sulle donne saranno moltissime e ovunque, realizzate proprio per sollecitare chi ha ancora paura, dando voce a tutte coloro che, invece, hanno ripreso a vivere.<br \/>Ma perch\u00e9 scegliere il 25 Novembre?<br \/>L\u2019Onu ha deciso di organizzare questo evento in questa data perch\u00e9 nel 1981 alcune femministe, si incontrarono a Bogot\u00e0 (Colombia) per discutere sulla condizione femminile, ricordando l\u2019omicidio di tre sorelle che, il 25 novembre 1960, persero la vita combattendo contro il regime di Rafael Le\u00f3nidas Trujillo.<br \/>Da qui la decisione di onorare la donna e di dire NO alla violenza proprio in questa giornata.<br \/>Nel 2005 moltissime organizzazioni, Centri Antiviolenza e alcune Case delle donne decisero di organizzare svariati eventi per onorare questa giornata, che aumentano anno dopo anno.<br \/>Tutto il Mondo, da Nord a Sud, metter\u00e0 in scena iniziative importanti, organizzate da associazioni che ogni giorno raccolgono la testimonianza di donne distrutte e rinate, dignit\u00e0 perse e ricostruite, <strong>donne che ritornano ad essere donne grazie al coraggio<\/strong>.<\/p>\n<p>\u201cCHI E&#8217; NELL\u2019ERRORE COMPENSA CON LA VIOLENZA MA CiO&#8217; CHE GLI MANCA, IN VERITA&#8217;, E&#8217; LA FORZA\u201d<br \/><em>Goethe<\/em><\/p>\n<p><em>&nbsp;<\/em><\/p>\n<p><em>(Simona Gangale)<br \/><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; \u201cAvere coraggio di aver coraggio\u201d, \u00e8 questa la frase<\/p>\n","protected":false},"author":22,"featured_media":8316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-8315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8315"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8316"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}