{"id":83351,"date":"2017-09-11T04:47:01","date_gmt":"2017-09-11T02:47:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-porto-della-cocaina-un-sequestro-216-chilogrammi-stipati-un-container\/"},"modified":"2023-01-16T19:36:31","modified_gmt":"2023-01-16T18:36:31","slug":"175095-al-porto-della-cocaina-un-sequestro-216-chilogrammi-stipati-un-container","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/175095-al-porto-della-cocaina-un-sequestro-216-chilogrammi-stipati-un-container\/","title":{"rendered":"Al &#8216;porto della cocaina&#8217; un nuovo sequestro, 216 chilogrammi stipati in un container"},"content":{"rendered":"<h4>A pochi giorni dal sequestro di oltre due quintali di cocaina, continua la lotta al narcotraffico delle Fiamme gialle e dell&#8217;agenzia delle Dogane al porto di Gioia Tauro<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>GIOIA TAURO (RC) &#8211; Gli uomini della Guardia di Finanza di Reggio Calabria e dei funzionari dell\u2019Agenzia delle Dogane, hanno intercettato un nuovo ed ingente carico di cocaina. Questa volta, nascosti tra sacchi contenenti gomma in granuli, provenienti dal Sud America, sono stati rinvenuti ben <strong>10 borsoni contenenti 200 panetti di cocaina purissima, pari a 216 chili.<\/strong><\/p>\n<p>Il risultato \u00e8 frutto, ancora una volta, della sinergia delle istituzioni a presidio del porto mediante la predisposizione di piani di intervento complementari, che mirano a contenere le manifestazioni di grave pericolo per la collettivit\u00e0 conseguenti all\u2019immissione nel mercato illegale delle sostanze stupefacenti.<\/p>\n<p>Pericoli che si manifestano non solo negli effetti pi\u00f9 immediati e deleteri, quali quelli connessi all\u2019uso delle sostanze stupefacenti, ma anche in quelli, pi\u00f9 subdoli, sotterranei e forse ancor pi\u00f9 devastanti, legati al reinvestimento nell\u2019economia legale degli enormi capitali illecitamente lucrati dalle mafie che gestiscono i grandi traffici di droga.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-175097 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/finanza-cocaina-porto-gioia-tauro.jpg\" alt=\"finanza cocaina porto gioia tauro\" width=\"570\" height=\"406\" title=\"\"><\/p>\n<p>Basti infatti pensare che, mentre all\u2019origine un chilo di foglie di coca viene venduto dal coltivatore ad appena 78 centesimi di Euro, lo stesso quantitativo di cocaina, una volta definitivamente raffinato, ha un costo di 1.800 Euro per il produttore, il quale riesce a cederlo ai grossisti americani o europei tra i 25.000 ed i 30.000 Euro; considerando che la cocaina pu\u00f2 essere tagliata fino ad aumentarne il peso di ben quattro volte e che al minuto spaccio un grammo di sostanza \u00e8 ceduto per circa 100 Euro, \u00e8 facile immaginare quanto siano imponenti i volumi di denaro incamerati da chi gestisce il traffico.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/MevW1ISy62E?rel=0&amp;controls=0&amp;showinfo=0\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Soldi che, una volta reinvestiti e riciclati, sono in grado di inquinare pesantemente i circuiti legali dell\u2019economia e di alterare le condizioni di concorrenza, sottraendo opportunit\u00e0 di lavoro alle imprese che rispettano le regole Dall\u2019inizio dell\u2019anno, il sequestro di quasi 1.600 kg di cocaina, ha permesso di infliggere alla \u2018ndrangheta rilevantissime perdite economiche, sia sotto il profilo dei capitali investiti che dei mancati guadagni: la droga complessivamente sequestrata, una volta lavorata ed immessa in commercio, raggiunte le piazze di spaccio, avrebbe infatti fruttato oltre 650 milioni di euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pochi giorni dal sequestro di oltre due quintali di cocaina, continua la lotta al narcotraffico delle Fiamme gialle e dell&#8217;agenzia delle Dogane al porto di Gioia Tauro<\/p>\n","protected":false},"author":22,"featured_media":83352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-83351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=83351"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/83352"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=83351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=83351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=83351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}