{"id":83519,"date":"2017-09-14T18:04:35","date_gmt":"2017-09-14T16:04:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cocaina-tra-le-strade-de-rende-segnalati-due-giovani-cosentini\/"},"modified":"2023-01-16T19:36:43","modified_gmt":"2023-01-16T18:36:43","slug":"175801-cocaina-tra-le-strade-de-rende-segnalati-due-giovani-cosentini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/175801-cocaina-tra-le-strade-de-rende-segnalati-due-giovani-cosentini\/","title":{"rendered":"Cocaina tra le strade di Rende, segnalati due giovani cosentini"},"content":{"rendered":"<h4>Operati numerosi controlli e perquisizioni la notte scorsa dai carabinieri della compagnia di Rende.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Continuano i controlli sul territorio rendese da parte dei carabinieri del locale comando. Nelle ultime ventiquattro ore un ventisettenne cosentino \u00e8 stato denunciato in stato di libert\u00e0 per guida in stato di alterazione psico-fisica dall\u2019uso di sostanze stupefacenti. Fermato la scorsa notte mentre in auto transitava nel Comune di Rende \u00e8 stato controllato e trasferito presso l&#8217;ospedale di Cosenza dove a seguito di accertamenti sanitari \u00e8 risultato positivo all&#8217;uso di sostanze stupefacenti<strong>. Perquisita l&#8217;autovettura l&#8217;amico con il quale viaggiava \u00e8 stato trovato in possesso di un involucro in cellophane contenente un grammo di cocaina e segnalato alla Prefettura di Cosenza quale assuntore di stupefacenti.<\/strong> La patente del primo veniva immediatamente ritirata mentre lo stupefacente \u00e8 stato sottoposto a sequestro.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche un altro giovane cosentino di venti anni \u00e8 stato nella notte segnalato alla Prefettura di Cosenza quale assuntore di stupefacenti.<strong> I militari dopo averlo fermato mentre passeggiava tra le strade di Rende e perquisito lo hanno trovato in possesso di un involucro in cellophane<\/strong> contenente un grammo di cocaina immediatamente\u00a0sottoposta a sequestro. Un ventunenne cosentino invece, sempre nella serata di ieri, \u00e8 stato denunciato in stato\u00a0di libert\u00e0 per porto ingiustificato di armi od oggetti atti ad offendere. I militari infatti dopo averlo controllato e perquisito hanno rinvenuto, occultato sotto il sedile lato guida della sua vettura un pugnale della lunghezza di 25 centimetri successivamente sottoposto a sequestro.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operati numerosi controlli e perquisizioni la notte scorsa dai carabinieri della compagnia di Rende.<\/p>\n","protected":false},"author":22,"featured_media":83520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-83519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=83519"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/83519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/83520"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=83519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=83519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=83519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}