{"id":84074,"date":"2017-10-01T04:45:39","date_gmt":"2017-10-01T02:45:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-castrolibero-nasce-la-nuova-commissione-speciale-cultura\/"},"modified":"2023-01-16T19:37:20","modified_gmt":"2023-01-16T18:37:20","slug":"178012-a-castrolibero-nasce-la-nuova-commissione-speciale-cultura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/178012-a-castrolibero-nasce-la-nuova-commissione-speciale-cultura\/","title":{"rendered":"A Castrolibero nasce la nuova Commissione Speciale Cultura"},"content":{"rendered":"<h4><strong>L\u2019Amministrazione Comunale di Castrolibero ha istituito la Commissione Speciale Cultura.<\/strong><!--more--><\/h4>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em>CASTROLIBERO (CS) &#8211; L\u2019Amministrazione Comunale di Castrolibero, in sintonia con la scelta di determinare un maggiore coinvolgimento dei cittadini negli indirizzi amministrativi, ha<strong> istituito la Commissione Speciale Cultura.<\/strong> I nuovi componenti, eletti dal Consiglio Comunale, da diverso tempo operano, attraverso le loro professionalit\u00e0, in ambito culturale. Ragion per cui sapranno dare un <strong>importante contributo ad una Amministrazione che da sempre \u00e8 impegnata nella promozione di eventi che hanno assunto, nel corso degli anni, un rilievo nazionale.<\/strong> \u201cLa Cultura ha un valore educativo, oltre che ricreativo \u2013 ha dichiarato la Consigliera delegata<strong> Yleana Illuminato<\/strong> -. Essa \u00e8 uno<strong> strumento di sensibilizzazione per diffondere fra le persone una pedagogia del bello.<\/strong> Abbiamo la fortuna, come territorio, di usufruire di<strong> luoghi che possiedono un grande valore storico e artistico.<\/strong> Si tratta, grazie alle competenze individuate, di renderli ancora pi\u00f9 accoglienti e suggestivi\u201d. A far parte della Commissione sono stati designati:<strong> Angela Gatto, con l\u2019incarico di presiederla, Luigi Filice, Antonio Iaconianni, Luigi Morrone e Maria Teresa Toscano.<\/strong> Il Sindaco Giovanni Greco, nel manifestare la propria gratitudine e riconoscenza verso quanti ritengono prioritario impegnarsi per il bene della Comunit\u00e0, formula i migliori auguri in uno spirito di proficua e reciproca collaborazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione Comunale di Castrolibero ha istituito la Commissione Speciale Cultura.<\/p>\n","protected":false},"author":22,"featured_media":84075,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,564],"tags":[],"class_list":["post-84074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=84074"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/84075"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=84074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=84074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=84074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}