{"id":84330,"date":"2017-10-05T08:42:42","date_gmt":"2017-10-05T06:42:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fue-una-historia-de-amor-parte-da-cosenza-il-primo-tangoperaballet\/"},"modified":"2023-01-16T19:37:36","modified_gmt":"2023-01-16T18:37:36","slug":"179218-fue-una-historia-de-amor-parte-da-cosenza-il-primo-tangoperaballet","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/179218-fue-una-historia-de-amor-parte-da-cosenza-il-primo-tangoperaballet\/","title":{"rendered":"&#8220;Fu\u00e8, una Historia de Amor&#8221;. Parte da Cosenza il primo TangOperaBallet"},"content":{"rendered":"<h4>Una storia d\u2019amore vera, scritta musicata e diretta dal cosentino Francesco Perri, per la prima volta in Calabria.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Dopo oltre 15 anni di ricerca tanguera, parte da Cosenza una nuova produzione riservata ai pi\u00f9 bei palcoscenici italiani, con una nuova <strong>produzione teatrale realizzata con orchestra, ballerini e tangueri, dedicata al tango argentino.\u00a0<\/strong>Si tratta di un\u2019opera scritta, musicata e diretta dal <strong>maestro Francesco Perri, <\/strong>che sar\u00e0 presentata in anteprima in Calabria gi\u00e0 nella primavera del 2018, con il sostegno alla produzione di A Pois, dell\u2019Associazione Musicale Aura e di CalabriaTango. Lo spettacolo sul tango, ancora una volta<strong> Made in Calabria, ha il merito di essere il primo TangOperaBallet presente nei teatri italiani dopo la rappresentazione Maria de Buenos Aires nel lontano 1968 scritta dai maestri Piazzolla e Ferrer.\u00a0<\/strong>Titolo dell\u2019opera sar\u00e0 <strong>Fu\u00e8, una Historia de Amor (<em>E\u2019 stata una storia d\u2019amore<\/em>)<\/strong> con coreografie di <strong>Ciccio Aiello e Sofia Galanaki<\/strong>, tangueri di levatura internazionale presenti nei pi\u00f9 grandi festival del mondo, e la partecipazione del famoso <strong>corpo di ballo Calabriatango.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-179220 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/10\/I-tangueri-Ciccio-Aiello-e-Sofia-Galanaki-186x280.jpg\" alt=\"I tangueri Ciccio Aiello e Sofia Galanaki\" width=\"154\" height=\"231\" title=\"\">Intanto, mentre si allestisce <strong>lo spettacolo, il 14 e 15 ottobre<\/strong> prossimi, entrambi i giorni alle ore 10.00, presso l\u2019Hotel San Francesco di Rende, i maestri coreografi Aiello e Galanaki terranno un <strong>casting di ballo<\/strong> per selezionare coppie di tangueri per il corpo di ballo (<em>5 coppie<\/em>) e la scelta dei sei ballerini protagonisti (<em>3 coppie<\/em>). Per prenotare la partecipazione al casting \u00e8 possibile mettersi in contatto con info@calabriatango.it o telefonicamente al numero 338.4996611. <strong>L\u2019opera \u00e8 uno struggente spettacolo\/balletto tratto da una tragica storia d\u2019amore e morte accaduta nel Sud Italia agli inizi del \u2019900.\u00a0<\/strong>Il linguaggio musicale tanguero si adatta bene alla tipologia di ricostruzione della storia dove sensualit\u00e0, passione, eroismo e duelli si alterneranno con forza attraverso una struttura scenografica di sole luci pensate nella tradizione e visione del pi\u00f9 volte <strong>Premio Oscar Vittorio Storaro,<\/strong> oltre una struttura musicale multimediale e innovativa nel linguaggio di rappresentazione.<\/p>\n<div id=\"attachment_179221\" style=\"width: 383px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-179221\" class=\"size-medium wp-image-179221\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/10\/M\u00b0-Francesco-Perri-373x280.jpg\" alt=\"M\u00b0 Francesco Perri\" width=\"373\" height=\"280\" title=\"\"><p id=\"caption-attachment-179221\" class=\"wp-caption-text\">M\u00b0 Francesco Perri<\/p><\/div>\n<p>La lingua utilizzata, che mescola<strong> l\u2019italiano allo spagnolo e al dialetto calabrese, vuole quasi idealizzare il lunfardo<\/strong> (dialetto nato a <strong>Buenos Aires<\/strong> durante la seconda met\u00e0 del XIX secolo con l\u2019approdare delle immigrazioni europee, sopratutto italiana e spagnola, che si\u00a0insediarono nei quartieri pi\u00f9 poveri e di bassa classe sociale, ndr)<strong> come veicolo di emozione che trova origine nel gergo popolare.<\/strong> Donne bellissime, con musiche ferme e suadenti che si ispirano alla tradizione tanguera e alle contaminazioni popolari del Sud Italia, saranno la principale e autentica particolarit\u00e0 dell\u2019opera-tango Fu\u00e8.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una storia d\u2019amore vera, scritta musicata e diretta dal cosentino Francesco Perri, per la prima volta in Calabria.<\/p>\n","protected":false},"author":22,"featured_media":84331,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-84330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=84330"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/84331"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=84330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=84330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=84330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}