{"id":84873,"date":"2017-10-17T12:00:00","date_gmt":"2017-10-17T10:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terranova-da-sibari-protestano-22-ex-ammortizzatori-sociali-formazione-e-neanche-un-centesimo\/"},"modified":"2023-01-16T19:38:12","modified_gmt":"2023-01-16T18:38:12","slug":"181417-terranova-da-sibari-protestano-22-ex-ammortizzatori-sociali-formazione-e-neanche-un-centesimo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/181417-terranova-da-sibari-protestano-22-ex-ammortizzatori-sociali-formazione-e-neanche-un-centesimo\/","title":{"rendered":"Terranova da Sibari, protestano 22 ex ammortizzatori sociali: &#8220;formazione e neanche un centesimo&#8221;"},"content":{"rendered":"<h4>Sono sempre pi\u00f9 esasperati i 22 lavoratori ex\u00a0 percettori di ammortizzatori sociali in deroga, tirocinanti al Comune di Terranova da Sibari per la totale indifferenza da parte degli organismi regionali, circa il pagamento delle spettanze dovute e di cui ancora non hanno visto nemmeno un centesimo.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>TERRANOVA DA SIBARI (CS) &#8211; Il loro percorso formativo \u00e8 iniziato il 19 giugno scorso, e continua a passare nella pi\u00f9 totale indifferenza sia da parte dell\u2019Assessorato al lavoro della Regione Calabria che, della stessa INPS, in una sorta di gioco delle parti, in cui ognuno scarica sull&#8217;altro le proprie responsabilit\u00e0. Frustrazione, rabbia, rassegnazione, disperazione: ormai i percettori non hanno pi\u00f9 sentimenti da esprimere. Nonostante i continui solleciti e le continue richieste di ricevere ci\u00f2 che spetta loro di diritto, ad oggi il nulla totale. Si sentono presi in giro dalle parole, che rimangono solo parole, alle quali <strong>non seguono i fatti reali e concreti<\/strong>.<\/p>\n<p>La verit\u00e0 nuda e cruda \u00e8 che, pur impegnati quotidianamente per<strong> 4 ore al giorno e per 5 giorni a settimana,<\/strong> da pi\u00f9 di 4 mesi, tali soggetti, continuano ad essere esclusi da qualsiasi forma di sostentamento economico che penalizza e mortifica la loro stessa dignit\u00e0 di uomini e lavoratori.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-181418 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/10\/protesta-comune-terranova-sibari.jpg\" alt=\"protesta comune terranova sibari\" width=\"493\" height=\"259\" title=\"\">Proprio ieri il<strong> Sindaco di Terranova da Sibari, Luigi Lirangi,<\/strong> ha voluto incontrare nella Sala Comunale di Palazzo di Citt\u00e0, i lavoratori impegnati all\u2019interno dell\u2019Ente, i quali hanno manifestato e partecipato al Primo Cittadino tutto il loro disagio e disappunto nei confronti della Regione Calabria, rivendicando i loro diritti e soprattutto chiedendo in maniera forte al Primo Cittadino, di attivare tutti i canali necessari, affinch\u00e8 questa situazione incresciosa venga finalmente risolta. Lavoratori che vivono il disagio sociale per la mancanza di lavoro e rischiano soprattutto di rimanere fuori da qualsiasi forma di ammortizzatore sociale<strong>. Dal 19 giugno, quando hanno preso avvio i progetti formativi,<\/strong> per la loro prestazione i lavoratori non hanno ricevuto nulla di nulla. E la cosa grave \u00e8 che nessuna luce si intravede alla fine del tunnel.<\/p>\n<p>Nel rimpallo delle responsabilit\u00e0, infatti, di certo c\u2019\u00e8 che\u00a0il processo dei pagamenti di 800 euro mensili lordi \u00e8 in piena fase di stallo.\u00a0Una situazione che, tra l\u2019altro, fa il paio con quella delle altre migliaia di colleghi tirocinanti, sparsi per la regione. All\u2019avvio dei progetti era stata dipinta tutt\u2019altra situazione, anzi la manifestazione d\u2019interesse a cui avevano aderito i vari comuni calabresi, veniva presentata come un\u00a0accordo pilota\u00a0che avrebbe permesso di accorciare i\u00a0tempi di pagamento\u00a0delle indennit\u00e0 ai lavoratori, ex mobilit\u00e0 in deroga negli enti locali e imprese. E, invece, le solite questioni burocratiche\u00a0fra Ministero del Lavoro, Inps e Regione Calabria\u00a0ha mandato in\u00a0tilt l\u2019intero sistema.\u00a0A rendere ancora pi\u00f9 paradossale la vicenda, il particolare che\u00a0i fondi,\u00a0indirizzati a favore dei sussidi di disoccupazione,\u00a0sono da tempo gi\u00e0 a disposizione del Governo regionale, per\u00f2 chiss\u00e0 perch\u00e9 tutto resta fermo in attesa di chiss\u00e0 quale provvidenziale intervento divino.<\/p>\n<p>Il Sindaco Lirangi, coinvolto in prima persona sulla vicenda da parte dei 22 lavoratori, ha espresso la sua pi\u00f9 totale solidariet\u00e0, ribadendo al contempo il suo impegno e disponibilit\u00e0 ad affrontare la questione, anche attraverso il coinvolgimento dell\u2019intera Amministrazione Comunale, ribadendo ci\u00f2 che era gi\u00e0 stato espresso con una lettera nelle settimane scorse, inviata al Prefetto di Cosenza, al Presidente della Giunta Regionale <strong>Oliverio<\/strong>, e all\u2019Assessore al ramo <strong>Roccisano<\/strong>, affinch\u00e8 si attivassero, ciascuno per le proprie competenze e responsabilit\u00e0 nella risoluzione della vicenda. Una disponibilit\u00e0 piena ed incondizionata a farsi portavoce insieme agli altri Sindaci calabresi per promuovere una vera e propria protesta, che sensibilizzi gli organismi regionali a procedere al pagamento di quanto dovuto ai tanti lavoratori calabresi.<\/p>\n<p>&#8220;Non si pu\u00f2 chiedere a categorie sociali che gi\u00e0 vivono il dramma della mancanza del lavoro di aspettare ancora \u2013 ha affermato il Primo Cittadino di Terranova da Sibari \u2013 si faccia tutto ci\u00f2 che \u00e8 necessario e si esca una volta per tutte da questa forma di ambiguit\u00e0 che sta creando malessere sociale fra tanti lavoratori che sono sull\u2019orlo della disperazione. I lavoratori non sono pi\u00f9 disponibili a tollerare oltre questo stato di cose, spero che si intervenga al pi\u00f9 presto ma soprattutto che questo grido di allarme non rimanga ancora una volta inascoltato&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono sempre pi\u00f9 esasperati i 22 lavoratori ex\u00a0 percettori di ammortizzatori sociali in deroga, tirocinanti al Comune di Terranova da Sibari per la totale indifferenza da parte degli organismi regionali, circa il pagamento delle spettanze dovute e di cui ancora non hanno visto nemmeno un centesimo.<\/p>\n","protected":false},"author":21,"featured_media":84874,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-84873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=84873"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/84873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/84874"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=84873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=84873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=84873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}