{"id":8604,"date":"2012-11-28T12:30:01","date_gmt":"2012-11-28T11:30:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8604"},"modified":"2023-01-17T13:41:48","modified_gmt":"2023-01-17T12:41:48","slug":"3717-sisma-pollino-gabrielli-sui-luoghi-del-terremoto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3717-sisma-pollino-gabrielli-sui-luoghi-del-terremoto\/","title":{"rendered":"Sisma Pollino: Gabrielli sui luoghi del terremoto"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211; Lo Stato pensa ai terremotati. Il capo della protezione civile Franco Gabrielli, stamattina \u00e8 arrivato a Cosenza per coordinare un vertice in prefettura. Attorno al tavolo, oltre al numero uno <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>della Prociv, si sono seduti il prefetto di Cosenza Raffaele Cannizzaro, nominato dallo Stato commissario per l&#8217;emergenza, il sindaco di Mormanno, Guglielmo Armentano, nonch\u00e8 i responsabili locali e regionali della Protezione Civile.<\/strong> Al vertice hanno partecipato anche i vigili del fuoco del Comando provinciale di Cosenza, con a capo della delegazione il comandante Gino Novello. Nel corso della riunione \u00e8 stato fatto il punto sulla situazione, analizzando gli edifici a rischio, focalizzando l&#8217;attenzione sulle gravi e grandi emergenze da risolvere al pi\u00f9 presto e predisponendo un piano d&#8217;intervento strategico per il maltempo che, nelle prossime ore, punter\u00e0 decisamente sulla nostrra regione con abbondanti rovesci temporaleschi e temperature basse. <strong>Finita la valutazione operativa (tra gli invitati c&#8217;era anche il presidente della Provincia Mario Oliverio, ndr), lo stato maggiore della Prociv, poco dopo le 14, ha lasciato il palazzo della Prefettura per raggiungere Mormanno e gli altri territori del Cosentino e del Potentino, particolarmente interessati dal sisma. Nel lasciare la stanza della riunione il capo della Protezione Civile, rispondendo alle domande dei giornalisti sui finanziamenti da destinare ai territori terremotati, ha assicurato che lo Stato e il Governo, garantiranno l&#8217;elargizione di somme consistenti, destinate alle ricostruzione e alla messa in sicurezza dei territori, autentico, secondo il capo della Prociv, tallone d&#8217;Achille della nostra regione, con un elevatissimo numero di territori ad elevato rischio sismico, nonch\u00e8 idrogeologico. Un sopralluogo tecnico, effettuato con monitoraggi sia dall&#8217;alto che da terra, che permeter\u00e0 agli uomini della protezione civile e ai vigili del fuoco di stabilire l&#8217;ordine delle priorit\u00e0 da gestire per garantire non solo la salvaguardia degli edifici a rischio e l&#8217;incolumit\u00e0 pubblica ma anche per attrezzare aree d&#8217;emergenza adeguate per ospitare tutta quella fetta di popolazione che per questioni di sicurezza e di inagibilit\u00e0 strutturale non pu\u00f2 mettere piede all&#8217;interno delle abitazioni.&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Lo Stato pensa ai terremotati. Il capo della protezione civile Franco Gabrielli, stamattina \u00e8 arrivato a Cosenza per coordinare un vertice in prefettura. Attorno al tavolo, oltre al numero uno<\/p>\n","protected":false},"author":22,"featured_media":8605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-8604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8604"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8605"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}