{"id":86048,"date":"2017-11-14T14:46:19","date_gmt":"2017-11-14T13:46:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/badante-addormenta-rapina-e-chiude-in-casa-un-anziano-di-luzzi\/"},"modified":"2023-01-16T19:39:31","modified_gmt":"2023-01-16T18:39:31","slug":"186604-badante-addormenta-rapina-e-chiude-in-casa-un-anziano-di-luzzi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/186604-badante-addormenta-rapina-e-chiude-in-casa-un-anziano-di-luzzi\/","title":{"rendered":"Badante addormenta, rapina e chiude in casa un anziano di Luzzi"},"content":{"rendered":"<h4>La donna era riuscita a sottrarre al pensionato le chiavi della cassaforte da cui aveva prelevato oltre 15mila euro<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LUZZI (CS) &#8211; Aspetta che il suo assistito si addormenta e lo rapina. I\u00a0carabinieri di Luzzi\u00a0 hanno tratto in arresto, per il reato di rapina impropria una 49enne di nazionalit\u00e0 rumena residente nel popoloso comune dell&#8217;hinterland cosentino. I militari intervenuti nella nottata, su segnalazione dei familiari della vittima, hanno rintracciato e bloccato la donna. La badante poco prima di essere stata fermata pare abbia aspettato che l&#8217;anziano per il quale lavorava, un 87enne di Luzzi, si addormentasse per sottrarre le chiavi della cassaforte e asportare la somma in contanti di 15.750 euro e vari monili in oro. <strong>Prima di darsi alla fuga, la quarantanovenne avrebbe chiuso la vittima all\u2019interno della camera da letto portando con s\u00e9 le chiavi.<\/strong> La donna a seguito di perquisizione personale \u00e8 stata trovata in possesso delle chiavi di case, della cassaforte e della refurtiva, che \u00e8 stata immediatamente recuperata e restituita all\u2019anziano. L\u2019arrestata, al termine delle formalit\u00e0 di rito, \u00e8 stata trattenuta presso le camera di sicurezza della Compagnia Carabinieri di Rende, in attesa del processo per direttissima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna era riuscita a sottrarre al pensionato le chiavi della cassaforte da cui aveva prelevato oltre 15mila euro<\/p>\n","protected":false},"author":22,"featured_media":86049,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-86048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=86048"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/86049"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=86048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=86048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=86048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}