{"id":86132,"date":"2017-11-16T12:58:07","date_gmt":"2017-11-16T11:58:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/studenti-calabresi-ignorati-dalla-regione-caruso-oliverio-dimentica-il-diritto-allo-studio\/"},"modified":"2023-01-16T19:39:37","modified_gmt":"2023-01-16T18:39:37","slug":"186905-studenti-calabresi-ignorati-dalla-regione-caruso-oliverio-dimentica-il-diritto-allo-studio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/186905-studenti-calabresi-ignorati-dalla-regione-caruso-oliverio-dimentica-il-diritto-allo-studio\/","title":{"rendered":"Studenti calabresi ignorati dalla Regione, Caruso: &#8220;Oliverio dimentica il diritto allo studio&#8221;"},"content":{"rendered":"<h4><strong>Nicola Caruso (CORUC): \u201cLa Regione \u00e8 un tempio invaso dai mercanti del Partito Democratico e dei suoi sodali, personaggi in cerca solo di passerelle politiche e di consenso\u201d<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>ARCAVACATA (CS)\u00a0&#8211; &#8220;Si \u00e8 riunita nella giornata di ieri la seconda commissione della Regione Calabria, quella che si occupa, tra le altre cose, di Bilancio. Il primo punto all\u2019ordine del giorno era di quelli che sanno di patata bollente per questa governance regionale:<strong> fabbisogno finanziario per garantire il diritto allo studio.\u00a0<\/strong>Come al solito, questa maggioranza disomogenea di governo ha stupito chi fosse venuto a conoscenza degli esiti della discussione.&#8221; Questo quanto afferma<strong> Nicola Caruso<\/strong> (RDU &#8211; Rinnovamento Democratico Universitario), Senatore Accademico UNICAL e rappresentante presso il Comitato Regionale di Coordinamento delle Universit\u00e0 Calabresi. &#8220;I consiglieri &#8211; continua &#8211; Sergio Franco (Oliverio Presidente), Giuseppe Aieta (Partito Democratico) e Flora Sculco (Calabria in rete) hanno fatto a gara per strapparsi le vesti in nome del <strong>Diritto allo Studio e delle difficolt\u00e0 delle famiglie calabresi, invocando a pi\u00f9 riprese la necessit\u00e0 di tenere questo tema al riparo da logiche di strumentalizzazione politica.\u00a0<\/strong>Leggo i resoconti consiliari e resto a bocca aperta perch\u00e9 davvero non credevo che questa<strong> classe politica<\/strong> potesse rivelarsi <strong>tanto squallida e subdola.<\/strong> Mi chiedo come sia possibile che il governo regionale si accorga solo ora che ci sia questo problema, visto che da mesi denuncio su tutte le testate regionali questa piaga sociale. <strong>Per quanto tempo ancora dovremo richiedere la convocazione del CORUC?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-186907 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/11\/Nicola-Caruso-281x280.jpg\" alt=\"Nicola Caruso\" width=\"281\" height=\"280\" title=\"\">Qualcuno forse dimentica che questo \u00e8 l\u2019unico organo dove si possono prendere decisioni a lungo termine, che sono frutto di discussione e confronto, in quanto lo stesso \u00e8 istituzionalmente preposto a creare un ponte tra Universit\u00e0 e governo regionale. Fa bene allora il consigliere Fausto Orsomarso (gruppo misto) a denunciare la<strong> reiterata mancata convocazione del CORUC, organo composto da soggetti legittimati a livello istituzionale a rappresentare le istanze delle Universit\u00e0 calabresi.<\/strong> Evidentemente, <strong>Oliverio e la sua cricca hanno orecchie solo per amici, compari e compagni di partito<\/strong> e questa \u00e8 un\u2019ulteriore prova del fatto che, quello di ieri, altro non era che il solito teatrino, di cui restano solo chiacchiere, fumo e qualche selfie. O<strong>rmai la Regione Calabria, da luogo istituzionale, si \u00e8 trasformata in un tempio invaso dai mercanti del Partito Democratico e dei suoi sodali, personaggi in cerca solo di passerelle politiche e di consenso.<\/strong> Quegli stessi mercanti che parlano di evitare scontri politici su questi argomenti ma si occupano di Diritto allo Studio solo confrontandosi con compagni di partito asserviti e addomesticati, senza dare risposte concrete ma solo facendo salotto per discutere di aria fritta. Ora basta, ora <strong>gli studenti calabresi hanno necessit\u00e0 di provvedimenti seri, programmati e duraturi.<\/strong><\/p>\n<p>Che non succeda, visto l\u2019avvicinarsi di elezioni politiche, regionali e universitarie, che si offra un <strong>contentino momentaneo solo per avere un tornaconto elettorale?<\/strong> Gi\u00e0 in precedenza si \u00e8 pensato che si potesse risolvere questo problema impegnando fondi POR anzich\u00e9 aumentare il capitolato in bilancio. Per intenderci, <strong>si \u00e8 assicurato un investimento precario e a tempo determinato, anzich\u00e9 uno stabile e di lunga durata.<\/strong> I sospetti si fanno pi\u00f9 forti nel momento in cui rileviamo che l\u2019attenzione \u00e8 troppo bassa su un tema che meriterebbe, ad esempio, la stessa <strong>energicit\u00e0 con cui Oliverio promette di incatenarsi a Roma per procacciare una fetta di potere in pi\u00f9 sulla sanit\u00e0. Dobbiamo forse pensare che al Presidente della Regione interessi di pi\u00f9 il potere sulla sanit\u00e0 che i diritti degli studenti calabresi?<\/strong> Oppure pensa di essersi sbarazzato della questione con gli insufficienti investimenti sul POR, di cui, tra l\u2019altro, stentiamo ancora a vedere i risultati? A questo punto, dobbiamo pensare che lui sia l\u2019unico responsabile di questo disagio, visto che la sua maggioranza, almeno a parole, si esprime in maniera netta a favore della risoluzione di questa questione.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicola Caruso (CORUC): \u201cLa Regione \u00e8 un tempio invaso dai mercanti del Partito Democratico e dei suoi sodali, personaggi in cerca solo di passerelle politiche e di consenso\u201d<\/p>\n","protected":false},"author":21,"featured_media":86133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-86132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=86132"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/86133"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=86132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=86132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=86132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}