{"id":8624,"date":"2012-11-28T15:01:20","date_gmt":"2012-11-28T14:01:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8624"},"modified":"2023-01-17T13:41:49","modified_gmt":"2023-01-17T12:41:49","slug":"3728-sanita-lennesima-vergogna-400-precari-a-rischio-taglio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3728-sanita-lennesima-vergogna-400-precari-a-rischio-taglio\/","title":{"rendered":"Sanit\u00e0, l&#8217;ennesima vergogna: 400 precari a rischio &#8220;taglio&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211; Il sistema delle vergogne. Ancora una volta \u00e8 la sanit\u00e0 calabrese a far notizia. Ovviamente il titolo strillato \u00e8 dedicato, tanto per cambiare, alla politica dei tagli. Con la scusa di far cassa, l&#8217;Asp <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>di Cosenza, anzich\u00e8 pensare ad &#8220;azzerare&#8221; il bilancio in rosso tagliando spese inutili e riducendo o eliminando voci di spesa, troppo spesso, con nesuna ricaduta sui bisogni dell&#8217;utenza, pensa di rimettere a posto i conti, tagliando il numero dei suoi dipendenti. E non stiamo parlando di ruoli di secondo grado, ma di 400 e passa precari divisi tra fisioterapisti, logopedisti e addetti alla persona che, seppur contrattualizzati a tempo determinato, verranno tagliati, licenziati, mandati a casa.&nbsp;Sono gli angeli dell&#8217;unit\u00e0 operativa di neuropsichiatria infantile, cui fa capo il servizio di riabilitazione dell&#8217;et\u00e0 evolutiva dell&#8217;Azienda Sanitaria di Cosenza <\/strong> Il danno che crea questo taglio lo pagheranno quei tanti bambini diversamente abili di Cosenza e della sua vasta provincia che quotidianamente usufruiscono e beneficiano dell&#8217;alta professionalit\u00e0 lavorativa e del sostegno umano ed affettuoso di questi &#8220;angeli&#8221; in camice. Un danno che si estender\u00e0 anche alle famiglie di questi piccoli pazienti che da oggi, cos\u00ec come da un domani, sempre pi\u00f9 vicino, dovranno fare i salti mortali per permettere ai loro congiunti di continuare ad utilizzare questo servizio.<strong> Ma dove? in che modo? e soprattutto a quali costi? La politica, quella che finge di interessarsi alle esigenze della gente, rimane incollata alle proprie poltrone, mostrando fintamente interesse per risolvere la vicenda ma ritrovandosi poi a fare spallucce davanti alle sollecitazioni dell&#8217;utenza. Le famiglie e i bambini in questa loro battaglia, per la difesa della salute e della salvaguardia di un servizio medico di alta qualit\u00e0, non solo sole. Al loro fianco e non potrebbe essere diversamente ci sono questi 400e passa &#8220;angeli&#8221; in camice che hanno scelto di fare il loro lavoro non come forma di retribuzione ma come missione al servizio degli altri. Ci sono anche le sigle sindacali che, da tempo, hanno cercato di instaurare la politica del dialogo con l&#8217;Azienda sanitaria provinciale di Cosenza, cos\u00ec come con la stessa Regione Calabria. Il dialogo \u00e8 stato infruttuoso, soprattutto perch\u00e8 nel sistema sanitario \u00e8 andato in tilt anche l&#8217;ascolto. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il sistema delle vergogne. Ancora una volta \u00e8 la sanit\u00e0 calabrese a far notizia. Ovviamente il titolo strillato \u00e8 dedicato, tanto per cambiare, alla politica dei tagli. Con la scusa di far cassa, l&#8217;Asp<\/p>\n","protected":false},"author":22,"featured_media":8625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-8624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8624"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8625"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}