{"id":86394,"date":"2017-11-22T13:53:24","date_gmt":"2017-11-22T12:53:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-sulla-statale-18-ferita-donna\/"},"modified":"2023-01-16T19:39:55","modified_gmt":"2023-01-16T18:39:55","slug":"187975-incidente-sulla-statale-18-ferita-donna","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/187975-incidente-sulla-statale-18-ferita-donna\/","title":{"rendered":"Grave incidente sulla statale 18, ferita una donna"},"content":{"rendered":"<h4>Lo scontro tra le vetture \u00e8 avvenuto in un popoloso Comune del Tirreno cosentino<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>PRAIA A MARE (CS) &#8211; Poco prima delle 14.00, in localit\u00e0 Colcinello, a Praia a Mare si \u00e8 verificato un grave incidente. Nel sinistro sono rimaste coinvolte due persone: un imprenditore di Scalea G. M. e una donna di Praia a Mare S. M.. Quest&#8217;ultima \u00e8 stata d&#8217;urgenza trasportata dai sanitari del 118 all&#8217;Ospedale di Cosenza\u00a0dove le sono state riscontrate ferite giudicate guaribili in 30 giorni e la frattura di una vertebra, per G. M. invece la prognosi \u00e8 di 7 giorni. Lo scontro tra le due auto pare sia avvenuto all&#8217;altezza delle gallerie nei pressi degli svincoli per l&#8217;ospedale e per Tortora in direzione nord. <strong>La donna si trovava su una C1 della Citroen quando all&#8217;improvviso ha rallentato ed \u00e8 stata tamponata dalla BMW X3 sulla quale viaggiava l&#8217;imprenditore<\/strong>. Sul posto la polizia stradale di Scalea per i rilievi del caso.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo scontro tra le vetture \u00e8 avvenuto in un popoloso Comune del Tirreno cosentino<\/p>\n","protected":false},"author":22,"featured_media":86395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-86394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=86394"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/86394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/86395"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=86394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=86394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=86394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}