{"id":87501,"date":"2017-12-19T12:03:36","date_gmt":"2017-12-19T11:03:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/prosciolte-rende-e-catanzaro-ai-giallorossi-1-punto-di-penalizzazione-dalla-covisoc\/"},"modified":"2023-01-16T19:41:09","modified_gmt":"2023-01-16T18:41:09","slug":"192518-prosciolte-rende-e-catanzaro-ai-giallorossi-1-punto-di-penalizzazione-dalla-covisoc","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/192518-prosciolte-rende-e-catanzaro-ai-giallorossi-1-punto-di-penalizzazione-dalla-covisoc\/","title":{"rendered":"Prosciolte Rende e Catanzaro. Ai giallorossi 1 punto di penalizzazione dalla Covisoc"},"content":{"rendered":"<h4>Nell&#8217;inchiesta Money gate prosciolti Catanzaro e Avellino. Ai giallorossi\u00a0\u00e8 stato inflitto un punto di penalizzazione ma solo per inadempimenti amministrativi.\u00a0Prosciolti anche il\u00a0<strong>Rende<\/strong>\u00a0ed il presidente\u00a0Fabio Coscarella perch\u00e9 sul deferimento relativo alla presunta non veridicit\u00e0 delle garanzie bancarie il fatto non costituisce violazione<\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>ROMA &#8211;\u00a0Il Tribunale Federale Nazionale, presieduto da Cesare Mastrocola \u2013 Sezione Disciplinare &#8211; ha disposto il <strong>proscioglimento di tutti i deferiti nell\u2019ambito del procedimento<\/strong>\u00a0Money Gate relativo alla gara <strong>Catanzaro-Avellino<\/strong> disputata il 5 maggio 2013 ed alla presunta combine. Il Procuratore Federale aveva deferito i due club e sette tesserati delle due societ\u00e0 per aver posto in essere atti diretti ad alterare il regolare svolgimento e il conseguente risultato finale del match valevole per la penultima giornata del Campionato di Lega Pro Girone \u2018B\u2019 della stagione sportiva 2012\/13.\u00a0<strong>Al club\u00a0giallorosso \u00e8 stato\u00a0inflitto 1 punto di penalizzazione<\/strong> &#8220;per non aver provveduto, entro il termine del 26 giugno 2017, al pagamento degli emolumenti dovuti fino al mese di maggio 2017&#8221; ai propri tesserati. Inibito inoltre il legale rappresentante del club all&#8217;epoca dei fatti Ambra Cosentino (3 mesi).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-192532\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/12\/Tribunale-Federale-Nazionale.png\" alt=\"Tribunale Federale Nazionale\" width=\"597\" height=\"392\" title=\"\"><\/p>\n<h3><span style=\"color: #000000;\">Prosciolto il Rende e il Presindente Coscarella<\/span><\/h3>\n<p><strong>Prosciolti il Rende ed il legale rappresentante Fabio Coscarella<\/strong> (&#8220;perch\u00e9 il fatto non costituisce violazione&#8221;) relativamente alla vicenda legata alla segnalazione del Presidente della Lega Pro Gabriele Gravina sulla presunta non veridicit\u00e0 delle garanzie bancarie depositate dalla Societ\u00e0 Rende Calcio 1968 Srl in data 27 luglio 2017. Per il Tribunale non solo la\u00a0seconda fidejussione espone una validit\u00e0 retroattiva a far data dal 27\/07\/2017, cio\u00e8 il giorno precedente alla scadenza normativamente prescritta, ma soprattutto &#8211; scrive nella sentenza &#8211; se \u00e8 vero che vi fu un superficiale affidamento del dirigente nel primo conferimento dell\u2019incarico ai fini del reperimento della originaria fidejussione al mediatore incaricato, \u00e8 parallelamente vero che <strong>il Sig. Coscarella in epoca contestuale all&#8217;accertamento della prima fidejussione invalida, si premur\u00f2 immediatamente al fine di reperire e ottenere una nuova garanzia valida<\/strong>, onde sanare la precedente con decorrenza antecedente al prescritto termine di decadenza.\u00a0In tal senso ritiene il Tribunale che i prevenuti vadano prosciolti poich\u00e9 il deferimento riferisce parzialmente in merito alla dinamica di azione posta in essere dal Sig. Coscarella.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Q<span style=\"color: #000000;\">uesto il dispositivo e le motivazioni pubblicate dal Tribunale Federale Nazionale\u00a0<\/span><\/strong><\/h3>\n<p><!--nextpage--><\/p>\n<p>&#8220;Ritiene il Tribunale che la vicenda meriti una analisi metodologica maggiormente confacente al caso concreto, comunque in grado di porre nella giusta luce l&#8217;insieme di tutti gli episodi occorsi al Rende Calcio, in rapida successione, onde conferire alla decisione un quadro esaustivo dei profili giuridico fattuali che riguardano la posizione dei prevenuti, cos\u00ec da tener conto non soltanto di quanto trascritto nella parte dispositiva del deferimento, ma anche degli eventi pre e post rilascio della prima fidejussione oggetto della contestazione. Dai documenti resi dalla Procura Federale si evince, in punto di fatto, che il Sig. Fabio Coscarella unitamente alla domanda di ripescaggio della squadra in serie C, consegn\u00f2 in FIGC una prima fidejussione rilasciata dalla Svenska Handelsbanken, filiale di Schipol, rivelatasi successivamente priva di efficacia. <strong>Risulta altres\u00ec che in epoca coeva all&#8217;accertamento della validit\u00e0 o meno di detta garanzia, il dirigente si premur\u00f2, nel breve volgere di pochi giorni, di reperire una seconda polizza fidejussoria rilasciata da altro Ent<\/strong>e, sanando cos\u00ec la posizione di inadempienza del sodalizio sotto il profilo sostanziale, ma non nei sanciti tempi per aver oltrepassato il termine di presentazione della garanzia fissato al giorno 28\/07\/2017 (C.U. del Presidente Federale n. 10\/A del 14\/07\/2017).<\/p>\n<p>A seguito di tale comportamento la Procura Federale ha contestato al dirigente la violazione degli artt. 1, comma 1, e 8, commi 1 e 2 CGS; e alla Societ\u00e0 l&#8217;art. 4 comma 1 CGS. In linea di principio si conviene con la Procura Federale laddove esprime principi sanzionatori riferiti a violazioni di carattere temporale, il cui rispetto \u00e8 rigorosamente dovuto a cura dei tesserati; ma \u00e8 parimenti corretto constatare che l\u2019analisi dei comportamenti attuati nel caso di specie va considerata nella sua interezza, attraverso la completa esegesi dei fatti oggettivamente rinvenibili dagli atti istruttori del procedimento, a maggior ragione ove si consideri la manifesta volont\u00e0 del prevenuto di sanare subito la posizione invalida attraverso il deposito di una nuova garanzia (cio\u00e8 la seconda fidejussione) avente efficacia antecedente rispetto alla scadenza sancita dal menzionato C.U. Presidenziale: infatt<strong>i, nella specie, la seconda fidejussione espone una validit\u00e0 retroattiva a far data dal 27\/07\/2017, cio\u00e8 il giorno precedente alla scadenza normativamente prescritta<\/strong>. In tal senso ritiene il Tribunale che i prevenuti vadano prosciolti poich\u00e9 il deferimento riferisce parzialmente in merito alla dinamica di azione posta in essere dal Sig. Coscarella, focalizzando l\u2019attenzione sul solo primo episodio (fidejussione invalida e violazione del termine di presentazione), che preso singolarmente potrebbe ingenerare oggettive perplessit\u00e0 in ordine al comportamento leale e corretto del prevenuto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-192220\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/12\/rendecatania101.jpg\" alt=\"rendecatania101\" width=\"581\" height=\"276\" title=\"\"><\/p>\n<p>Ma vige agli atti un secondo rilievo, peraltro diffusamente trattato nella narrazione probatoria, nonch\u00e9 dalla difesa, sulla cui contezza esimente non viene svolta menzione alcuna nel dispositivo. <strong>Se dunque \u00e8 vero che vi fu un superficiale affidamento del dirigente nel primo conferimento dell\u2019incarico ai fini del reperimento della originaria fidejussione al mediatore incaricato, \u00e8 parallelamente vero che il Sig. Coscarella in epoca contestuale all&#8217;accertamento della prima fidejussione invalida, si premur\u00f2 immediatamente al fine di reperire e ottenere una nuova garanzia valida, onde sanare la precedente con decorrenza antecedente al prescritto termine di decadenza<\/strong>. Consegue che, nella fattispecie, merita maggiore tutela il contegno collaborativo svolto dal Sig. Coscarella inteso nel coacervo, piuttosto che l&#8217;analisi asettica e parziale degli eventi riferiti al solo primo episodio, in presenza delle innumerevoli circostanze concrete aventi natura scriminante e pacificamente evincibili dal contenuto stesso del deferimento. A ben vedere, il convincimento della Procura Federale trae spunto dal solo primo tempo di una vicenda oltremodo articolata e sofferta quale quella in esame, cio\u00e8 l&#8217;aver prodotto e utilizzato una fidejussione (la prima) priva di qualsiasi efficacia, senza aver effettuato alcun controllo preventivo sulla validit\u00e0 della stessa e senza aver avuto rapporti diretti con soggetti autorizzati a emettere la garanzia secondo le norme federali. Tuttavia tale proiezione non \u00e8 rappresentativa del comportamento attuato dal Rende Calcio, invero dipanatosi nell&#8217;occasione in due tempi concatenati tra loro.<\/p>\n<p>Traslando quindi i fatti all&#8217;interno delle norme di relazione, <strong>il convincimento colpevolista adottato dalla Procura Federale non trova coerente<\/strong> ragione poich\u00e9 focalizzato unicamente sul controllo preventivo e sulla rinvenuta originaria superficialit\u00e0, che per\u00f2 non trova conferma nei correttivi svolti successivamente (seconda fidejussione) per sanare integralmente e tempestivamente la posizione inadempiente, in onore ai presupposti di fattiva e concreta volont\u00e0 di sanare una posizione rivelatasi inefficace, per colpa esclusiva di terzi intermediari. <strong>Per tale ragione ritiene il Tribunale che il comportamento del Sig. Fabio Coscarella non sia stato dettato da scarsa lealt\u00e0, correttezza o probit\u00e0, n\u00e9 sia ascrivibile al contestato art. 8 CGS<\/strong>, ma di converso sia riconducibile alla ipotesi scriminante che opera in onore allo specifico concetto giuridico della comparazione tra tutti i comportamenti posti in essere dal prevenuto, tra i quali la volont\u00e0 di non ledere le norme del diritto hanno assunto un deciso sopravvento rispetto alla obiettiva leggerezza adottata in occasione del rilascio della prima fidejussione. P.Q.M.<\/p>\n<p><strong>Il Tribunale Federale Nazionale, Sezione Disciplinare proscioglie il Sig. Fabio Coscarella e la Societ\u00e0 Rende Calcio 1966 Srl, perch\u00e9 il fatto inteso nella sua intierezza non costituisce violazione<\/strong>.<\/p>\n<p>Il Presidente del TFN Sezione Disciplinare Dott. Cesare Mastrocola<\/p>\n<p>Il Segretario Federale Antonio Di Sebastiano<\/p>\n<p>Il Presidente Federale Carlo Tavecchio<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;inchiesta Money gate prosciolti Catanzaro e Avellino. Ai giallorossi\u00a0\u00e8 stato inflitto un punto di penalizzazione ma solo per inadempimenti amministrativi.\u00a0Prosciolti anche il\u00a0Rende\u00a0ed il presidente\u00a0Fabio Coscarella perch\u00e9 sul deferimento relativo alla presunta non veridicit\u00e0 delle garanzie bancarie il fatto non costituisce violazione<\/p>\n","protected":false},"author":24,"featured_media":87502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-87501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/87501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=87501"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/87501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/87502"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=87501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=87501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=87501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}