{"id":87836,"date":"2017-12-30T15:15:53","date_gmt":"2017-12-30T14:15:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cosenza-e-inarrestabile-battuta-anche-la-paganese-con-le-reti-di-bruccini-e-dorazio\/"},"modified":"2023-01-16T19:41:31","modified_gmt":"2023-01-16T18:41:31","slug":"193896-il-cosenza-e-inarrestabile-battuta-anche-la-paganese-con-le-reti-di-bruccini-e-dorazio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/193896-il-cosenza-e-inarrestabile-battuta-anche-la-paganese-con-le-reti-di-bruccini-e-dorazio\/","title":{"rendered":"Il Cosenza \u00e8 inarrestabile. Battuta anche la Paganese con le reti di Bruccini e D&#8217;Orazio"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong><b>Quarto sigillo consecutivo per i rossoblu che chiudono il 2017 battendo con il pi\u00f9 classico dei risultati la Paganese, al termine di un match senza storia\u00a0e deciso dalle reti in apertura di Mirko Bruccini e nel secondo tempo di D&#8217;Orazio. Cosenza che vola al 7&#8242; posto in classifica<\/b><\/strong><\/span><br \/>\n<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #000000;\">PAGANI (SA)\u00a0&#8211; E sono quattro. Il Cosenza conferma il suo stato di grazia portando a casa il quarto sigillo consecutivo di questo strepitoso dicembre, grazie al successo ottenuto contro una Paganese\u00a0inconcludente e mai in partita, <strong>battuta per 2 a 0<\/strong> con le reti firmate <strong>all&#8217;11&#8217; da Mirko Bruccini<\/strong> (per il centrocampista rossoblu 5 rete stagionale) e a met\u00e0 secondo tempo <strong>da D&#8217;Orazio<\/strong>. Successo che permette al Cosenza <strong>di salire al 7&#8242; posto in classifica <\/strong>a soli 3 punti dal quarto posto. Partita mai in discussione quella andata in scena al Marcello Torre e letteralmente <strong>dominata dal Cosenza<\/strong> che oltre alle due marcature pu\u00f2 recriminare su almeno <strong>4 nitide palle goal<\/strong> sbagliate da Tutino e compagni che vanno alla sosta invernale con il miglior rendimento di tutto il girone nell&#8217;ultimo mese e mezzo. Merito di una sqaudra che ha saputo reagire alle difficolt\u00e0 trovando la giusta quadratura grazie alla sagacia del suo tecnico Piero Braglia vero protagonista di questa irresistibile ascesa.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-194019\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/12\/Paganese-Cosenza.jpg\" alt=\"Paganese Cosenza\" width=\"590\" height=\"332\" title=\"\"><\/p>\n<p><span style=\"color: #000000;\">Tornando alla gara, il Cosenza sin dai primissimi minuti spinge sull&#8217;acceleratore con l&#8217;indiavolato Tutino creando pericoli alla porta di Gomiz che all&#8217;11 capitola. L&#8217;attaccante napoletano porta palla e serve Calamai che si beve Picone con una finta e pennella un pallone sul secondo palo dove c&#8217;\u00e8 appostato <strong>Bruccini che non ci pensa due volte e colpisce al volo il pallone<\/strong> che finisce nel sacco. La rete del vantaggio mette in discesa la gara del Cosenza che pu\u00f2 agire in contropiede, mentre in difesa<strong> Idda, Pasqualoni e Dermaku dormono sonni tranquilli<\/strong>, anche perch\u00e9 la Paganese non si rende mai pericolosa. I rossoblu invece quando attaccano fanno male e s<strong>fiorano il raddoppio creando tre nitide occasioni<\/strong> da goal con <strong>Idda che cicca il pallone da pochi passi<\/strong> e con lo scatenato <strong>Tutino che prima si vede deviato un tiro a botta<\/strong> sicura da Galli subentrato a Gomis, poi prova a superare il portiere campano con un t<strong>occo morbido ma il pallone esce sul fondo di poco<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Il secondo tempo <\/strong>\u00e8 avaro di emozioni, anche perch\u00e9 il Cosenza<strong> gestisce il vantaggio con assoluta tranquillit\u00e0<\/strong>\u00a0mentre la Paganese non ha la forza n\u00e8 gli uomini per creare pericoli a Saracco che si limita all&#8217;ordinaria amministrazione. Braglia sostituisce Mendicino con Statella per sfruttare la velocit\u00e0 nella ripartenze\u00a0e i cambi, ancora una volta, danno ragione al tecnico toscano perch\u00e9 i rossoblu<strong>\u00a0al 68&#8242; chiudono la gara con D&#8217;Orazio<\/strong> che su cross di Calamai st<strong>oppa di petto e con una precisa vol\u00e9e infila il pallone nell&#8217;angolo<\/strong>. Il tempo si chiude con un <strong>goal annullato a Scarpa<\/strong> per fuorigioco ed il <strong>tris sfiorato da Tutino<\/strong> fermato solo da un grande intervento di Galli. In pratica \u00e8 l&#8217;ultimo acuto di una gara che permette al Cosenza di chiudere alla grande il 2017 e andare alla sosta invernale consapevole che c&#8217;\u00e8 tutto un girone di ritorno per continuare a scalare posizioni di classifica.<\/span><\/p>\n<div><span style=\"color: #000000;\">\u00a0<\/span><\/div>\n<p><a href=\"https:\/\/quicosenza.it\/news\/507\" rel=\"attachment wp-att-49952\"><br \/>\n<\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38498 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Paganese_Calcio_1926_Logo.png\" alt=\"Paganese Calcio 1926 Logo\" width=\"170\" height=\"187\" title=\"\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48820 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/05\/Logo-Cosenza-Calcio.png\" width=\"147\" height=\"190\" alt=\"\" title=\"\"><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 18pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Paganese\u00a0 \u00a0 \u00a0 &#8211;\u00a0 \u00a0<\/span><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0\u00a0Cosenza\u00a0<\/span><\/span><\/span><\/strong><\/span><span style=\"color: #ff0000; font-size: 20pt;\"><a target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">0\u00a0&#8211;\u00a02<\/span><\/a><\/span><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 14pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\"><script type=\"text\/javascript\">\/\/ \nfunction blink_one() { document.getElementById('blink').style.visibility='visible'; setTimeout('blink_two()',1000); } function blink_two() { document.getElementById('blink').style.visibility='hidden'; setTimeout('blink_one()',1000); } blink_one();\n\/\/ <\/script><\/span><\/span><\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Marcatori<\/strong>: 9&#8242; Bruccini, 68&#8242; D&#8217;Orazio<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\">SECONDO\u00a0TEMPO<br \/>\n<b><b style=\"color: #000000;\"><\/b><\/b><\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\">94&#8242; &#8211;\u00a0<span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">FINALE DI GARA<\/span><\/span><\/span><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">92&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong>Sostituzione Paganese. Dentro Grillo al posto di Tascone<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n90&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Ci saranno\u00a04&#8242; minuti di recupero<\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">87&#8242; &#8211;<\/b><\/b><\/strong><\/span><\/strong>\u00a0Doppio Cambio nel Cosenza. Fuori Palmiero e Bruccini\u00a0e dentro Trovato e Loviso<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n86&#8242; &#8211; <\/b><\/b><\/strong><\/span><\/strong>Il<strong><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\">\u00a0<\/b><\/b><\/strong><\/strong>Cosenza sfiora il tris con Tutino che se ne va in velocit\u00e0 e a tu per tu con Galli prova a piazzare il pallone nell&#8217;angolo ma il portiere della Paganese si supera e dice no<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a079&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong>Ammonito Bruccini per un intervento duro su Scarpa\u00a0<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">72&#8242; &#8211;<span style=\"color: #0000ff;\">\u00a0<\/span><\/b><\/b><\/strong><\/span><\/strong>Sostituzione Paganese. Se ne va Talamo, al suo posto Regolanti<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">71&#8242; &#8211;<\/b><\/b><\/strong><\/span><\/strong> C<span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">ambio nel Cosenza. Fuori Pasqualoni e dentro Pascali<\/span><\/span><\/span><\/span><\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49956\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Goal2.gif\" alt=\"Goal2\" width=\"136\" height=\"68\" title=\"\">68&#8242; &#8211;<span style=\"color: #ff0000;\"><span style=\"color: #ff0000; font-weight: bold;\">\u00a0GOAL\u00a0COSENZA CON\u00a0D&#8217;ORAZIO. <span style=\"color: #000000;\">Azione insistita del Cosenza conclusa con un cross preciso di\u00a0Calamai\u00a0che pesca D&#8217;Orazio\u00a0dimenticato in area. il terzino del Cosenza ha tutto il tempo\u00a0per stoppare il pallone di petto e con\u00a0un sinistro\u00a0al volo spedirlo nell&#8217;angolo alto dove Galli non pu\u00f2 nulla<\/span><\/span><\/span><br \/>\n65&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Succede davvero poco in questo secondo tempo. Paganese confusionaria e mai pericolosa, Cosenza che si limita a controllare provando qualche ripartenza con Tutino e Statella<\/span><\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a064&#8242; &#8211;<span style=\"color: #000000;\">\u00a0<\/span><\/b><\/b><\/strong><\/span><\/strong>Palmiero sgambetta ingenuamente Meroni a centrocampo e si becca il giallo<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a060&#8242; &#8211; <\/b><\/b><\/strong><\/span><\/strong>Piana abbatte Statella che si stava involando verso la porta di Galli. Giallo inevitabile per il difensore centrale della Paganese<strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a055&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Calcione di\u00a0Bensaja a Palmiero. Cartellino giallo per il centrocampista della Paganese<\/span><\/span><\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">52&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Primo cambio nel Cosenza e Braglia decide di togliere dal campo Mendicino. Al suo posto Statella. Rossoblu che di fatto giocheranno senza una prima punta<\/span><\/span><\/span><\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n49&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Punizione da posizione interessante per la Paganese. Batte Scarpa a giro, pallone nelle braccia di Saracco<\/span><\/span><\/span><strong><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><b><b style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">45&#8242; &#8211;\u00a0<\/b><\/b><\/strong><\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Riparte il match e c&#8217;\u00e8 un&#8217;altro cambio nei padroni di casa. Fuori Picone, che nel primo tempo a sinistra non ne ha azzeccata una, dentro Carini<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\"><br \/>\nPRIMO\u00a0TEMPO<br \/>\n<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n47&#8242; &#8211;\u00a0FINALE DI PRIMO TEMPO<br \/>\n45&#8242; &#8211; <\/span><\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Ci saranno due minuti di recupero<\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n44&#8242; &#8211;\u00a0<\/span><\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Cosenza sprecone in questo finale di primo tempo. Girata di D&#8217;Orazio che mette il pallone sul secondo palo per Corsi che per\u00f2 non arriva a ribadire in rete<\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/span><\/span><\/span><\/span><\/span><\/b><\/strong><\/b><\/strong><\/span><span style=\"color: #000000;\"><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">39&#8242; &#8211;\u00a0<\/span><\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Ancora un&#8217;occasionissima per Tutino che brucia in velocit\u00e0 Picone e sull&#8217;uscita del portiere Galli lo supera con un tocco morbido che per\u00f2 si spegne sul fondo uscendo di pochissimo<\/span><\/span><\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n34&#8242; &#8211;\u00a0<\/span><\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Mendicino serve in area Tutino\u00a0<\/span><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">che calcia al volo sul primo palo, miracolo di Galli che riesce a deviare in angolo con una mano. Pochi secondi prima angolo di D&#8217;Orazio che pesca in area Idda che tutto solo scivola incredibilmente a pochi passi dalla porta<\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a032&#8242; &#8211;\u00a0<\/span><\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Ammonito Picone per un fallo su Tutino che lo aveva saltato secco con un gioco di gambe<\/span><\/span><\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><br \/>\n29&#8242; &#8211;<\/span>\u00a0<\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Cesaretti si libera di Palmiero e calcia dal limite di destro che non \u00e8 il suo piedi. Pallone debole che Saracco fa suo\u00a0<\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><span style=\"color: #0000ff;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><span style=\"color: #000000;\">28&#8242; &#8211;<\/span>\u00a0<\/span><\/b><\/strong><\/b><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">Doppio cambio nella Paganese. Si fa male il portiere Gomis ed entra Galli. Fuori anche Maiorano e dentro\u00a0Ngamba<\/span><\/span><\/span><\/span><strong style=\"color: #000000;\"><b><strong style=\"color: #000000;\"><b style=\"color: #000000;\"><br \/>\n14&#8242; &#8211;\u00a0<\/b><\/strong><\/b><\/strong><span style=\"color: #000000;\">Azione personale di Tascone che salta in velocit\u00e0 due difensori del Cosenza e quasi dal limite dell&#8217;area calcia un pallone che finisce di poco alto sulla traversa<\/span><span style=\"color: #000000;\"><span style=\"color: #000000;\"><br \/>\n<span style=\"color: #000000;\"><b><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49956\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Goal2.gif\" alt=\"Goal2\" width=\"136\" height=\"68\" title=\"\">9&#8242; &#8211;<\/b><\/span><span style=\"color: #ff0000;\"><span style=\"color: #ff0000; font-weight: bold;\">\u00a0GOAL\u00a0COSENZA CON\u00a0BRUCCINI. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #000000;\">Azione avviata da Tutino che serve Calamai sulla sinistra\u00a0che con un dribbling fa secco Picone e mette in area un pallone sul quale Bruccini \u00e8 bravissimo a coordinarsi e\u00a0colpire al volo battendo Gomis che pu\u00f2 solo sfiorare. Per il centrocampista rossoblu 5 rete stagionale<\/span><\/span><\/strong><\/span><\/span><\/span><br \/>\n<b style=\"color: #000000;\"> 1&#8242; &#8211;\u00a0<\/b><span style=\"color: #000000;\">Primo tiro in porta dopo 30 secondi ed \u00e8 del Cosenza con un destro debole di Mendicino dal limite che Gomis blocca a terra\u00a0<\/span><strong style=\"color: #000000;\"><br \/>\n0&#8242; &#8211;<\/strong><span style=\"color: #000000;\">\u00a0Il Cosenza batte il calcio d&#8217;avvio. Rossoblu che in questo primo tempo attaccheranno da sinistra verso destra<\/span><br \/>\n<span style=\"color: #000000;\"> Le due squadre osservano un minuto di silenzio per commemorare l&#8217;ex tecnico della Paganese Rino Santin scomparso ieri all&#8217;et\u00e0 di 84 anni<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\">Ci sono due novit\u00e0 dell&#8217;ultimo minuto. Nella Paganese non c&#8217;\u00e8 Baccolo che si \u00e8 fatto male nel riscaldamento. Al suo posto Bensaja. Nel Cosenza Baclet dato inizialmente in panchina finisce invece tribuna<\/span><\/p>\n<p><span style=\"color: #000000;\">Paganese e Cosenza fanno il loro ingresso in campo. Gli uomini di Braglia in campo con la divisa bianca da trasferta. Padroni di casa in completo azzurro<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>PAGANESE CACLIO 1926\u00a0(4-3-3)<\/strong>: Gomis (28&#8242; Galli), Della Corte, Maiorano (28&#8242; Ngamba), Scarpa, Meroni, Talamo (72&#8242; Regolanti), Bensaja, Piana, Picone (45&#8242; Carini), Cesaretti, Tascone (92&#8242; Grillo)<\/span><span style=\"color: #000000;\"><br \/>\n<strong style=\"color: #000000;\">Panchina: <\/strong>Galli, Carini,<strong style=\"color: #000000;\">\u00a0<\/strong>Ngamba, Regolanti, Negro, Berdardini, Pavan, Buxton, Acampora, Dinielli, Grillo<br \/>\n<strong style=\"color: #000000;\">Allenatore:\u00a0<\/strong>Massimiliano Favo<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>COSENZA CALCIO\u00a0(3-5-2):\u00a0<\/strong>Saracco, Corsi, Idda,\u00a0Palmiero (88&#8242; Trovato), Mendicino (45&#8242; Statella), Pasqualoni (71&#8242; Pascali), Bruccini (88&#8242; Loviso), Calamai, Tutino, D\u2019Orazio, Dermaku<strong><strong><br \/>\nPanchina:\u00a0<\/strong><\/strong>Perina, Statella, Boniotti, Baclet,\u00a0Trovato, Liguori, Loviso, Pascali<strong><br \/>\n<strong>Allenatore:<\/strong>\u00a0<\/strong>Piero Braglia<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Arbitro<\/strong>: Signor Paride De Angeli di\u00a0Abbiategrasso<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Assistenti:\u00a0<\/strong>Signor Francesco Bruni di Brindisi e signor Paolo Laudato di Taranto<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Ammoniti<\/strong>: Picone (P),\u00a0Bensaja (P), Piana (P), Palmiero (C), Bruccini (C)<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Espulsi:<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Angoli<\/strong>: 0-5<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Note<\/strong>:\u00a0Pomeriggio nuvoloso ma non freddo a Pagani. Terreno del Marcello Torre in discrete condizioni. Pochissimi gli spettatori e quantificabili in alcune centinaia. Presenti una cinquantina di tifosi del Cosenza sistemati nel loro settore Prima del fischio d&#8217;inizio le due squadre hanno osservato\u00a0 un minuto di silenzio per commemorare l&#8217;ex tecnico della Paganese Rino Santin\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quarto sigillo consecutivo per i rossoblu che chiudono il 2017 battendo con il pi\u00f9 classico dei risultati la Paganese, al termine di un match senza storia\u00a0e deciso dalle reti in apertura di Mirko Bruccini e nel secondo tempo di D&#8217;Orazio. Cosenza che vola al 7&#8242; posto in classifica<\/p>\n","protected":false},"author":23,"featured_media":87837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-87836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/87836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=87836"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/87836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/87837"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=87836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=87836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=87836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}