{"id":88283,"date":"2018-01-14T05:30:39","date_gmt":"2018-01-14T04:30:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/alberi-monumentali-ditalia-confermate-le-maestose-testimonianze-dellaspromonte\/"},"modified":"2023-01-16T18:48:07","modified_gmt":"2023-01-16T17:48:07","slug":"195699-alberi-monumentali-ditalia-confermate-le-maestose-testimonianze-dellaspromonte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/195699-alberi-monumentali-ditalia-confermate-le-maestose-testimonianze-dellaspromonte\/","title":{"rendered":"Alberi monumentali d\u2019Italia: confermate le maestose testimonianze dell\u2019Aspromonte"},"content":{"rendered":"<h4>L\u2019albero secolare tipico \u00e8 considerato esempio di maestosit\u00e0 e longevit\u00e0. A volte si tratta di vere e proprie rarit\u00e0 botaniche<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ASPROMONTE (RC) &#8211; Sono ben venticinque gli Alberi Monumentali che vegetano nel Parco dell\u2019Aspromonte. Lo si evince dal primo elenco nazionale approvato dal Ministero delle Politiche Agricole e forestali. Testimoni del lungo lavoro della natura,<strong> \u201cportatori di un valore estetico, culturale e naturalistico\u201d, gli Alberi Monumentali \u201caccompagnano\u201d la storia ed il sentimento delle popolazioni dell\u2019Aspromonte<\/strong> e da sempre sono oggetto di studio da parte della comunit\u00e0 scientifica locale ed internazionale. Il posizionamento nella classifica regionale \u00e8 di tutto rispetto: <strong>circa il 30% degli Alberi Monumentali presenti in Calabria, infatti, hanno vita in Aspromonte<\/strong> che si conferma, ancora una volta, quale area di eccellente valenza biogeografica d\u2019Italia.<\/p>\n<p>Che lo si consideri isolato o facente parte di formazioni boschive naturali,<strong> l\u2019albero secolare tipico, \u00e8 considerato esempio di maestosit\u00e0 e longevit\u00e0. A volte si tratta di vere e proprie rarit\u00e0 botaniche<\/strong>; altre ancora recano un preciso riferimento ad eventi o memorie rilevanti dal punto di vista storico, culturale, documentario o delle tradizioni locali. \u201c<strong>Dall\u2019Olmo Campestre di San Lorenzo<\/strong> (su cui, recentemente, l\u2019Ente Parco ha avviato una importante operazione di tutela) alla Quercia Ibrida di \u201cCroce di Dio sia Lodato\u201d a Samo, dal castagno di San Giorgio di Pietra Cappa al Tasso di Zerv\u00f2 (Santa Cristina),<strong> l\u2019elenco dei nostri \u201cedifici vegetali\u201d \u00e8 di grande rilievo scientifico<\/strong> \u2013 dichiara il Presidente <strong>Giuseppe Bombino<\/strong> &#8211; e conferma la valenza naturalistica dell\u2019Aspromonte quale<strong> \u201crifugio\u201d per le specie floristiche e faunistiche.<\/strong> Gli Alberi Monumentali consentono di diversificare le peculiarit\u00e0 del territorio e costituiscono punti di richiamo turistici ed escursionistici, nonch\u00e9 riferimento per attivit\u00e0 formative e di educazione ambientale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019albero secolare tipico \u00e8 considerato esempio di maestosit\u00e0 e longevit\u00e0. A volte si tratta di vere e proprie rarit\u00e0 botaniche<\/p>\n","protected":false},"author":22,"featured_media":88284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-88283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=88283"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/88284"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=88283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=88283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=88283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}