{"id":88321,"date":"2018-01-12T07:05:17","date_gmt":"2018-01-12T06:05:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bar-e-ristoranti-tra-firenze-e-prato-sequestrati-a-imprenditore-legato-alla-ndrina-giglio\/"},"modified":"2023-01-16T18:48:10","modified_gmt":"2023-01-16T17:48:10","slug":"195871-bar-e-ristoranti-tra-firenze-e-prato-sequestrati-a-imprenditore-legato-alla-ndrina-giglio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/195871-bar-e-ristoranti-tra-firenze-e-prato-sequestrati-a-imprenditore-legato-alla-ndrina-giglio\/","title":{"rendered":"Bar e ristoranti tra Firenze e Prato sequestrati a imprenditore legato alla &#8216;ndrina Giglio"},"content":{"rendered":"<h4>Il sequestro ha interessato locali a Firenze e immobili a Prato. Nel mirino un affiliato &#8216;ndrina &#8216;Giglio&#8217; di Strongoli, nel crotonese<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>FIRENZE &#8211; Alcuni noti locali di Firenze e immobili di pregio a Prato sono stati posti sotto sequestro nell&#8217;ambito di una operazione antiriciclaggio della Dia di Firenze nei confronti di un imprenditore calabrese trapiantato da anni nella regione, ritenuto legato alla &#8216;ndrina Giglio di Strongoli (Kr). Al centro dell&#8217;indagine \u00e8 finito<strong> Giuseppe Iuzzolino, 81 anni,<\/strong> il quale, coadiuvato da alcuni prestanome, avrebbe effettuato, nel tempo, ingenti investimenti in zona, pur in mancanza di una lecita capacit\u00e0 reddituale. Gli investigatori avrebbero poi appurato l&#8217;esistenza di flussi di denaro verso la Calabria, in favore di appartenenti alla\u00a0cosca<strong>.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-195872\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/antimafia-dia-firenze.jpg\" alt=\"antimafia-dia firenze\" width=\"590\" height=\"279\" title=\"\"><\/p>\n<h2>Sotto sequestro bar, pizzerie\u00a0e immobili di pregio<\/h2>\n<p>Tra i beni finiti sotto sequestro, del valore complessivo di o<strong>ltre 4 milioni di euro<\/strong>, anche i bar pasticceria<strong> Caldana e Il Barco<\/strong>, e il ristorante <strong>Pizza man di Firenze<\/strong>, e <strong>immobili di pregio situati nel complesso edilizio Il Teatro nel quartiere Il Pino di Prato<\/strong>, oltre ad altri immobili, partecipazioni societarie e rapporti bancari sequestrati tra la Toscana e Crotone. <strong>Gli altri indagati<\/strong> in concorso per i reati di evasione fiscale e per quello di associazione per delinquere finalizzata al riciclaggio sono <strong>Vincenzo Benincasa, Fiore Guercio e Martino Castiglione (di Strongoli),<\/strong> Alfredo Aldrovandi, di San Benedetto Val Di Sambro (Bologna) e residente a Firenze, e <strong>Luigi Guercio, nato a Cariati (Cs)<\/strong> e residente a Strongoli. Il Centro Operativo D.I.A. di Firenze ha dato esecuzione ad un provvedimento emesso dal locale Tribunale del Riesame, che ha disposto il sequestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sequestro ha interessato locali a Firenze e immobili a Prato. Nel mirino un affiliato &#8216;ndrina &#8216;Giglio&#8217; di Strongoli, nel crotonese<\/p>\n","protected":false},"author":22,"featured_media":88322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-88321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=88321"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/88322"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=88321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=88321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=88321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}