{"id":88367,"date":"2018-01-12T21:22:34","date_gmt":"2018-01-12T20:22:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-droga-e-imprenditoria-chiesta-condanna-per-moglie-e-figlia-del-boss-franco-muto\/"},"modified":"2023-01-16T18:48:13","modified_gmt":"2023-01-16T17:48:13","slug":"196031-ndrangheta-droga-e-imprenditoria-chiesta-condanna-per-moglie-e-figlia-del-boss-franco-muto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/196031-ndrangheta-droga-e-imprenditoria-chiesta-condanna-per-moglie-e-figlia-del-boss-franco-muto\/","title":{"rendered":"&#8216;Ndrangheta, droga e imprenditoria: chiesta condanna per moglie e figlia del boss Franco Muto"},"content":{"rendered":"<h4>L&#8217;inchiesta\u00a0riguarda sia il narcotraffico sia la gestione di importanti appalti nel Cosentino come quello di piazza Bilotti, del Lorica Ski e dell&#8217;aviosuperfice di Scalea<\/h4>\n<p><!--more--><br \/>\nCATANZARO &#8211; Il sostituto procuratore di Catanzaro Alessandro Prontera ha chiesto la condanna per tutti i 39 imputati al termine della sua requisitoria nel processo, con rito abbreviato, scaturito dalle operazioni &#8220;Frontiera&#8221; e &#8220;Cinque lustri&#8221; che hanno sgominato il clan Muto di Cetraro e la rete degli imprenditori di riferimento. Il pm ha chiesto pene comprese tra i 20 anni e i due anni. <strong>La pena pi\u00f9 alta \u00e8 stata richiesta per Franco Cipolla, detto &#8220;Tabacco&#8221;, di Cetraro, e Guido Maccari,<\/strong> ritenuti dagli inquirenti &#8220;organizzatori, col compito di gestire il traffico di narcotico, procurando e gestendo sempre nuovi canali di approvvigionamento di stupefacenti, di organizzare le piazze di spaccio selezionando e rifornendo i grossisti della consorteria&#8221;. Chiesta la condanna anche per i figli del boss Franco Muto\u00a0detto il\u00a0\u201cRe del pesce\u201d, Luigi (a 17 anni) e Mara (9 anni). Dieci anni \u00e8 stata invece la richiesta di condanna avanzata dal pm per Angelina Corsanto, moglie di Muto, ritenuta la reggente del clan dopo l&#8217;arresto del marito, tanto da detenere la &#8220;bacinella&#8221; dell&#8217;organizzazione criminale.\u00a0Franco Muto \u00e8 invece imputato nel processo con rito ordinario.<\/p>\n<p>&nbsp;<\/p>\n<p>Secondo l\u2019accusa la cosca e i suoi sodali avrebbero monopolizzato per oltre 30 anni le risorse economiche del territorio, dal commercio del pesce ai servizi di lavanderia degli alberghi, alla vigilanza nei locali notturni.\u00a0Ma non solo, sui Muto pende anche l\u2019accusa del controllo di un grosso traffico di stupefacenti che riforniva le principali localit\u00e0 balneari della costa tirrenica, da Diamante a Scalea e Praia a Mare. Il processo riprender\u00e0 il prossimo 15 gennaio. L&#8217;inchiesta &#8220;Frontiera&#8221;, partita da un troncone dell&#8217;indagine sull&#8217;omicidio di Angelo Vassallo, il sindaco-pescatore di Pollica (Salerno) ucciso nel 2010, <strong>ha portato nel luglio 2016 all&#8217;arresto di 58 persone ritenute dagli inquirenti appartenenti alla cosca Muto<\/strong>, indagate per associazione di tipo mafioso, associazione per delinquere finalizzata al traffico di sostanze stupefacenti, estorsione, rapina, usura e illecita concorrenza con violenza e minaccia. Proprio partendo dalla cosca Muto il 19 la Direzione distrettuale antimanfia di Catanzaro nel gennaio 2017, ha messo a segno l&#8217;inchiesta &#8220;Cinque lustri&#8221;, che ha consentito di svelare un&#8217;associazione per delinquere di tipo mafioso finalizzata alla turbativa di gare d&#8217;appalto nel settore pubblico nel periodo 2013-2015.\u00a0 Lavori che avrebbero interessato anche piazza Bilotti a Cosenza, il Lorica Ski a Lorica e l&#8217;aeroporto di Scalea.<\/p>\n<p>&nbsp;<\/p>\n<h3>RICHIESTE DI CONDANNA:<\/h3>\n<ul>\n<li>8 anni per Carlo Antonuccio;<\/li>\n<li>5 anni per Gianluca Arlia;<\/li>\n<li>2 anni per Salvatore Baldino;<\/li>\n<li>2 anni per Giuseppe Nicola Bosco;<\/li>\n<li>2 anni per Gennaro Brescia;<\/li>\n<li>7 anni per Giulio Caccamo;<\/li>\n<li>7 anni per Pietro Calabria;<\/li>\n<li>2 anni per Gianluca Caprino;<\/li>\n<li>8 anni per Angelo Casella;<\/li>\n<li>15 anni per Fedele Cipolla;<\/li>\n<li>20 anni per Franco Cipolla;<\/li>\n<li>10 anni per Angelina Corsanto;<\/li>\n<li>17 anni per Alessandro De Pasquale;<\/li>\n<li>6 anni per Antonio Di Pietromica;<\/li>\n<li>7 anni per Gianfranco Di Santo;<\/li>\n<li>9 anni per Giuseppe Natale Esposito;<\/li>\n<li>12 anni per Giuseppe Fiore;<\/li>\n<li>4 anni per Adolfo Foggetti;<\/li>\n<li>2 anni per Antonietta Galliano;<\/li>\n<li>20 anni per Guido Maccari;<\/li>\n<li>4 anni per Giuseppe Montemurro;<\/li>\n<li>17 anni per Luigi Muto;<\/li>\n<li>9 anni per Mara Muto;<\/li>\n<li>2 anni per Sandra Muto;<\/li>\n<li>15 anni per Carmine Occhiuzzi;<\/li>\n<li>15 anni per Luca Occhiuzzi;<\/li>\n<li>13 anni per Andrea Orsino;<\/li>\n<li>17 anni per Alfredo Palermo;<\/li>\n<li>16 anni per Valentino Palermo;<\/li>\n<li>6 anni per Sara Pascariello;<\/li>\n<li>8 anni per Raimondi Sabrina;<\/li>\n<li>7 anni per Vittorio Reale;<\/li>\n<li>4 anni per Luigi Sarmiento;<\/li>\n<li>15 anni per Giuseppe Scornaienchi;<\/li>\n<li>14 anni per Salvatore Sinicropi;<\/li>\n<li>8 anni per Rocco Trazza;<\/li>\n<li>16 anni per Carmelo Valente;<\/li>\n<li>6 anni per Pietro Valente.<\/li>\n<\/ul>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3787\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Frontiera \u2013 Cinque Lustri, processo diviso in due. Rito abbreviato per Franco Muto perch\u00e8 ha 78 anni<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2244\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Operazioni \u201cCumbertazione\u201d e \u201c5 Lustri\u201d, eseguiti 33 fermi \u2013 NOMI e AZIENDE SEQUESTRATE<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2249\">Appalti e \u2018ndrangheta: Fermati 35 imprenditori. Sigilli al parcheggio di Piazza Bilotti (FOTO e VIDEO)<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2594\">Cosenza inaugura il \u2018parcheggio di Franco Muto\u2019. Ecco cosa raccontano i \u2018pentiti\u2019<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;inchiesta\u00a0riguarda sia il narcotraffico sia la gestione di importanti appalti nel Cosentino come quello di piazza Bilotti, del Lorica Ski e dell&#8217;aviosuperfice di Scalea<\/p>\n","protected":false},"author":22,"featured_media":88368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-88367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=88367"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/88368"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=88367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=88367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=88367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}