{"id":88796,"date":"2018-01-23T07:48:00","date_gmt":"2018-01-23T06:48:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ego-lalbum-debutto-del-cantante-alessandro-rosace\/"},"modified":"2023-01-16T18:48:41","modified_gmt":"2023-01-16T17:48:41","slug":"197985-ego-lalbum-debutto-del-cantante-alessandro-rosace","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/197985-ego-lalbum-debutto-del-cantante-alessandro-rosace\/","title":{"rendered":"Ego, \u00e8 l&#8217;album di debutto del cantante Alessandro Rosace"},"content":{"rendered":"<h4>Un album solista, dove Rosace si esprime attraverso la sua voce, l&#8217;utilizzo dell&#8217;elettronica e delle sue composizioni atipiche.\u00a0<!--more--><\/h4>\n<div dir=\"auto\">COSENZA- Si spazia da un&#8217;atmosfera psichedelica, ad un groove africano, con richiami che strizzano l&#8217;occhio ad una musica introspettiva, riflessiva, innovativa e accattivante. La voce \u00e8 il faro di tutte le composizioni, una voce libera dalla gabbia, che prende forma, colore e suono mettendo in luce l&#8217;ecclettico e cristallino talento di Alessandro Rosace. <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-197988 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/IMG_20180121_183735_005-400x400.jpg\" alt=\"IMG_20180121_183735_005\" width=\"295\" height=\"295\" title=\"\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Diplomato con il massimo dei voti al conservatorio di Cosenza, in Canto Jazz, e al Biennio Jazz di Frosinone.\u00a0Ha studiato\u00a0con i maestri: Davide Santorsola, Cinzia Spata, Albert Hera, Elisabetta Antonini, Gianna Montecalvo, Marco Tiso, Carla Marcotulli, Carlo Lomanto. Il suo debutto\u00a0nel disco MMXV, di Stefano Pagni (alfamusic) con Danilo Rea, Israel Varela, Stefano Micarelli;\u00a0\u00a0il primo album da solista \u00e8 &#8216;EGO&#8217;, Voce Elettronica e Composizioni Originali.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un album solista, dove Rosace si esprime attraverso la sua voce, l&#8217;utilizzo dell&#8217;elettronica e delle sue composizioni atipiche.\u00a0<\/p>\n","protected":false},"author":20,"featured_media":88797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-88796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=88796"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/88797"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=88796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=88796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=88796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}