{"id":8897,"date":"2012-12-03T15:50:17","date_gmt":"2012-12-03T14:50:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8897"},"modified":"2023-01-17T13:42:04","modified_gmt":"2023-01-17T12:42:04","slug":"3873-colpi-pistola-contro-automobile-avvocato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3873-colpi-pistola-contro-automobile-avvocato\/","title":{"rendered":"Colpi pistola contro automobile avvocato"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>LAMEZIA TERME (CATANZARO)<\/strong> &#8211; Alcuni colpi di pistola sono stati sparati da sconosciuti a Lamezia Terme contro l&#8217;automobile dell&#8217;avvocato<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">penalista Leopoldo Marchese.<br \/>L&#8217;intimidazione e&#8217; stata messa in atto mentre l&#8217;avvocato era in casa e l&#8217;automobile era parcheggiata nel giardino della sua abitazione. Quando Marchese e&#8217; uscito si e&#8217; accorto dell&#8217;episodio. L&#8217;avvocato ha presentato denuncia ai militari della Guardia di finanza. &#8221;Non mi lascio intimidire da nessuno&#8221;, ha detto Marchese. (Fonte ANSA)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME (CATANZARO) &#8211; Alcuni colpi di pistola sono stati sparati da sconosciuti a Lamezia Terme contro l&#8217;automobile dell&#8217;avvocato<\/p>\n","protected":false},"author":22,"featured_media":8898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-8897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8897"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8898"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}