{"id":88983,"date":"2018-01-26T19:50:10","date_gmt":"2018-01-26T18:50:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/calatrava-da-mancini-ad-occhiuto-un-ponte-dedicato-ai-giovani\/"},"modified":"2023-01-16T18:48:53","modified_gmt":"2023-01-16T17:48:53","slug":"198784-calatrava-da-mancini-ad-occhiuto-un-ponte-dedicato-ai-giovani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/198784-calatrava-da-mancini-ad-occhiuto-un-ponte-dedicato-ai-giovani\/","title":{"rendered":"Calatrava, da Mancini ad Occhiuto: &#8220;Un ponte dedicato ai giovani&#8221;"},"content":{"rendered":"<h4>Inaugurato il ponte costruito sul fiume Crati, con i suoi 130 metri di ampiezza e l\u2019imponente torre di 104 metri. La gaffe dell\u2019archistar Santiago Calatrava \u201cnon ci sono state vittime\u201d<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Un <strong>pianista<\/strong> che suona sospeso nel vuoto e una serie di <strong>spettacolari, apparizioni &#8216;aeree&#8217;<\/strong> per celebrare la leggerezza e la fantasia&#8221;. Cos\u00ec aveva promesso il primo cittadino Occhiuto durante la conferenza stampa romana di presentazione dell&#8217;inaugurazione del ponte Caltrava, e cos\u00ec ha mantenuto fede con il taglio del nastro avvenuto in queste ore alla presenza di autorit\u00e0 militari, civili, religiose. Un imponente spiegamento di forze dell&#8217;ordine e di Steward per regolare\u00a0l&#8217;affuenza\u00a0di una moltitudine di gente accorsa per vedere l&#8217;opera tanto &#8220;chiacchierata&#8221; ma pur sempre un&#8217;opera di importanza straordinaria per il sud, la Calabria, Cosenza e l&#8217;Italia tutta. Un po&#8217; di disordine iniziale, per via della calca delle persone, incuranti di transenne e frecce direzionali, che sostavano per essere i primi, dopo il taglio del nastro, a posizionarsi in prima linea per la grande festa.<\/p>\n<p>Prima del discorso ufficiale l&#8217;architetto <strong>Santiago Calatrava<\/strong> insieme al primo cittadino Occhiuto, si sono fermati con la stampa per rispondere ad alcune domande. Per il &#8220;padre&#8221; dell&#8217;opera costruita sul fiume, i<strong>l ponte ha anche un significato simbolico e &#8220;credo che sarebbe quello che oggi rappresenta una citt\u00e0 che vuole essere presente nel ventunesimo secolo come Cosenza&#8221;<\/strong>. Occhiuto punta sui giovani, sul futuro del sud e non \u00e8 impreparato , anche se con un po&#8217; di titubanza, a rispondere sugli ex fondi Gescal: \u00abAbbiamo <strong>avuto l&#8217;onore e il merito di completare questa opera,<\/strong> per la citt\u00e0 di Cosenza, dopo tante problematiche che non avevano mai fatto iniziare il cantiere. Vuol dire che c&#8217;\u00e8 <strong>continuit\u00e0 tra passato e futuro<\/strong>. La destiniamo al futuro di questa citt\u00e0, soprattutto a giovani perch\u00e9 possano guardare a questo ponte ed essere <strong>orgogliosi di questa citt\u00e0<\/strong>, per fare della Calabria <strong>questa idea di innovazione<\/strong> di citt\u00e0 che \u00e8 cos\u00ec straordinaria, non solo per quello che ha ereditato dal passato ma per quello che ha realizzato in questi anni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-198808\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/Inaugurazione-Calatrava06.jpg\" alt=\"Inaugurazione Calatrava06\" width=\"590\" height=\"332\" title=\"\"><\/p>\n<p>Sulla moltitudine di gente presente all&#8217;inaugurazione : \u00abI <strong>cittadini<\/strong> hanno <strong>apprezzato<\/strong> questa idea di <strong>modernit\u00e0<\/strong>, da tanti anni che la ricercano; e questa lunga attesa ha finalmente portato qui le persone, ad impadronirsi di un pezzo di citt\u00e0 in un&#8217;area marginale. E&#8217; un <strong>segno importante per questo territorio<\/strong> di innovazione, di creativit\u00e0, un processo di rigenerazione della citt\u00e0, un&#8217;opera di qualit\u00e0 realizzata in Italia. E Cosenza lancia un segnale di possibilit\u00e0 di crescita anche del sud.\u00a0 <strong>Sugli ex fondi Gescal<\/strong> e sui costi sostenuti Occhiuto risponde: \u00abAlla fine \u00e8 costato quello che era\u00a0 l&#8217;indotto:\u00a0<strong>13 milioni di euro<\/strong> e riguardano i finanziamenti delle zone del <strong>piano di recupero urbano,<\/strong> dove si possono realizzare opere pubbliche. Incalzato ancora dalle domande della stampa sui fondi ex Gescal Occhiuto risponde \u00ab<strong>Noi abbiamo preso il finanziamento dalla regione Calabria<\/strong>\u00bb<\/p>\n<p>&nbsp;<\/p>\n<h2>Il sindaco Mario Occhiuto &#8220;Questo ponte che canta&#8221; il senso del territorio<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-198802 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/Inaugurazione-Calatrava01-440x248.jpg\" alt=\"Inaugurazione Calatrava01\" width=\"440\" height=\"248\" title=\"\">Finanziato con <strong>13<\/strong> <strong>milioni e mezzo di euro<\/strong> (che arrivano a <strong>20 milioni con le opere accessorie<\/strong>), il bianco ponte con i suoi <strong>130 metri di ampiezza e l&#8217;imponente torre di 104 metri<\/strong>, realizzato dall&#8217;impresa Cimolai ha impegnato dal 2011 l&#8217;amministrazione comunale. &#8220;Il ponte \u00e8 un segno di vittoria, che dimostra che anche in Italia si possono fare le opere pubbliche&#8221;, ha sempre sostenuto il sindaco Occhiuto dal momento in cui i lavori hanno ripreso ad andare avanti convinto di riuscire ad arrivare al giorno dell&#8217;inaugurazione cos\u00ec com&#8217;\u00e8 successo oggi. \u00abSu questo ponte fantastico, su questa opera pubblica sono con la mia giunta, i dirigenti del comune, le maestranze, tante le persone impegnate. Un contributo importante, anche per questa giornata, da tutta la macchina amministrativa comunale, la polizia municipale e tutte le forze dell&#8217;ordine, il vescovo Nunnari presente per l&#8217;inaugurazione di questo ponte <strong>intitolato a San Francesco di Paola il nostro santo patrone della Calabria, co-patrone della citt\u00e0 di Cosenza<\/strong>. Avevo preparato una bozza di discorso\u00a0 &#8211; continua Occhiuto- ma guardavo il viso e gli occhi delle persone e guardavo questo senso di stupore, di meraviglia: <strong>oggi noi celebriamo questo ponte\u00a0 &#8220;che canta&#8221;<\/strong>. Ecco, non parlano solo le persone, non sorridono. In questo caso <strong>anche le opere possono parlare, esprimere, cantare questa meraviglia\u00a0 e bellezza al mondo.<\/strong> Vedevo negli occhi delle persone lo stupore osservando l&#8217;opera. Mi colpisce moltissimo! L&#8217;opera canta perch\u00e9 <strong>contiene questo senso del territorio: contiene il fiume, collega due quartieri popolari, Gergeri e via Popilia<\/strong>. Un&#8217;opera che ha gi\u00e0 riqualificato con la sua presenza questi quartieri,\u00a0<strong>un tempo emarginati<\/strong> e aspettano questa riqualificazione.<\/p>\n<p>Qui, verr\u00e0 realizzata una grande piazza che collegher\u00e0 il <strong>planetario,<\/strong> e tra un mese verr\u00e0 inaugurato, e sar\u00e0 il secondo planetario in Italia come dimensioni, con una grande piazza e il <strong>fiume navigabile<\/strong> che entra nel centro storico. Anche in questa occasione ci sar\u00e0 un recupero della citt\u00e0 antica. Ecco, questo ponte contiene questa storia, il nostro territorio; ha alle spalle la Sila e contiene anche il passato. Un ponte che guarda al <strong>centro storico<\/strong>, al castello. Un ponte che canta alla bellezza del passato, del territorio ma anche del futuro, \u00e8 un segno del futuro. Ieri ho ritrovato il discorso che fece <strong>Giacomo Mancini<\/strong> 20 anni fa, e lo ringrazio, perch\u00e9 ebbe questa <strong>grande idea<\/strong> che noi abbiamo avuto la possibilit\u00e0 di portare avanti. Questo era un cantiere bloccato perch\u00e9 c&#8217;erano delle bonifiche da fare, un terreno sequestrato, un cantiere mai partito, dove Mancini ebbe questa idea felice. Mancini parlava di questa opera come <strong>un&#8217;opera dedicata ai giovani<\/strong> che vedono questo segno quando passano da qui, e vedono il centro storico, i fiumi; anche questo \u00e8 <strong>un esempio di democrazia urbana<\/strong> diceva l&#8217;architetto Calatrava. Un&#8217;opera pubblica \u00e8 per tutti, possono vederla tutti. E diceva Mancini: &#8220;questa <strong>opera di cultura raffinata&#8221;<\/strong> producono questo stimolo nei giovani:\u00a0la portano con loro dove vanno,\u00a0 si inorgogliscono, <strong>rispettano la citt\u00e0 e l&#8217;amano<\/strong>. Ecco perch\u00e9 \u00e8 importante realizzare queste opere e andremo avanti in questo processo di rinnovamento della citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h2>La gaffe dell&#8217;archistar Calatrava &#8220;non ci sono state vittime&#8221;<!--nextpage--><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-198807 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/Inaugurazione-Calatrava05-440x247.jpg\" alt=\"Inaugurazione Calatrava05\" width=\"440\" height=\"247\" title=\"\">\u00abRingrazio i Sindaci Mancini e Occhiuto che ha portato avanti questo ponte con tanta energia e tanta fede. Un momento questo anche per ringraziare Dio, <strong>per avere concluso quest&#8217;opera senza nessun incidente &#8211; <\/strong>dichiara Santiago Calatrava dal palco<b>&#8211;<\/b>. Tutti gli operai e tutti quelli che hanno contribuito sono riusciti a superare con perizia e prudenza tutte le difficolt\u00e0, conservando l&#8217;integrit\u00e0. Ringrazio gli operai a quelli che con le loro mani, la loro esperienza e il loro sapere sono riusciti a portare questa opera cos\u00ec ardita e contemporanea\u00bb.<\/p>\n<p>Forse per\u00f2 l&#8217;<strong>archistar<\/strong> ha dimenticato che <strong>un morto c&#8217;\u00e8 stato per questo ponte<\/strong>, che sar\u00e0 pur bianco, ma se guardato bene \u00e8 <strong>macchiato del sangue<\/strong> di <strong>Raffele Tenuta<\/strong>, meglio conosciuto\u00a0 come Maurizio, l\u2019operaio di 53 anni di Marano Marchesato, deceduto all\u2019ospedale dell\u2019Annunziata di Cosenza\u00a0dopo una lunga agonia. <strong>Pagato in nero<\/strong>, cercava di raccattare qualche soldo per se e la sua famiglia. Con l&#8217;<strong>omert\u00e0<\/strong> di chi ha preferito accompagnarlo a casa &#8220;morente&#8221; per non rivelare che c&#8217;erano delle <strong>irregolarit\u00e0 sul lavoro<\/strong>. Forse <strong>Calatrava non sa o dimentica, ma la citt\u00e0 non dimentica.<\/strong><\/p>\n<h3 style=\"text-align: center;\">LEGGI ANCHE<br \/>\n<span style=\"color: #0000ff;\">\u00a0<\/span><br \/>\n<span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3845\" target=\"_blank\" rel=\"noopener\">Proteste durante l\u2019inaugurazione del Ponte di Calatrava: \u201cNon c\u2019\u00e8 nulla da festeggiare\u201d (FOTO E VIDEO)<\/a><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugurato il ponte costruito sul fiume Crati, con i suoi 130 metri di ampiezza e l\u2019imponente torre di 104 metri. La gaffe dell\u2019archistar Santiago Calatrava \u201cnon ci sono state vittime\u201d<\/p>\n","protected":false},"author":37,"featured_media":88984,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-88983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=88983"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/88983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/88984"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=88983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=88983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=88983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}