{"id":89272,"date":"2018-02-03T16:15:03","date_gmt":"2018-02-03T15:15:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-gas-naturale-siglato-protocollo-con-74-comuni\/"},"modified":"2023-01-16T18:49:13","modified_gmt":"2023-01-16T17:49:13","slug":"200114-cosenza-gas-naturale-siglato-protocollo-con-74-comuni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/200114-cosenza-gas-naturale-siglato-protocollo-con-74-comuni\/","title":{"rendered":"Cosenza, gas naturale, siglato protocollo con 74 Comuni"},"content":{"rendered":"<h4>La Provincia di Cosenza\u00a0firma\u00a0convenzione\u00a0e\u00a0continuare l&#8217;iter di gara per individuare\u00a0gestore unico a garanzia di uniformit\u00e0 di trattamento (Elenco Comuni)<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00c8 stata sottoscritta nel tardo pomeriggio di ieri, presso la sede di Piazza XV Marzo, la <strong>convenzione<\/strong> tra la <strong>Provincia di Cosenza<\/strong> e i Comuni appartenenti all\u2019Ambito Territoriale Minimo <strong>Cosenza 2 Est<\/strong>, per l\u2019affidamento del servizio di <strong>distribuzione del gas naturale<\/strong> in forma associata ai sensi del DM 226\/2011. L\u2019importante risultato \u00e8 frutto del lavoro e dell\u2019impegno della Provincia di Cosenza, coadiuvata dalla sua partecipata Alessco, che nell\u2019ultimo anno ha dato una forte accelerazione alle attivit\u00e0 propedeutiche alla firma della convenzione. In occasione dell\u2019incontro sono state illustrate le linee guida d\u2019ambito, che consentiranno ai Comuni di poter formulare gli elementi programmatici di sviluppo elaborati con il supporto di Alessco.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-109043 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/provincia-di-cosenza-374x280.jpg\" alt=\"provincia-di-cosenza\" width=\"268\" height=\"201\" title=\"\">I <strong>tecnici<\/strong> della Provincia e di Alessco si sono sin da subito dichiarati <strong>disponibili a supportare gli Uffici Comunali<\/strong> nella raccolta e implementazione dei dati. \u00c8 un risultato rilevante, che pu\u00f2 permettere di proseguire l\u2019iter di gara per individuare il <strong>nuovo gestore unico<\/strong> delle reti gas per l\u2019intero territorio dell\u2019ambito Cosenza 2, costituito da ben <strong>settantaquattro Comuni<\/strong> e che potr\u00e0 garantire uniformit\u00e0 di trattamento per i cittadini e maggiori introiti per le casse comunali. Nei prossimi giorni sar\u00e0 convocata l\u2019<strong>Assemblea dei Sindaci<\/strong> per la <strong>costituzione<\/strong> della <strong>Cabina di Regia<\/strong>, che avr\u00e0 il compito di favorire il confronto e la collaborazione tra i Comuni e la Stazione appaltante.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">Ambiti territoriali del settore della distribuzione del gas naturale secondo le tabelle riportate nel portale\u00a0 del Ministero dello Sviluppo Economico<\/h3>\n<h3 style=\"text-align: center;\">Gli\u00a0elenchi dei Comuni COSENZA 1 &#8211; OVEST\u00a0e COSENZA 2 &#8211; EST<!--nextpage--><\/h3>\n<p>&nbsp;<\/p>\n<p><strong>Cosenza 2 &#8211; Est<\/strong><\/p>\n<ol>\n<li><strong>Acri<\/strong><\/li>\n<li><strong>Albidona<\/strong><\/li>\n<li><strong>Alessandria del Carretto<\/strong><\/li>\n<li><strong>Altilia<\/strong><\/li>\n<li><strong>Amendolara<\/strong><\/li>\n<li><strong>Aprigliano<\/strong><\/li>\n<li><strong>Belsito<\/strong><\/li>\n<li><strong>Bianchi<\/strong><\/li>\n<li><strong>Bisignano<\/strong><\/li>\n<li><strong>Bocchigliero<\/strong><\/li>\n<li><strong>Calopezzati<\/strong><\/li>\n<li><strong>Caloveto<\/strong><\/li>\n<li><strong>Campana<\/strong><\/li>\n<li><strong>Canna<\/strong><\/li>\n<li><strong>Cariati<\/strong><\/li>\n<li><strong>Carpanzano<\/strong><\/li>\n<li><strong>Casole Bruzio<\/strong><\/li>\n<li><strong>Cassano allo Ionio<\/strong><\/li>\n<li><strong>Castiglione Cosentino<\/strong><\/li>\n<li><strong>Castroregio<\/strong><\/li>\n<li><strong>Celico<\/strong><\/li>\n<li><strong>Cellara<\/strong><\/li>\n<li><strong>Cerchiara di Calabria<\/strong><\/li>\n<li><strong>Colosimi<\/strong><\/li>\n<li><strong>Corigliano Calabro<\/strong><\/li>\n<li><strong>Cropalati<\/strong><\/li>\n<li><strong>Crosia<\/strong><\/li>\n<li><strong>Figline Vegliaturo<\/strong><\/li>\n<li><strong>Francavilla Marittima<\/strong><\/li>\n<li><strong>Grimaldi<\/strong><\/li>\n<li><strong>Lappano<\/strong><\/li>\n<li><strong>Longobucco<\/strong><\/li>\n<li><strong>Luzzi<\/strong><\/li>\n<li><strong>Malito<\/strong><\/li>\n<li><strong>Mandatoriccio<\/strong><\/li>\n<li><strong>Mangone<\/strong><\/li>\n<li><strong>Marzi<\/strong><\/li>\n<li><strong>Montegiordano<\/strong><\/li>\n<li><strong>Nocara<\/strong><\/li>\n<li><strong>Oriolo<\/strong><\/li>\n<li><strong>Paludi<\/strong><\/li>\n<li><strong>Panettieri<\/strong><\/li>\n<li><strong>Parenti<\/strong><\/li>\n<li><strong>Pedace<\/strong><\/li>\n<li><strong>Pedivigliano<\/strong><\/li>\n<li><strong>Piane Crati<\/strong><\/li>\n<li><strong>Pietrafitta<\/strong><\/li>\n<li><strong>Pietrapaola<\/strong><\/li>\n<li><strong>Plataci<\/strong><\/li>\n<li><strong>Rocca Imperiale<\/strong><\/li>\n<li><strong>Rogliano<\/strong><\/li>\n<li><strong>Rose<\/strong><\/li>\n<li><strong>Roseto Capo Spulico<\/strong><\/li>\n<li><strong>Rossano<\/strong><\/li>\n<li><strong>Rovito<\/strong><\/li>\n<li><strong>San Cosmo Albanese<\/strong><\/li>\n<li><strong>San Demetrio Corone<\/strong><\/li>\n<li><strong>San Giorgio Albanese<\/strong><\/li>\n<li><strong>San Giovanni in Fiore<\/strong><\/li>\n<li><strong>San Lorenzo Bellizzi<\/strong><\/li>\n<li><strong>San Lorenzo del Vallo<\/strong><\/li>\n<li><strong>San Pietro in Guarano<\/strong><\/li>\n<li><strong>Santa Sofia d&#8217;Epiro<\/strong><\/li>\n<li><strong>Santo Stefano di Rogliano<\/strong><\/li>\n<li><strong>Scala Coeli<\/strong><\/li>\n<li><strong>Scigliano<\/strong><\/li>\n<li><strong>Serra Pedace<\/strong><\/li>\n<li><strong>Spezzano Albanese<\/strong><\/li>\n<li><strong>Spezzano della Sila<\/strong><\/li>\n<li><strong>Spezzano Piccolo<\/strong><\/li>\n<li><strong>Tarsia<\/strong><\/li>\n<li><strong>Terranova da Sibari<\/strong><\/li>\n<li><strong>Terravecchia\u00a0<\/strong><\/li>\n<li><strong>Trebisacce<\/strong><\/li>\n<li><strong>Trenta<\/strong><\/li>\n<li><strong>Vaccarizzo Albanese<\/strong><\/li>\n<li><strong>Villapiana<\/strong><\/li>\n<li><strong>Zumpano\u00a0<\/strong><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Cosenza 1 &#8211; Ovest<\/strong><\/p>\n<ol>\n<li><strong>Acquaformosa<\/strong><\/li>\n<li><strong>Acquappesa<\/strong><\/li>\n<li><strong>Aiello Calabro<\/strong><\/li>\n<li><strong>Aieta<\/strong><\/li>\n<li><strong>Altomonte<\/strong><\/li>\n<li><strong>Amantea<\/strong><\/li>\n<li><strong>Belmonte Calabro<\/strong><\/li>\n<li><strong>Belvedere Marittimo<\/strong><\/li>\n<li><strong>Bonifati<\/strong><\/li>\n<li><strong>Buonvicino<\/strong><\/li>\n<li><strong>Carolei<\/strong><\/li>\n<li><strong>Castrolibero<\/strong><\/li>\n<li><strong>Castrovillari<\/strong><\/li>\n<li><strong>Cerisano<\/strong><\/li>\n<li><strong>Cervicati<\/strong><\/li>\n<li><strong>Cerzeto<\/strong><\/li>\n<li><strong>Cetraro<\/strong><\/li>\n<li><strong>Civita<\/strong><\/li>\n<li><strong>Cleto<\/strong><\/li>\n<li><strong>Cosenza<\/strong><\/li>\n<li><strong>Diamante<\/strong><\/li>\n<li><strong>Dipignano<\/strong><\/li>\n<li><strong>Domanico<\/strong><\/li>\n<li><strong>Fagnano Castello<\/strong><\/li>\n<li><strong>Falconara Albanese<\/strong><\/li>\n<li><strong>Firmo<\/strong><\/li>\n<li><strong>Fiumefreddo Bruzio<\/strong><\/li>\n<li><strong>Frascineto<\/strong><\/li>\n<li><strong>Fuscaldo<\/strong><\/li>\n<li><strong>Grisolia<\/strong><\/li>\n<li><strong>Guardia Piemontese<\/strong><\/li>\n<li><strong>Lago<\/strong><\/li>\n<li><strong>Laino Borgo<\/strong><\/li>\n<li><strong>Laino Castello<\/strong><\/li>\n<li><strong>Lattarico<\/strong><\/li>\n<li><strong>Longobardi<\/strong><\/li>\n<li><strong>Lungro<\/strong><\/li>\n<li><strong>Maier\u00e0<\/strong><\/li>\n<li><strong>Malvito<\/strong><\/li>\n<li><strong>Marano Marchesato<\/strong><\/li>\n<li><strong>Marano Principato<\/strong><\/li>\n<li><strong>Mendicino<\/strong><\/li>\n<li><strong>Mongrassano<\/strong><\/li>\n<li><strong>Montalto Uffugo<\/strong><\/li>\n<li><strong>Morano Calabro<\/strong><\/li>\n<li><strong>Mormanno<\/strong><\/li>\n<li><strong>Mottafollone<\/strong><\/li>\n<li><strong>Orsomarso<\/strong><\/li>\n<li><strong>Paola<\/strong><\/li>\n<li><strong>Papasidero<\/strong><\/li>\n<li><strong>Paterno Calabro<\/strong><\/li>\n<li><strong>Praia a Mare<\/strong><\/li>\n<li><strong>Rende<\/strong><\/li>\n<li><strong>Roggiano Gravina<\/strong><\/li>\n<li><strong>Rota Greca<\/strong><\/li>\n<li><strong>San Basile<\/strong><\/li>\n<li><strong>San Benedetto Ullano<\/strong><\/li>\n<li><strong>San Donato di Ninea<\/strong><\/li>\n<li><strong>San Fili<\/strong><\/li>\n<li><strong>San Lucido<\/strong><\/li>\n<li><strong>San Marco Argentano<\/strong><\/li>\n<li><strong>San Martino di Finita<\/strong><\/li>\n<li><strong>San Nicola Arcella<\/strong><\/li>\n<li><strong>San Pietro in Amantea<\/strong><\/li>\n<li><strong>San Sosti<\/strong><\/li>\n<li><strong>San Vincenzo la Costa<\/strong><\/li>\n<li><strong>Sangineto<\/strong><\/li>\n<li><strong>Santa Caterina Albanese<\/strong><\/li>\n<li><strong>Santa Domenica Talao<\/strong><\/li>\n<li><strong>Santa Maria del Cedro<\/strong><\/li>\n<li><strong>Sant&#8217;Agata di Esaro<\/strong><\/li>\n<li><strong>Saracena<\/strong><\/li>\n<li><strong>Scalea<\/strong><\/li>\n<li><strong>Serra d&#8217;Aiello<\/strong><\/li>\n<li><strong>Torano Castello<\/strong><\/li>\n<li><strong>Tortora<\/strong><\/li>\n<li><strong>Verbicaro<\/strong><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia di Cosenza\u00a0firma\u00a0convenzione\u00a0e\u00a0continuare l&#8217;iter di gara per individuare\u00a0gestore unico a garanzia di uniformit\u00e0 di trattamento (Elenco Comuni)<\/p>\n","protected":false},"author":37,"featured_media":89273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-89272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89272"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89273"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}