{"id":89308,"date":"2018-02-05T08:01:41","date_gmt":"2018-02-05T07:01:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/confiscati-i-beni-ad-un-imprenditore-edile-per-200-milioni-di-euro\/"},"modified":"2023-01-16T18:49:15","modified_gmt":"2023-01-16T17:49:15","slug":"200324-confiscati-i-beni-ad-un-imprenditore-edile-per-200-milioni-di-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/200324-confiscati-i-beni-ad-un-imprenditore-edile-per-200-milioni-di-euro\/","title":{"rendered":"Confiscati i beni ad un imprenditore edile, per 200 milioni di euro"},"content":{"rendered":"<h4>La confisca segue il sequestro di beni per un valore complessivo pari a 200 milioni di euro ha colpito Salvatore Mazzei, 62 anni, imprenditore edile.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; L&#8217;imprenditore edile lametino,<strong> Salvatore Mazzei<\/strong> \u00e8 ritenuto legato alle<strong> cosche della &#8216;ndrangheta<\/strong> ed il provvedimento a suo carico \u00e8 stato emesso dal Tribunale di Catanzaro ed \u00e8 stato eseguito dai Carabinieri del Nucleo operativo ecologico di Catanzaro, del Comando Provinciale Carabinieri di Catanzaro e del Gruppo Carabinieri di Lamezia Terme.<\/p>\n<p>I beni confiscati sono<strong> 26 societa&#8217; 67 fabbricati; 176 appezzamenti di terreno; 13 autocarri; 5 autovetture; 10 macchine operatrici per cantiere e un motociclo<\/strong>. La confisca \u00e8 stata preceduta da un sequestro richiesto dalla Procura della Repubblica di Catanzaro, Direzione distrettuale antimafia, diretta dal procuratore della Repubblica di Catanzaro Nicola Gratteri e coordinata dall&#8217;aggiunto Giovanni Bombardieri, nell&#8217;ambito di una strategia investigativa, finalizzata alla sottrazione di beni riconducibili a soggetti collegati, o contigui, ad organizzazioni di &#8216;ndrangheta.<\/p>\n<p>L&#8217;indagine, avviata nel 2011, inizialmente dalla Procura di Lamezia Terme, successivamente trasferita per competenza territoriale, alla Procura di Catanzaro, ha permesso di ricostruire, attraverso una minuziosa attivita&#8217;, un patrimonio illecitamente acquisito pari a 200 milioni di euro. L&#8217;attenta analisi dei dati acquisiti ha permesso di accertare una rilevante sproporzione tra i redditi dichiari ed il flusso di denaro realmente a disposizione di Mazzei e del nucleo familiare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La confisca segue il sequestro di beni per un valore complessivo pari a 200 milioni di euro ha colpito Salvatore Mazzei, 62 anni, imprenditore edile.<\/p>\n","protected":false},"author":22,"featured_media":89309,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-89308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89308"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89309"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}