{"id":8931,"date":"2012-12-04T10:22:11","date_gmt":"2012-12-04T09:22:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8931"},"modified":"2023-01-17T13:42:07","modified_gmt":"2023-01-17T12:42:07","slug":"3890-natale-sara-il-peggiore-dal-2010-consumi-in-calo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3890-natale-sara-il-peggiore-dal-2010-consumi-in-calo\/","title":{"rendered":"Natale, sar\u00e0 il peggiore dal 2010. Consumi in calo"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROMA<\/strong> &#8211; Natale in chiaroscuro: sale la speranza, ma cresce anche il numero di coloro che temono sia il peggiore del triennio.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Secondo il sondaggio Confesercenti-Swg il 54% degli italiani (era il 51% nel 2011) si affida alla speranza per definire l&#8217;ormai prossimo Natale ed in tal modo cerca di contrastare gli incubi della crisi e del futuro. Ma cresce anche in modo netto il numero di coloro che non si fanno illusioni: per 19 milioni di connazionali, infatti, questo sar\u00e0 il peggior Natale dal 2010 (si sale dal 25% del 2011 al 38% di quest&#8217;anno), 20 milioni non vedono differenze con l&#8217;anno passato, mentre una consistente minoranza, 11 milioni, crede in un miglioramento.<br \/>A risentirnesono i consumi: questo dicembre, in totale, gli italiani spenderanno 36,8 miliardi: il 3% in meno rispetto al 2011, quando spesero 38 miliardi. In calo della stessa percentuale anche &#8216;l&#8217;effetto Natale, l&#8217;insieme di spese innescate dalle festivit\u00e0 dell&#8217;ultimo mese dell&#8217;anno: nel 2012 \u00e8 di 10,7 miliardi, contro gli 11 registrati nel 2011. Le tredicesime serviranno per far fronte ai mutui, pagare i debiti e ripristinare il risparmio eroso dalla crisi. (Fonte TMNews)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Natale in chiaroscuro: sale la speranza, ma cresce anche il numero di coloro che temono sia il peggiore del triennio.<\/p>\n","protected":false},"author":22,"featured_media":8932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-8931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8931"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8932"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}