{"id":89341,"date":"2018-02-06T09:53:45","date_gmt":"2018-02-06T08:53:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/intervista-a-franco-corbelli-liberi-e-uguali-immigrazione-serve-rispetto-della-dignita\/"},"modified":"2023-01-16T18:49:17","modified_gmt":"2023-01-16T17:49:17","slug":"200437-intervista-a-franco-corbelli-liberi-e-uguali-immigrazione-serve-rispetto-della-dignita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/200437-intervista-a-franco-corbelli-liberi-e-uguali-immigrazione-serve-rispetto-della-dignita\/","title":{"rendered":"Intervista a Franco Corbelli &#8211; Liberi e Uguali: &#8220;immigrazione, serve rispetto della dignit\u00e0&#8221; (AUDIO)"},"content":{"rendered":"<h4>Franco Corbelli, leader\u00a0del Movimento Diritti Civili,\u00a0<span class=\"Apple-style-span\">scende in campo alla prossima<\/span>\u00a0competizione elettorale del 4 marzo<span class=\"Apple-style-span\">\u00a0per Liberi e Uguali, nel collegio senatoriale uninominale<\/span>\u00a0di\u00a0<span class=\"Apple-style-span\">Cosenza.<\/span><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Il candidato Corbelli, che corre con il partito di Piero Grasso ha scelto Liberi e Uguali perch\u00e8 &#8220;<strong>c&#8217;\u00e8 una condivisione totale<\/strong> per quelle che sono le battaglie che porto avanti da oltre 30 anni sul tema dei diritti civili , del lavoro, dei diritti della persona. Era il partito, forse l&#8217;unico che potevo accettare per questa competizione elettorale, perch\u00e8 credo che se riusciremo in questa impresa veramente storica, noi potremo dare pi\u00f9 forza alle nostre battaglie e iniziative umanitarie e questo \u00e8 il partito ideale per sostenermi&#8221;. &#8220;Sono in questo partito da indipendente perch\u00e8 la mia storia non appartiene e non apparterr\u00e0 mai a nessun partito. Ma questo partito per la storia dei suoi componenti, \u00e8 in grado di rappresentare le istanze dei lavoratori, del mondo della scuola, le istanze sociali che riguardano tutti. Cosa che ha completamente disatteso <strong>il partito di Renzi perch\u00e8 non \u00e8 pi\u00f9 partito &#8216;democratico&#8217; come \u00e8 noto<\/strong>&#8220;.<br \/>\n&nbsp;<\/p>\n<h4>Immigrazione: &#8220;Non si pu\u00f2 obbligare un solo paese, come l&#8217;Italia, ad accogliere un popolo di disperati&#8221;<\/h4>\n<p>&nbsp;<br \/>\n&#8220;La posizione di Liberi e Uguali e di Diritti Civili \u00e8 a tutti nota. Il rispetto di queste persone &#8211; ha s<strong>piegato Corbelli nell&#8217;intervista rilasciata a Quicosenza<\/strong>.it &#8211; che rischiano la vita per cercare un mondo migliore. Noi abbiamo il dovere di aiutarli ma questo non vuol dire non chiedere a loro il rispetto delle regole e non significa lasciare da sola l&#8217;Italia. E&#8217; un problema che va affrontato a livello europeo e che ci sia la possibilit\u00e0 di questa gente, ma concretamente, di essere aiutata e di evitare che possano esserci con le traversate nel Mediterraneo queste stragi. Siamo per un accoglienza giusta, nei limiti del possibile, ma per il rispetto sacro e doveroso della dignit\u00e0 e della vita di queste persone&#8221;.<br \/>\n&nbsp;<br \/>\n&#8220;Per l&#8217;immigrazione non viene fatto abbastanza e la cronaca ci dice che non tutto \u00e8 stato fatto come si doveva fare. L&#8217;immigrazione \u00e8 stata spesso oggetto di interesse, e questa \u00e8 una cosa ignobile. Ecco io mi auguro che si guardi a questo fenomeno e problema epocale con grande senso di responsabilit\u00e0. L&#8217;immigrazione non deve essere considerata un business ma un problema da affrontare con impegno e rispetto di queste persone. Sino ad oggi non \u00e8 stato cos\u00ec&#8221;. Sui rapporti con l&#8217;Europa, Corbelli sottolinea: &#8220;Non si pu\u00f2 obbligare un solo paese, come l&#8217;Italia, ad accogliere tutto questo popolo di disperati e bisogna rivedere, con il trattato di Dublino e con tutte le leggi che sono state fatte anni addietro, e che oggi alla luce di qeusta emergenza epocale vanno riformulate, rimodulate. Se questo popolo venisse distribuito a livello europeo, non ci sarebbe il problema ma se questa situazione viene lasciata solo in mano all&#8217;Italia diventa una emergenza&#8221;.<br \/>\n&nbsp;<\/p>\n<h4>La sanit\u00e0: &#8220;vorrei istituire la figura del Garante della Salute&#8221;<\/h4>\n<p>&nbsp;<br \/>\nIo credo che il problema della sanit\u00e0 dovr\u00e0 essere una delle priorit\u00e0 e lo sar\u00e0 sicuramente per Liberi e Uguali. Lo \u00e8 stato come priorit\u00e0 per Diritti Civili. Se eletto al Parlamento la prima cosa che far\u00f2 \u00e8 imporr\u00f2 il Garante della Salute al servizio dei cittadini. L&#8217;istituzione \u00e8 importante perch\u00e8 i cittadini avranno un riferimento per quelle lista d&#8217;attesa infinite, per quei ricoveri che non ci sono, per scongiurare casi di malasanit\u00e0. Mi batter\u00f2 per questo e sar\u00e0 il primo passo. E poi le strutture, che non vanno depotenziate.<br \/>\n&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">ASCOLTA L&#8217;AUDIO INTEGRALE dell&#8217;intervista a Franco Corbelli<br \/>\n[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/Corbelli-completa-.mp3&#8243;]<br \/>\n<\/span><\/h3>\n<p>&nbsp;<\/p>\n<h4>La sicurezza:\u00a0 &#8220;le forze dell&#8217;ordine devono essere messe nelle condizioni di operare&#8221;<\/h4>\n<p>&nbsp;<br \/>\nDobbiamo vederlo come baluardo per la legalit\u00e0 del nostro Paese ma bisogna anche mettere le forze dell&#8217;ordine nelle condizioni di operare con maggiore sicurezza e pensando alle condizioni di grande disagio in cui sono costretti. Se pensiamo alla retribuzione, \u00e8 una cosa veramente ignobile, per chi rischia la vita. Io non faccio promesse io sono per i fatti, e per i diritti che vanno rispettati. Io non posso rinnegare la mia storia garantista, ma nel rispetto dell&#8217;operato della magistratura. Questo baluardo di legalit\u00e0, magistratura e forze dell&#8217;ordine va salvaguardato ma non rinnegando i nostri principi e difendendo i diritti.<br \/>\n&nbsp;<\/p>\n<h4>Lavoro e disoccupazione: &#8220;basta creare nuovi precari&#8221;<\/h4>\n<p>&nbsp;<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-200614 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/Franco-Corbelli-.jpg\" alt=\"Franco Corbelli\" width=\"284\" height=\"356\" title=\"\">Di certo non vogliamo ancora creare nuovi precari e non saremo mai per far aumentare il precariato. Saremo per il ripristino dell&#8217;articolo 18 perch\u00e8 non si pu\u00f2 pensare di licenziare anche un operaio, una persona adulta, dalla sera alla mattina, magari vicina alla pensione: \u00e8 una cosa ingiusta e antidemocratica. Bisogna pensare anche che ereditiamo la legge Fornero che ha creato drammi nelle famiglie. E credo che una delle prime battaglie che porter\u00f2 in Parlamento \u00e8 questa: dare certezze alle persone per quanto riguarda la loro pensione e pensare che una delle emergenze del nostro Paese sono i giovani e il lavoro da dare a loro. Non ho la presunzione di pensare di risolvere i problemi ma il mio contributo andr\u00e0 in questa direzione&#8221;.<br \/>\n&nbsp;<br \/>\n&#8220;Bisogna partire da una serie di incentivi: all&#8217;occupazione, per le imprese anche per le famiglie. Questa dovr\u00e0 essere la linea da cui partire. In una realt\u00e0 come la nostra, la Calabria, dove il tasso di disoccupazione \u00e8 alle stelle, bisogna anche in questo caso, che le politiche tengano conto delle diverse realt\u00e0 territoriali. Individuare delle aree dove intervenire con forza e determinazione. Ritengo che si debba dare priorit\u00e0 a chi non ha un lavoro, e soprattutto sostenere le piccole e medie imprese che sono quelle che lavorano, creano occupazione e in regioni come la nostra sono il vero motore dell&#8217;economia&#8221;.<br \/>\n&nbsp;<br \/>\n<strong>&#8220;Sui finanziamenti,<\/strong> l&#8217;importante \u00e8 non sprecare ed essere certi che poi quel finanziamento (anche fondo perduto) produca sul piano dell&#8217;economia. dell&#8217;occupazione e sul piano industriale, ritengo che anche un finanziamento a fondo perduto sia da valutare positivamente. Non devono essere concessi alla cieca, ma controllati e verificati. Questo per sostenere le imprese che hanno bisogno, ma non regalando soldi o finanziamenti a pioggia perch\u00e8 questa \u00e8 una politica che non ha mai prodotto nulla ed ha creato sprechi e ruberie&#8221;.<\/p>\n<h4>Le famiglie: &#8220;Una politica seria non c&#8217;\u00e8 mai stata&#8221;<\/h4>\n<p>&nbsp;<br \/>\n&#8220;Io credo &#8211; spiega Corbelli &#8211; che una politica seria per le famiglie nel nostro Paese non c&#8217;\u00e8 mai stata. Guardiamo alle famiglie e pensiamo alle promesse: reddito di inclusione ecc&#8230;. Queste sono iniziative dal sapore elettorale fatto non a caso alla vigilia delle elezioni. Il mio impegno concreto \u00e8 di portare in Parlamento un&#8217;iniziativa che tenga conto della realt\u00e0 di ogni famiglia nel senso valutare i disoccupati di una famiglia, il reddito e intervenire concretamente. Altrimenti si rischia di dare finanziamenti a pioggia a persone e famiglie che non ne hanno bisogno. Ci vuole un&#8217;iniziativa che tenga conto del reale bisogno delle famiglie. Una famiglia ad esempio, ha tre giovani disoccupati, dobbiamo fare in modo di farne assumere uno. Certo non \u00e8 un discorso semplice da realizzare ma se parliamo di uguaglianza sociale questo \u00e8 un punto da cui partire. Giustizia ed eguaglianza sociale&#8221;.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franco Corbelli, leader\u00a0del Movimento Diritti Civili,\u00a0scende in campo alla prossima\u00a0competizione elettorale del 4 marzo\u00a0per Liberi e Uguali, nel collegio senatoriale uninominale\u00a0di\u00a0Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":89342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,369],"tags":[],"class_list":["post-89341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-speciale-elezioni-2018"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89341"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89342"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}